{"id":197556,"date":"2023-09-08T10:39:59","date_gmt":"2023-09-08T14:39:59","guid":{"rendered":"https:\/\/www.noticel.com\/ahora\/la-calle\/20230908\/en-vivo-presentan-al-nuevo-obispo-auxiliar-de-san-juan-designado-por-el-papa\/"},"modified":"2025-07-12T02:49:51","modified_gmt":"2025-07-12T02:49:51","slug":"padre-tomas-gonzalez-recibe-el-nombramiento-con-devocion-al-servicio","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20230908\/padre-tomas-gonzalez-recibe-el-nombramiento-con-devocion-al-servicio\/","title":{"rendered":"Padre Tom\u00e1s Gonz\u00e1lez recibe el nombramiento con devoci\u00f3n al servicio"},"content":{"rendered":"<h3>Ha sido nombrado por el Papa Francisco como Obispo Auxiliar de San Juan.<\/h3>\n<p>El Arzobispo de San Juan, Roberto Gonz\u00e1lez Nieves,\u00a0anunci\u00f3 la designaci\u00f3n del Papa Francisco para el nuevo\u00a0Obispo Auxiliar de San Juan, el Padre Tom\u00e1s Gonz\u00e1lez Gonz\u00e1lez.<\/p>\n<p>Actualmente es P\u00e1rroco de la Parroquia Santa Luisa de Marillac en Las Cumbres, San Juan, Vicario General y Moderador de la Curia de la Arquidi\u00f3cesis.<\/p>\n<p>Este nombramiento seg\u00fan Gonz\u00e1lez fue una total sorpresa. Sin embargo, lo recibe con mucho amor y compromiso.<\/p>\n<p>\u00abNo me esperaba esto para nada -dijo entre risas-me sorprendi\u00f3 porque no es algo que yo estaba aspirando. Estaba sirviendo donde me hab\u00edan asignado y desde la fe estoy confiando en la gracia que ha obrado en mi y seguir\u00e1 obrando para poder responder al Se\u00f1or y procurar aprender m\u00e1s en compa\u00f1\u00eda de los hermanos que Dios pone en nuestro camino\u00bb, cont\u00f3 <strong id=\"strong-88d53739f74164a22ff835d508b2fd0b\">a NotiCel. <\/strong><\/p>\n<p>\u00abSiempre procuro en todas mis responsabilidades servir ya sea desde el escritorio, sea visitando enfermos, sea confirmando, compartiendo con la familia, ayudando a mi madre. Todo para m\u00ed es servir donde me toque estar. No soy perfecto, se que tengo cosas por mejorar pero esta es la direcci\u00f3n; buscar servir donde la iglesia me necesite\u00bb, indic\u00f3.<\/p>\n<p>Su formaci\u00f3n al sacerdocio fue en el Seminario Mayor Regional San Juan Bautista en San Juan del 1994 al 2000. Se le orden\u00f3 di\u00e1cono en noviembre del 200 en la Gruta de Lourdes y ordenado Sacerdote el 6 de agosto del 2001 en la Catedral de San Juan.<\/p>\n<p>Tambi\u00e9n ha sido Capell\u00e1n del Recinto de Ciencias Medicas (2001-2017).<\/p><div class=\"notic-content-middle\" id=\"notic-4005309962\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>\u00abEste proceso de transici\u00f3n ahora se compone de varias etapas porque hoy se hizo p\u00fablico el anuncio, pero todav\u00eda sigo en la Parroquia y sigo atendi\u00e9ndola. Ahora me toca ir pensando en detalles para la celebraci\u00f3n y eventualmente habr\u00e1n reuniones, adquirir vestimentas, hacer una semana de ejercicios espirituales de retiro y planificar la mudanza; pero estoy listo\u00bb, expres\u00f3.<\/p>\n<p>La fecha de ordenaci\u00f3n episcopal del nuevo Obispo ser\u00e1 el pr\u00f3ximo 18 de noviembre en la Iglesia Santa Teresita en la Calle Lo\u00edza en Santurce a las 11:00am.<\/p>\n<p>En el cargo de Papa Francisco ha elegido al ministerio episcopal a cuatro de los seis obispos que actualmente est\u00e1n ejerciendo el ministerio episcopal en Puerto Rico.<\/p>\n<p>\u00abEstoy agradecido, todos dependemos de la gente para llegar a donde estamos y obviamente me quedo corto de agradecer a la familia, vecinos, amigos, hermanos sacerdotes, tanta gente que ha aportado para que yo llegue hasta aqu\u00ed, aunque me falta mucho por aprender. Hay que tener los pies en la tierra y saber que no es perfecto. As\u00ed que, en ese sentido se que contar\u00e9 con la ayuda de mucha gente para seguir hacia adelante y darle a Dios lo mejor que uno pueda\u00bb, puntualiz\u00f3.<\/p>\n<p>\u00abQuisiera felicitar a nombre de la Provincia Eclesi\u00e1stica de Puerto Rico, a nombre de la familia arquidiocesana y a nombre propio, al Obispo electo Tom\u00e1s, por esta elecci\u00f3n y designaci\u00f3n que le ha hecho el Papa. Nuestro profundo agradecimiento al Papa Francisco por obsequiarle a nuestra Arquidi\u00f3cesis un nuevo Obispo Auxiliar. Es un signo mas de su amor y solicitud pastoral por la Iglesia que peregrina en Puerto Rico\u00bb, expres\u00f3 el Arzobispo Roberto en declaraciones escritas.<\/p>\n<p>Mira esta transmisi\u00f3n en vivo desde la Catedral de San Juan.<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.facebook.com\/plugins\/video.php?height=314&#038;href=https%3A%2F%2Fwww.facebook.com%2Fnoticelpr%2Fvideos%2F1930725967329336%2F&#038;show_text=false&#038;width=560&#038;t=0\" width=\"560\" height=\"314\" style=\"border:none;overflow:hidden\" scrolling=\"no\" frameborder=\"0\" allowfullscreen=\"true\" allow=\"autoplay; clipboard-write; encrypted-media; picture-in-picture; web-share\"><\/iframe><\/p>","protected":false},"excerpt":{"rendered":"<p>Ha sido nombrado por el Papa Francisco como Obispo Auxiliar de San Juan. El Arzobispo de San Juan, Roberto Gonz\u00e1lez Nieves,\u00a0anunci\u00f3 la designaci\u00f3n del Papa Francisco para el nuevo\u00a0Obispo Auxiliar de San Juan, el Padre Tom\u00e1s Gonz\u00e1lez Gonz\u00e1lez. Actualmente es P\u00e1rroco de la Parroquia Santa Luisa de Marillac en Las Cumbres, San Juan, Vicario General [&hellip;]<\/p>","protected":false},"author":10,"featured_media":250794,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12,2],"tags":[],"class_list":["post-197556","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-calle","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/197556","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=197556"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/197556\/revisions"}],"predecessor-version":[{"id":250795,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/197556\/revisions\/250795"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/250794"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=197556"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=197556"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=197556"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}