{"id":196487,"date":"2023-08-06T06:00:00","date_gmt":"2023-08-06T10:00:00","guid":{"rendered":"https:\/\/www.noticel.com\/?post_type=article&#038;p=196487"},"modified":"2025-07-12T03:59:56","modified_gmt":"2025-07-12T03:59:56","slug":"actividad-de-construccion-aumento-en-7-5-en-el-ano-fiscal-2022","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/economia\/20230806\/actividad-de-construccion-aumento-en-7-5-en-el-ano-fiscal-2022\/","title":{"rendered":"Actividad de construcci\u00f3n aument\u00f3 en 7.5% en el a\u00f1o fiscal 2022"},"content":{"rendered":"<h3>Seg\u00fan datos publicados por la Junta de Planificaci\u00f3n.<\/h3>\n<p>La actividad de construcci\u00f3n privada y p\u00fablica en Puerto Rico aument\u00f3 nuevamente durante el a\u00f1o fiscal 2022 cuando alcanz\u00f3 la cifra estimada de $4,846.0 millones, que represent\u00f3 un aumento de $338.6 millones o 7.5% sobre los $4,507.4 millones estimados para el anterior a\u00f1o fiscal 2021.<\/p>\n<p>Seg\u00fan los datos reci\u00e9n publicados por la Junta de Planificaci\u00f3n, la inversi\u00f3n en construcci\u00f3n a nivel privado se estim\u00f3 en $3,415.1 millones, para un aumento de $763.5 millones o 28.8% frente a los  $2,651.6 millones del a\u00f1o fiscal 2021.<\/p>\n<p>Por el lado p\u00fablico, informa la agencia, dicha actividad se estim\u00f3 en $1,430.9 millones, que en  este caso represent\u00f3 una disminuci\u00f3n de $424.9 millones o 22.9% respecto al a\u00f1o fiscal 2021 cuando la actividad de construcci\u00f3n p\u00fablica se estim\u00f3 en $1,855.8 millones.<\/p>\n<p>Esa relaci\u00f3n result\u00f3 en que en el a\u00f1o fiscal 2022 la inversi\u00f3n privada represent\u00f3 el 70.5% de la inversi\u00f3n total, mientras que la inversi\u00f3n p\u00fablica estimada represent\u00f3 el restante 29.5%.<\/p>\n<p>La reciente publicaci\u00f3n \u201cEstad\u00edsticas Seleccionadas Sobre la Industria de la Construcci\u00f3n-2022\u201d de dicha agencia esta es la inversi\u00f3n en construcci\u00f3n m\u00e1s alta luego de los dos a\u00f1os que siguieron al hurac\u00e1n Mar\u00eda en el 2017.<\/p>\n<p>La del 2018 fue de $8,065.4 millones, y la del 2019 alcanz\u00f3 los $7,245.5 millones. Ya en el 2020 ese total se redujo a $3,722.4 millones en el 2020, y volvi\u00f3 entonces a subir a $4,507.4 millones en el 2021 y a los $4,846.0 millones estimados para el 2022.<\/p>\n<p>Previo a ese periodo y hasta el 2017 la inversi\u00f3n en construcci\u00f3n ven\u00eda decreciendo en Puerto Rico, seg\u00fan los datos de esta publicaci\u00f3n que cubre solo los a\u00f1os fiscales que van del 2013 al 2022.<\/p>\n<p>Otro importante indicador de la reactivaci\u00f3n de este importante sector es el empleo en la construcci\u00f3n, el cual ha mantenido una tendencia ascendente durante el mencionado per\u00edodo publicado. Se indica que durante el a\u00f1o fiscal 2022, el empleo en el sector de la construcci\u00f3n alcanz\u00f3 las 58 mil personas, lo que represent\u00f3 un aumento de 7.4% en comparaci\u00f3n con el fiscal 2021, cuando este se situ\u00f3 en 54 mil empleos.<\/p>\n<p>Resalta el citado informe que los componentes de la inversi\u00f3n total que registraron aumentos en comparaci\u00f3n con el a\u00f1o fiscal 2021 fueron la vivienda privada, que aument\u00f3 54.3%; los edificios comerciales e industriales privados, que aumentaron en un 2.5%, los proyectos de instalaciones privados, que reflejaron un crecimiento de 55.5%; y los proyectos de instalaciones p\u00fablicos, con un aumento de 35%.<\/p><div class=\"notic-content-middle\" id=\"notic-3511442378\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>Experimentaron bajas en la misma comparaci\u00f3n la vivienda p\u00fablica, con una merma de 27.2%; los edificios comerciales e industriales p\u00fablicos, con una baja de 31.7%; y las agencias del Gobierno Central y municipios que mostraron una ca\u00edda de 34.4%.<\/p>\n<p><strong id=\"strong-a18cd9f32a07cc3c2b30083de00c4709\">La inversi\u00f3n privada y p\u00fablica<\/strong><\/p>\n<p>La composici\u00f3n de la inversi\u00f3n privada en el fiscal 2022 fue de $ 717.5 millones en vivienda privada; de $1,358.5 millones en edificios comerciales e industriales privados; y de $1,339.2 millones en proyectos de instalaciones privados.<\/p>\n<p>En este \u00faltimo grupo destacan los $602.7 millones invertidos en telecomunicaciones y los $428.4 millones invertidos en energ\u00eda renovable.<\/p>\n<p>Por el lado p\u00fablico, la inversi\u00f3n en vivienda fue de apenas $7.5 millones la de edificios comerciales e industriales p\u00fablicos fue de $41.1 millones, mientras que aquella en proyectos de instalaciones p\u00fablicos esta fue de $398.8 millones, para el mencionado aumento de 35%.<\/p>\n<p>La inversi\u00f3n de las agencias gubernamentales en infraestructura las encabez\u00f3 nuevamente en el fiscal 2022 la Autoridad de Carreteras y Transportaci\u00f3n, con $221.1 millones; seguida de la Autoridad de Acueductos y Alcantarillados con $154.2millones y por la Autoridad de Energ\u00eda El\u00e9ctrica, con $129.2 millones.<\/p>\n<p>La cantidad y valor de los permisos de construcci\u00f3n registraron alzas durante este periodo fiscal. En el caso de los permisos privados estos totalizaron 4,587 con un valor de $1,241.3 millones, superando los 3,984 del 2021 y su valor estimado entonces en $1,077.8 millones.<\/p>\n<p>Los permisos para construcci\u00f3n del sector p\u00fablico totalizaron 1,657, con un valor estimado de $375.2 millones. Estos tambi\u00e9n superaron los 1,079 permisos del fiscal 2021 y su valor estimado de $273.7 millones.<\/p>\n<p>En total se emitieron en el fiscal 2022 6,245 permisos con un valor estimado de $1,638 millones.<\/p>","protected":false},"excerpt":{"rendered":"<p>Seg\u00fan datos publicados por la Junta de Planificaci\u00f3n. La actividad de construcci\u00f3n privada y p\u00fablica en Puerto Rico aument\u00f3 nuevamente durante el a\u00f1o fiscal 2022 cuando alcanz\u00f3 la cifra estimada de $4,846.0 millones, que represent\u00f3 un aumento de $338.6 millones o 7.5% sobre los $4,507.4 millones estimados para el anterior a\u00f1o fiscal 2021. Seg\u00fan los [&hellip;]<\/p>","protected":false},"author":0,"featured_media":252998,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[22],"tags":[],"class_list":["post-196487","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/196487","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=196487"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/196487\/revisions"}],"predecessor-version":[{"id":252999,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/196487\/revisions\/252999"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/252998"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=196487"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=196487"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=196487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}