{"id":196252,"date":"2023-07-28T05:45:00","date_gmt":"2023-07-28T09:45:00","guid":{"rendered":"https:\/\/www.noticel.com\/?post_type=article&#038;p=196252"},"modified":"2025-07-12T04:20:15","modified_gmt":"2025-07-12T04:20:15","slug":"bajaron-en-junio-las-ventas-de-cemento","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/economia\/20230728\/bajaron-en-junio-las-ventas-de-cemento\/","title":{"rendered":"Bajaron en junio las ventas de cemento"},"content":{"rendered":"<h3>Adem\u00e1s, en total la producci\u00f3n fue durante el pasado mes de 820,000 sacos, que son 40,000 menos que el a\u00f1o pasado.<\/h3>\n<p>Las ventas de cemento registraron una leve baja durante el pasado mes de junio, cuando registraron unos 1,270, 000 sacos de 94 libras, para un reducci\u00f3n de 5.0% frente los 1,345,000 sacos vendidos el mismo mes del pasado a\u00f1o 2022.<\/p>\n<p>A pesar de esa baja, informada por el Instituto de Estad\u00edsticas de Puerto Rico, ese total de junio le coloca en el cuarto  mes de mayores ventas de cemento durante el reci\u00e9n concluido a\u00f1o fiscal 2022-2023. Estas fueron superadas solo por los 1,463,000  sacos de marzo, los 1,397,000 de mayo pasado y los 1,329,000 de agosto.<\/p>\n<p>El total de ventas acumuladas durante ese a\u00f1o fiscal alcanz\u00f3 los 14,494,00 sacos de 94 libras de cemento, lo que les mantiene por debajo de aquellas registradas durante el a\u00f1o fiscal anterior, cuando estas se estimaron en 15,071,000, lo que representa una baja de 3.8%.<\/p>\n<p>Mientras tanto la venta acumulada en los primeros seis meses del a\u00f1o calendario (enero a junio) resulta tambi\u00e9n en una baja de apenas 0.4%, frente a esos mismos seis meses del a\u00f1o anterior. El total acumulado en este a\u00f1o 2023 es de 7,645,000 sacos, frente a los 76,676,000 de los mismos seis meses del a\u00f1o anterior.<\/p>\n<p>En lo que respecta a la producci\u00f3n de cemento, hubo una baja respecto al anterior mes de mayo y tambi\u00e9n cuando se compara con el mes de junio de 2022. En total la producci\u00f3n fue durante el pasado mes de junio de 820,000 sacos, que son 40,000 menos que el a\u00f1o pasado, lo que equivale a una baja de 4.6%.<\/p><div class=\"notic-content-middle\" id=\"notic-2054306436\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-970&#215;90\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1.jpg 970w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-300x28.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-768x71.jpg 768w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-18x2.jpg 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"90\"   \/><\/a><\/div>\n<p>Diferente a las ventas, la producci\u00f3n de cemento aument\u00f3 durante el reci\u00e9n concluido a\u00f1o fiscal 2022-2023, Esta fueron de 8,849,000 sacos en el fiscal 2023, superando as\u00ed los 7,879,000 durante el pasado a\u00f1o fiscal 2022, para una fuerte alza de 12.3%.<\/p>\n<p>Los datos acumulados en los primeros seis meses del a\u00f1o calendario reflejan por su lado, una producci\u00f3n de 4,747,000 sacos de 94 libras, que son 550,000 m\u00e1s  que los 4,198,00 en el 2022, para un incremento de 13.1%.<\/p>\n<p>Lea:<\/p>\n<p><a href=\"https:\/\/noticel.com\/en\/economia\/gobierno\/top-stories\/20230414\/bde-separa-20-millones-para-apoyar-empresarios-de-la-construccion\/\" id=\"link-5595c9488bc4ea18d7060927b85b5437\">BDE separa $20 millones para apoyar empresarios de la construcci\u00f3n<\/a><\/p>\n<p><a href=\"https:\/\/noticel.com\/en\/economia\/top-stories\/20230712\/indice-de-actividad-economica-mantuvo-su-crecimiento-en-mayo\/\" id=\"link-1fb6b3ca8a835fb0d177b9b271fa66e4\">Indice de Actividad Econ\u00f3mica mantuvo su crecimiento en mayo<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Adem\u00e1s, en total la producci\u00f3n fue durante el pasado mes de 820,000 sacos, que son 40,000 menos que el a\u00f1o pasado. Las ventas de cemento registraron una leve baja durante el pasado mes de junio, cuando registraron unos 1,270, 000 sacos de 94 libras, para un reducci\u00f3n de 5.0% frente los 1,345,000 sacos vendidos el [&hellip;]<\/p>","protected":false},"author":0,"featured_media":253525,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[22],"tags":[],"class_list":["post-196252","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/196252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=196252"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/196252\/revisions"}],"predecessor-version":[{"id":253526,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/196252\/revisions\/253526"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/253525"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=196252"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=196252"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=196252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}