{"id":193681,"date":"2023-05-16T08:21:04","date_gmt":"2023-05-16T12:21:04","guid":{"rendered":"https:\/\/www.noticel.com\/ahora\/top-stories\/tribunales\/20230516\/demandan-a-genera-pr-por-uso-ilegal-de-la-marca-en-puerto-rico\/"},"modified":"2025-07-12T07:31:41","modified_gmt":"2025-07-12T07:31:41","slug":"demandan-a-genera-pr-por-uso-ilegal-de-la-marca-en-puerto-rico","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20230516\/demandan-a-genera-pr-por-uso-ilegal-de-la-marca-en-puerto-rico\/","title":{"rendered":"Demandan a Genera PR por uso ilegal de la marca en Puerto Rico"},"content":{"rendered":"<h3>Ya exist\u00eda en Puerto Rico una empresa de nombre GenEra.<\/h3>\n<p>La compa\u00f1\u00eda de energ\u00eda renovable GenEra present\u00f3 el lunes un recurso de interdicto (injuction) contra la empresa Genera PR \u201cpor el uso ilegal de su marca en todo el comercio de Estados Unidos y de Puerto Rico\u201d.<\/p>\n<p>\u201cSoy un ingeniero y empresario del patio, formado en Puerto Rico. Cuento con varias licencias y certificaciones que me capacitan para el trabajo que hago con mi compa\u00f1\u00eda de generaci\u00f3n de energ\u00eda solar. Fund\u00e9 mi compa\u00f1\u00eda en marzo del 2020 con mucho esfuerzo y sacrificio y desde entonces estamos usando de manera continua e ininterrumpida las marcas y nombres comerciales GENERA y GENERA PR. Esta situaci\u00f3n es sumamente injusta\u201d, dijo Sa\u00fal Gonz\u00e1lez Mendoza, fundador de GenEra en declaraciones escritas.<\/p>\n<p>Seg\u00fan Gonz\u00e1lez Mendoza, GenEra es una compa\u00f1\u00eda de responsabilidad limitada con fin social (L3C) cuyo objetivo es contribuir al desarrollo de la energ\u00eda renovable en Puerto Rico a trav\u00e9s de iniciativas de impacto social positivo en Puerto Rico.<\/p>\n<p>Aleg\u00f3 que su negocio comenz\u00f3 a verse afectado a principios del 2023, cuando comenz\u00f3 a recibir comunicaciones de clientes, suplidores y colaboradores, confundidos ante los anuncios p\u00fablicos del consorcio Genera PR.<\/p>\n<p>\u201cUno se esmera para tratar de echar adelante un negocio de impacto social y una compa\u00f1\u00eda poderosa trata de aplastar nuestro esfuerzo y adue\u00f1arse de nuestro nombre. Daremos la batalla y defenderemos lo nuestro como lo hace el pitirre contra el guaraguao\u201d, sostuvo.<\/p>\n<p>Gonz\u00e1lez Mendoza, a trav\u00e9s de su representaci\u00f3n legal, ha tenido varias comunicaciones con varios representantes del consorcio Genera PR sin lograr una soluci\u00f3n a esta controversia. La representaci\u00f3n legal del consorcio respondi\u00f3 que entienden no ha habido una utilizaci\u00f3n ilegal del nombre y marca GenEra.<\/p>\n<p>Por su parte, el vicepresidente de Asuntos Gubernamentales y P\u00fablicos de Genera PR, Iv\u00e1n B\u00e1ez, declar\u00f3 que el nombre de Genera PR est\u00e1 legalmente inscrito.<\/p>\n<p>\u00abQueremos aclarar que nuestro nombre, Genera PR, LLC, est\u00e1 en cumplimiento con las leyes de registro de entidades del Departamento de Estado. El mismo fue presentado para inscripci\u00f3n desde el 25 de enero de 2023, luego de una b\u00fasqueda donde no confligiera con ninguna otra empresa en la Isla\u00bb, indic\u00f3 en declaraciones escritas.<\/p>\n<p>\u00abLuego de consultar con nuestros abogados, entendemos que no hay conflicto de intereses dado que las compa\u00f1\u00edas se dedican a servicios diferentes. Genera PR opera y mantiene sistemas de generaci\u00f3n de energ\u00eda termal, mientras que GenEra L3C se dedica a servicios de energ\u00eda renovable, como la instalaci\u00f3n de paneles solares. De igual forma, la identidad visual de ambas compa\u00f1\u00edas es muy diferente en dise\u00f1o y colores\u00bb, agreg\u00f3.<\/p>\n<p>\u00abA pesar de nuestro inter\u00e9s en buscar un acuerdo favorecedor para ambas partes, la empresa GenEra L3C ha decidido acudir al tribunal. No obstante, en Genera PR seguiremos con los canales de comunicaci\u00f3n abiertos en \u00e1nimo de encontrar una soluci\u00f3n\u00bb, concluy\u00f3.<\/p>","protected":false},"excerpt":{"rendered":"<p>Ya exist\u00eda en Puerto Rico una empresa de nombre GenEra. La compa\u00f1\u00eda de energ\u00eda renovable GenEra present\u00f3 el lunes un recurso de interdicto (injuction) contra la empresa Genera PR \u201cpor el uso ilegal de su marca en todo el comercio de Estados Unidos y de Puerto Rico\u201d. \u201cSoy un ingeniero y empresario del patio, formado [&hellip;]<\/p>","protected":false},"author":0,"featured_media":259099,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[13,2],"tags":[],"class_list":["post-193681","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tribunales","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/193681","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=193681"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/193681\/revisions"}],"predecessor-version":[{"id":259100,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/193681\/revisions\/259100"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/259099"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=193681"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=193681"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=193681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}