{"id":192516,"date":"2023-04-18T18:22:15","date_gmt":"2023-04-18T22:22:15","guid":{"rendered":"https:\/\/www.noticel.com\/ahora\/legislatura\/20230418\/sin-votacion-medida-para-investigar-ley-de-salud-mental-de-puerto-rico\/"},"modified":"2025-07-12T08:52:18","modified_gmt":"2025-07-12T08:52:18","slug":"sin-votacion-medida-para-investigar-ley-de-salud-mental-de-puerto-rico","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20230418\/sin-votacion-medida-para-investigar-ley-de-salud-mental-de-puerto-rico\/","title":{"rendered":"Sin votaci\u00f3n medida para investigar \u201cLey de Salud Mental de Puerto Rico\u201d"},"content":{"rendered":"<h3>Uno de los prop\u00f3sitos de esta ley es promover la erradicaci\u00f3n de los prejuicios y estigmas contra la persona que padecen de trastornos mentales<\/h3>\n<p>La medida para investigar el alcance y efectividad de la Ley 408-2000, conocida como \u201cLey de Salud Mental de Puerto Rico\u201d, no pas\u00f3 a votaci\u00f3n final, pese a que fue aprobada a viva voz en la sesi\u00f3n ordinaria de la C\u00e1mara de Representantes.<\/p>\n<p>La medida propone investigar esta ley para probar el alcance que ha tenido, y analizar posibles legislaciones para enmendar la ley.<\/p>\n<p>Seg\u00fan la exposici\u00f3n de motivos de la medida, la ley actualmente se encarga de actualizar las necesidades de tratamiento, recuperaci\u00f3n y rehabilitaci\u00f3n para proteger a las poblaciones afectadas por trastornos mentales con unos servicios adecuados a la persona. Asimismo, busca consignar sus derechos a recibir los servicios de salud mental, incluyendo los de los menores de edad.<\/p>\n<p>De igual manera, la ley tiene como fin promover la erradicaci\u00f3n de los prejuicios y estigmas contra las personas que padecen de trastornos mentales; y proveer unas gu\u00edas precisas a los profesionales de la salud mental sobre los derechos de las personas que reciben servicios de salud mental. Asimismo, determinar los procesos necesarios para salvaguardar los derechos que mediante esta Ley se establecen.<\/p>\n<p>Por otro lado, la ley busca \u201carmonizar los cambios que han experimentado las instituciones que proveen servicios con el establecimiento de la Reforma de Salud\u201d, y  resaltar los principios b\u00e1sicos de cuidado en los servicios prestados. De igual manera, pretende destacar los aspectos de recuperaci\u00f3n y rehabilitaci\u00f3n como parte integrante del tratamiento, as\u00ed como la prevenci\u00f3n.<\/p><div class=\"notic-content-middle\" id=\"notic-2036959694\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>Seg\u00fan el protocolo, la Comisi\u00f3n de la Salud, tendr\u00e1 que rendir un informe con sus hallazgos, conclusiones y recomendaciones en un periodo de 180 d\u00edas luego de la aprobaci\u00f3n de la medida.<\/p>\n<p>Otra medida que qued\u00f3 fuera de la votaci\u00f3n fue la Resoluci\u00f3n de la C\u00e1mara 947 (R. de la C. 947), de la autor\u00eda de la representante Lydia M\u00e9ndez Silva. Esta pieza legislativa propuso investigar sobre servicios educativos que han sido denegados a estudiantes con autismo y con condiciones de salud mental.<\/p>\n<p>De igual manera, la medida propone evaluar si el Departamento de Educaci\u00f3n ha incumplido \u201ccon su deber ministerial\u201d de proveerles a la poblaci\u00f3n con diversidad funcional el derecho a una educaci\u00f3n p\u00fablica, gratuita y apropiada de acuerdo con la \u201cLey de Educaci\u00f3n para Individuos con Discapacidades (IDEA, por sus siglas en ingl\u00e9s)\u201d.<\/p>\n<p>Bajo esta ley est\u00e1n cobijados los ni\u00f1os y j\u00f3venes entre los 3 y 21 a\u00f1os que, determinado por un equipo multidisciplinario, son elegibles en una o m\u00e1s de las 13 categor\u00edas de discapacidad espec\u00edficas. Al ser diagnosticados, estos estudiantes necesitan una educaci\u00f3n especial y servicios relacionados para tener un desarrollo acad\u00e9mico exitoso.<\/p>\n<p>La educaci\u00f3n p\u00fablica, seg\u00fan la ley, se define como educaci\u00f3n especial y servicios relacionados. Por otro lado, la educaci\u00f3n especial significa la instrucci\u00f3n, sin costo para los padres, dise\u00f1ada, especialmente, para atender las necesidades \u00fanicas del menor con diversidad funcional.<\/p>","protected":false},"excerpt":{"rendered":"<p>Uno de los prop\u00f3sitos de esta ley es promover la erradicaci\u00f3n de los prejuicios y estigmas contra la persona que padecen de trastornos mentales La medida para investigar el alcance y efectividad de la Ley 408-2000, conocida como \u201cLey de Salud Mental de Puerto Rico\u201d, no pas\u00f3 a votaci\u00f3n final, pese a que fue aprobada [&hellip;]<\/p>","protected":false},"author":0,"featured_media":261567,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[5,2],"tags":[],"class_list":["post-192516","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-legislatura","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/192516","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=192516"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/192516\/revisions"}],"predecessor-version":[{"id":261568,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/192516\/revisions\/261568"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/261567"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=192516"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=192516"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=192516"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}