{"id":191486,"date":"2023-03-26T11:41:56","date_gmt":"2023-03-26T15:41:56","guid":{"rendered":"https:\/\/www.noticel.com\/agricultura\/20230326\/pescadores-se-ponen-al-dia-en-preparacion-para-semana-santa\/"},"modified":"2025-07-12T10:09:11","modified_gmt":"2025-07-12T10:09:11","slug":"pescadores-se-ponen-al-dia-en-preparacion-para-semana-santa","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/economia\/agricultura\/20230326\/pescadores-se-ponen-al-dia-en-preparacion-para-semana-santa\/","title":{"rendered":"Pescadores se ponen al d\u00eda en preparaci\u00f3n para Semana Santa"},"content":{"rendered":"<h3>Secretario del Departamento de Agricultura, Ram\u00f3n Gonz\u00e1lez Beir\u00f3, hizo un llamado a ciudadanos a visitar las villas pesqueras y comprar pescado fresco en apoyo a los productores locales.<\/h3>\n<p>El secretario del Departamento de Agricultura, Ram\u00f3n Gonz\u00e1lez Beir\u00f3, hizo hoy un llamado a los ciudadanos a visitar las villas pesqueras del pa\u00eds y comprar pescado fresco en apoyo a los productos locales en v\u00edspera de la Semana Santa.<\/p>\n<p>Seg\u00fan explic\u00f3 el secretario, una de las medidas tomadas por la agencia fue atemperar un contrato uniforme y centralizado con 12 pescader\u00edas \u00abpara que puedan vender y recibir clientes para esta temporada\u201d.<\/p>\n<p>El funcionario, quien hizo entrega de la Proclama Oficial que declara del 26 al 1 de marzo la Semana de la Industria Pesquera, detall\u00f3 los esfuerzos que se han gestionado para atender y mejorar las pescader\u00edas existentes.<\/p><div class=\"notic-content-middle\" id=\"notic-3840621877\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>Al respecto, abund\u00f3 que \u201cse hicieron mejoras en los muelles de villas pesquera en Salinas y Cata\u00f1o. Las villas pesqueras de Mayag\u00fcez fueron consolidadas para crear un solo grupo administrativo y facilitar la inversi\u00f3n de fondos CDBG DR del municipio de Mayag\u00fcez. Tanto las villas pesqueras de Ceiba, Guayama y Mayag\u00fcez completaron el proceso de subasta y en los pr\u00f3ximos meses concluye la remodelaci\u00f3n\u00bb.<\/p>\n<p>Agreg\u00f3 que, \u00abpor otro lado, estamos colaborando con los consorcios de los municipios de Mayag\u00fcez, Aguadilla y Vieques para desarrollar programas educativos en construcci\u00f3n de lanchas, muelles y rampas y en manejo de recursos pesqueros. Se est\u00e1 solicitando $1,000,000 a los municipios para cubrir los equipos y otros costos de licencias para los participantes\u00bb.<\/p>\n<p>El titular de Agricultura exhort\u00f3 a los pescadores a mantener \u00ablos altos niveles de calidad y compromiso con la conservaci\u00f3n de los recursos marinos para lograr que futuras generaciones puedan disfrutar de la pesca puertorrique\u00f1a\u00bb.<\/p>","protected":false},"excerpt":{"rendered":"<p>Secretario del Departamento de Agricultura, Ram\u00f3n Gonz\u00e1lez Beir\u00f3, hizo un llamado a ciudadanos a visitar las villas pesqueras y comprar pescado fresco en apoyo a los productores locales. El secretario del Departamento de Agricultura, Ram\u00f3n Gonz\u00e1lez Beir\u00f3, hizo hoy un llamado a los ciudadanos a visitar las villas pesqueras del pa\u00eds y comprar pescado fresco [&hellip;]<\/p>","protected":false},"author":0,"featured_media":263806,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[27],"tags":[],"class_list":["post-191486","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agricultura"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/191486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=191486"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/191486\/revisions"}],"predecessor-version":[{"id":263807,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/191486\/revisions\/263807"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/263806"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=191486"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=191486"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=191486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}