{"id":191237,"date":"2023-03-20T15:16:58","date_gmt":"2023-03-20T19:16:58","guid":{"rendered":"https:\/\/www.noticel.com\/ahora\/top-stories\/tribunales\/20230320\/alcalde-de-catano-posiblemente-testificara-por-parte-de-la-defensa-en-el-juicio-contra-angel-perez\/"},"modified":"2025-07-12T10:27:50","modified_gmt":"2025-07-12T10:27:50","slug":"alcalde-de-catano-posiblemente-testificara-por-parte-de-la-defensa-en-el-juicio-contra-angel-perez","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20230320\/alcalde-de-catano-posiblemente-testificara-por-parte-de-la-defensa-en-el-juicio-contra-angel-perez\/","title":{"rendered":"Alcalde de Cata\u00f1o posiblemente testificar\u00e1 por parte de la defensa en el juicio contra \u00c1ngel P\u00e9rez"},"content":{"rendered":"<h3>Julio Alicea Vasallo sali\u00f3 del tribunal luego de que la jueza Aida Delgado Col\u00f3n, recomend\u00f3 que cualquier posible testigo en el caso abandonara la sala.<\/h3>\n<p>El licenciado Osvaldo Carlo Linares, abogado del exalcalde de Guaynabo \u00c1ngel P\u00e9rez Otero, inform\u00f3 que posiblemente el alcalde de Cata\u00f1o, Julio Alicea Vasallo, sea testigo en el juicio por parte de la defensa.<\/p>\n<p>Carlo Linares se expres\u00f3 a su salida del Tribunal Federal en Hato Rey, luego de que la jueza Aida Delgado Col\u00f3n decretara receso hasta la 1:15 pm por presunto baj\u00f3n de az\u00facar por parte del testigo del Ministerio P\u00fablico, Oscar Santamaria Torres.<\/p>\n<p>\u201cPosiblemente, sea testigo (Alicea Vasallo), y podr\u00eda ser de la defensa\u201d, indic\u00f3 Carlo Linares.<\/p>\n<p>Al comenzar hoy el juicio por corrupci\u00f3n contra el exalcalde P\u00e9rez Otero, las partes se acercaron a la jueza Aida Delgado, y luego de unos minutos, la jueza recomend\u00f3 que cualquier posible testigo en el caso abandonara la sala.<\/p>\n<p>Luego de las expresiones de la jueza, Alicea Vasallo abandon\u00f3 la sala. Pese a que NotiCel le pregunt\u00f3 al alcalde si era testigo del Ministerio P\u00fablico o de defensa, el alcalde no quiso emitir comentarios, y asegur\u00f3 que ma\u00f1ana se expresar\u00e1 sobre el tema. De igual manera, el alcalde no quiso comentar sobre el estatus actual de las demandas que realiz\u00f3 el Municipio de Cata\u00f1o en el a\u00f1o 2021. El Municipio demand\u00f3 a Waste Collection, Asphalt y Island Builders Corp.<\/p>\n<p>En las demandas, el Municipio exigi\u00f3 el recobro, con intereses, y en cada una un pago por temeridad, valorado en $100,000, pero sin definir cu\u00e1les fueron los actos temerarios; un pago de $100,000 por honorarios; y un pago de $250,000 por da\u00f1os.<\/p>\n<p>De igual manera, Cata\u00f1o busca recobrar $13,418,333.30 de Waste Collection y Santamar\u00eda Torres, quien se declar\u00f3 culpable por conseguir contratos p\u00fablicos por soborno; $9,213,375.20 de J.R. Asphalt Inc. y sus codue\u00f1os Raymond Rodr\u00edguez Santos -quien tambi\u00e9n es culpable por soborno-, y Mario Villegas Vargas, sentenciado a 46 meses de prisi\u00f3n y tres a\u00f1os de libertad supervisada por el esquema de corrupci\u00f3n relacionado con el exalcalde de Cata\u00f1o Felix \u201cEl Cano\u201d Delgado Montalvo; y $584,220.00 de parte de Island Builders Corp. y Santamar\u00eda Torres.<\/p><div class=\"notic-content-middle\" id=\"notic-1616429289\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-970&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1.jpg 970w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-300x77.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-768x198.jpg 768w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-18x5.jpg 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"250\"   \/><\/a><\/div>\n<p>El juicio contra el exalcalde de Guaynabo comenz\u00f3 la semana pasada, y luego del tercer d\u00eda de juicio, que culmin\u00f3 con el testimonio del exalcalde de Cata\u00f1o, quien est\u00e1 convicto por corrupci\u00f3n, comenz\u00f3 el testimonio de Santamar\u00eda Torres.<\/p>\n<p>Durante el testimonio en la ma\u00f1ana de Santamar\u00eda Torres, se presentaron varios videos en el que se le observa junto a P\u00e9rez Otero en cafeter\u00edas pidiendo caf\u00e9 y \u201cbizcochitos de ma\u00edz\u201d mientras se pasaban un sobre por debajo de la mesa. En uno de los videos, ambos se observan en una guagua, y Santamar\u00eda le entrega un sobre blanco a P\u00e9rez Otero.<\/p>\n<p>A preguntas del fiscal federal Nicholas Cannon, Santamar\u00eda Torres confirm\u00f3 que el sobre blanco conten\u00eda $5,000 en efectivo. Asimismo, asegur\u00f3 que, el dinero que se entreg\u00f3 en la guagua el 19 de agosto de 2021, se lo provey\u00f3 la Oficina Federal de Investigaci\u00f3n (FBI, por sus siglas en ingl\u00e9s), y esta agencia inspeccion\u00f3 su veh\u00edculo antes del encuentro con el exalcalde de Guaynabo para verificar que no hubiese m\u00e1s dinero.<\/p>\n<p><strong id=\"strong-72ac0d3ba85dc98fd13e28cdb779e757\">Vea<\/strong>:<\/p>\n<p><a href=\"https:\/\/noticel.com\/en\/tribunales\/ahora\/top-stories\/20230320\/oscar-santamaria-y-su-llorao-llegan-al-banquillo-de-los-testigos\/\" id=\"link-4c0d1aefb51bbcbe3159c8ba11c7feed\">Oscar Santamar\u00eda, y su llora\u2019o, llegan al banquillo de los testigos<\/a><\/p>\n<p><a href=\"https:\/\/noticel.com\/en\/gobierno\/ahora\/top-stories\/20230320\/pierluisi-que-el-caso-de-angel-perez-sirva-como-disuasivo\/\" id=\"link-ccf85ba04dee51e8a2b8b22b8d1e9556\">Pierluisi: Que el caso de \u00c1ngel P\u00e9rez \u00absirva como disuasivo\u00bb<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Julio Alicea Vasallo sali\u00f3 del tribunal luego de que la jueza Aida Delgado Col\u00f3n, recomend\u00f3 que cualquier posible testigo en el caso abandonara la sala. El licenciado Osvaldo Carlo Linares, abogado del exalcalde de Guaynabo \u00c1ngel P\u00e9rez Otero, inform\u00f3 que posiblemente el alcalde de Cata\u00f1o, Julio Alicea Vasallo, sea testigo en el juicio por parte [&hellip;]<\/p>","protected":false},"author":0,"featured_media":264353,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[13,2],"tags":[],"class_list":["post-191237","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tribunales","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/191237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=191237"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/191237\/revisions"}],"predecessor-version":[{"id":264355,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/191237\/revisions\/264355"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/264353"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=191237"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=191237"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=191237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}