{"id":188725,"date":"2023-01-19T16:51:08","date_gmt":"2023-01-19T20:51:08","guid":{"rendered":"https:\/\/www.noticel.com\/economia\/emprender\/foodie\/vida\/20230119\/artesanos-y-comerciantes-locales-se-destacan-en-el-primer-dia-de-las-fiestas-de-la-sanse\/"},"modified":"2025-08-27T22:34:07","modified_gmt":"2025-08-27T22:34:07","slug":"artesanos-y-comerciantes-locales-se-destacan-en-el-primer-dia-de-las-fiestas-de-la-sanse","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/economia\/20230119\/artesanos-y-comerciantes-locales-se-destacan-en-el-primer-dia-de-las-fiestas-de-la-sanse\/","title":{"rendered":"Artesanos y comerciantes locales se destacan en el primer d\u00eda de las Fiestas de la SanSe"},"content":{"rendered":"<h3>Dos artesanos de joyer\u00eda, y una pareja de comerciantes locales, especializados en cocteler\u00eda, conversaron con NotiCel para compartir los servicios que ofrecer\u00e1n durante el evento<\/h3>\n<p>En el primer d\u00eda de las Fiestas de la Calle San Sebasti\u00e1n, el ambiente estuvo c\u00f3modo entre dos artesanos, que dieron a conocer sus piezas de joyer\u00eda, y una pareja de comerciantes locales que llevaron su innovador negocio de cocteler\u00eda al evento.<\/p>\n<p>En la Plaza del Quinto Centenario se ubican los artesanos, y negociantes locales con sus quioscos de comida y bebidas para llamar la atenci\u00f3n del p\u00fablico que recorre las calles del Viejo San Juan durante el d\u00eda. Este fue el caso del artesano Eduardo Paz, con su marca Kimpande; la artesana Doris Moro, con su marca Creaciones Cristaly; y de Tipsy Mobile, creado por Lorena Serrall\u00e9s y Jan Carlos Aulet.<\/p>\n<p><strong id=\"strong-b5af76c1595272ae2d1856248c6c2971\">Kimpande<\/strong><\/p>\n<p>El due\u00f1o y artesano de la marca \u201cKimpande\u201d comparti\u00f3 con NotiCel que su marca busca indagar en las ra\u00edces africanas de los puertorrique\u00f1os para educar sobre su cultura y educar m\u00e1s all\u00e1 de la bomba y la plena.<\/p>\n<p>\u201cYo quer\u00eda indagar un poco m\u00e1s, en cuanto a la herencia, y dar mayores detalles de cu\u00e1les eran los distintos grupos que fueron tra\u00eddos a la Isla\u201d, se\u00f1al\u00f3 el artesano.<\/p>\n<p>Las piezas de joyer\u00eda est\u00e1n hechas en bronce, plata, y hay algunas piezas con elementos de cuerno de res. Paz desarroll\u00f3 esta marca, ya que sent\u00eda la ausencia, en la artesan\u00eda, de joyer\u00eda que representara la herencia africana.<\/p>\n<p>\u201cLo que yo trato de hacer con cada una de las piezas es educar sobre nuestra herencia e historia. Por ejemplo, dentro de distintos grupos en el continente africano, el cuerno es visto como un elemento de buena suerte y de protecci\u00f3n. Por ejemplo, tengo una pulsera de bronce, que es en forma de \u2018rungu\u2019 y es como una macana que se hace en madera. Esto est\u00e1 atado a lo que es nuestra herencia africana \u201d, indic\u00f3 Paz.<\/p>\n<p>El artesano se\u00f1al\u00f3 que el \u201crungu\u201d, y las gargantillas con las puntas de cuerno est\u00e1n entre sus piezas m\u00e1s vendidas. Asimismo, espera gran movimiento por parte de los ciudadanos en los d\u00edas que restan de las Fiestas.<\/p>\n<p>La marca se puede encontrar a trav\u00e9s de la red social Instagram como @kimpande_jewerly.<\/p>\n<p><strong id=\"strong-26239a2ad11a4ecf0f9da448f18c14e0\">Creaciones Cristaly<\/strong><\/p>\n<p>La due\u00f1a de \u201cCreaciones Cristaly\u201d comparti\u00f3 que su pasi\u00f3n por la artesan\u00eda surgi\u00f3 luego de haberse retirado de su carrera como enfermera. Moro hace rosarios, pantallas, y collares de unas semillas llamadas cam\u00e1ndulas. Asimismo, comparti\u00f3 que estas semillas se asemejan al m\u00e1rmol por sus matices y sus l\u00edneas.<\/p>\n<p>\u201cYo era enfermera graduada, me retir\u00e9 y cog\u00ed esto de pasatiempo. Para m\u00ed esto es una terapia. Trabajo con semillas que son sacadas de la tierra, se limpian, se les da forma, y despu\u00e9s se hacen las prendas\u201d, explic\u00f3 Moro.<\/p>\n<p>Como parte del proceso, la artesana se\u00f1al\u00f3 que algunas semillas las encuentra por su cuenta, y otras se las proveen de Adjuntas o San Sebasti\u00e1n. De igual manera, la due\u00f1a indic\u00f3 que los rosarios que trabaja son los m\u00e1s que vende, y le toma, aproximadamente, 20 minutos en realizarlos.<\/p>\n<p>La artesana exhort\u00f3 a otros futuros artesanos a que trabajen, y no tengan miedo de crear cosas nuevas. Asimismo, Moro comparti\u00f3 su red social de Instagram (@creacionescristalipr) para las personas que est\u00e9n interesadas.<\/p>\n<p><strong id=\"strong-45b3db477388a2c969acf3bbac344ff4\">Tipsy Mobile Bar<\/strong><\/p>\n<p>El negocio de \u201cTipsy Mobile Bar\u201d es un carret\u00f3n antiguo de caballos restaurado en una barra m\u00f3vil para actividades privadas y eventos especiales. Durante la SanSe, tendr\u00e1n un men\u00fa de cocteler\u00eda desde \u201cMoscow Mule\u00bb hasta su cl\u00e1sico \u201cCoco Paradise\u201d.<\/p>\n<p>La pareja de emprendedores, Lorena Serrall\u00e9s y Jan Carlos Aulet, se motivaron a crear este negocio, ya que hace un a\u00f1o comenzaron la planificaci\u00f3n de su boda, y quer\u00edan \u201calgo divertido y diferente\u201d para el d\u00eda del casamiento. Por esta raz\u00f3n, decidieron hacerlo por su cuenta, ya que tienen a\u00f1os de experiencia en la industria coctelera.<\/p>\n<p>\u201cHacemos todo tipo de cocteler\u00eda personalizada, dependiendo los gustos del cliente, y vamos al evento, hasta el lugar que nos indique. Este servicio puede ser con los carretones, que tenemos uno blanco y uno negro o con unas barras m\u00f3viles peque\u00f1as que tenemos\u201d, explic\u00f3 Serall\u00e9s.<\/p>\n<p>Si desea recibir m\u00e1s informaci\u00f3n sobre los servicios del negocio, los puede contactar a trav\u00e9s de su p\u00e1gina de Instagram (@tipsymobilebar) o su p\u00e1gina web (tipsymobilebar.com).<\/p>","protected":false},"excerpt":{"rendered":"<p>Dos artesanos de joyer\u00eda, y una pareja de comerciantes locales, especializados en cocteler\u00eda, conversaron con NotiCel para compartir los servicios que ofrecer\u00e1n durante el evento En el primer d\u00eda de las Fiestas de la Calle San Sebasti\u00e1n, el ambiente estuvo c\u00f3modo entre dos artesanos, que dieron a conocer sus piezas de joyer\u00eda, y una pareja [&hellip;]<\/p>","protected":false},"author":1,"featured_media":269799,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[22,26,69],"tags":[],"class_list":["post-188725","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia","category-empresarismo","category-vida-y-bienestar"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/188725","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=188725"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/188725\/revisions"}],"predecessor-version":[{"id":269803,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/188725\/revisions\/269803"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/269799"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=188725"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=188725"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=188725"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}