{"id":186803,"date":"2022-12-05T13:00:41","date_gmt":"2022-12-05T17:00:41","guid":{"rendered":"https:\/\/www.noticel.com\/ahora\/top-stories\/20221205\/alcalde-de-ponce-asegura-no-va-a-renunciar\/"},"modified":"2025-07-12T15:43:23","modified_gmt":"2025-07-12T15:43:23","slug":"alcalde-de-ponce-asegura-no-va-a-renunciar","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20221205\/alcalde-de-ponce-asegura-no-va-a-renunciar\/","title":{"rendered":"Alcalde de Ponce asegura no va a renunciar"},"content":{"rendered":"<h3>En medio de investigaci\u00f3n de Justicia por supuestamente obligar a empleados a pagar un pr\u00e9stamo que tom\u00f3 para costear parte de su campa\u00f1a electoral.<\/h3>\n<p>El alcalde de Ponce, Luis Manuel Irizarry Pab\u00f3n asegur\u00f3 el lunes, que no va a renunciar tras los se\u00f1alamientos de una supuesta investigaci\u00f3n de Justicia por un pr\u00e9stamos atribuido a su campa\u00f1a para que empleados de confianza lo paguen.<\/p>\n<p>En entrevista radial (WKAQ 580 AM), el primer ejecutivo ponce\u00f1o dijo que desde octubre est\u00e1 cooperando con las autoridades, pero asegur\u00f3 que al momento no se le ha notificado que hay una investigaci\u00f3n en su contra y que todo se trata de conjeturas de sus enemigos pol\u00edticos.<\/p>\n<p>\u201cEn el mes de octubre, el Departamento de Justicia le pidi\u00f3 al municipio una informaci\u00f3n, unos expedientes de unos empleados. Este alcalde lo anunci\u00f3 y lo dijo de que vamos a estar cooperando en cualquier tipo de investigaci\u00f3n y lo hemos hecho hasta ahora. Definitivamente yo no le voy a contestar conjeturas, rumores, chismes, de personas que sabemos que algunos de ellos estuvieron conmigo y ellos saben por qu\u00e9 ya no est\u00e1n, y de adversarios pol\u00edticos. No tienen los votos y quieren difamar, y quieren atacar a este alcalde. Yo no voy a contestar alegaciones que yo no tengo conocimiento y que el Departamento de Justicia, a este alcalde, no le ha notificado hasta este momento ninguna otra cosa\u201d, dijo Irizarry Pab\u00f3n.<\/p>\n<p>\u00bbIrrizarry Pab\u00f3n no se quita. Irizarry Pab\u00f3n no va a renunciar, aquellos que estan diciendo eso. Yo voy a trabajar como lo he hecho hasta ahora. Yo no he tomado vacaciones. Voy a trabajar duro. y el que est\u00e9 a mi lado tiene que trabajar duro igual que el alcalde\u00bb, subray\u00f3.<\/p>\n<p>Seg\u00fan trascendi\u00f3 en los pasados d\u00edas, la Divisi\u00f3n de Integridad P\u00fablica y Asuntos del Contralor del Departamento de Justicia investiga denuncias que apuntan a que Irizarry Pab\u00f3n oblig\u00f3 a empleados municipales a que aportaran al pago de un pr\u00e9stamo personal de $50,000 que obtuvo y que no report\u00f3 al Contralor Electoral, aun cuando supuestamente utiliz\u00f3 gran parte del dinero para gastos relacionados con la pasada campa\u00f1a electoral.<\/p><div class=\"notic-content-middle\" id=\"notic-1318345465\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>Irizarry Pab\u00f3n asegur\u00f3 que nunca ha cometido nada ilegal, ni como alcalde ni en su plano personal y dijo que tampoco le preocupa que le radiquen cargos porque  estoy con la verdad\u00bb.<\/p>\n<p>\u201cAnte esas alegaciones an\u00f3nimas, que se prestan para da\u00f1ar reputaciones, yo no voy a contestar hasta el momento que Justicia determine si hay una investigaci\u00f3n directa contra esta persona. La gente me conoce, conoce al adversario, la gente conoce las personas que yo tuve que botar de mi gabinete (municipal) que no estaban haciendo el trabajo y estaban haciendo truquer\u00edas\u201d, sostuvo.<\/p>\n<p>Tras la publicaci\u00f3n de la investigaci\u00f3n, el candidato a la alcald\u00eda de Ponce por el Partido Nuevo Progresista (PNP), licenciado Pablo Col\u00f3n Santiago, ha solicitado reiteradamente la renuncia del alcalde.<\/p>\n<p>Col\u00f3n Santiago fue el director de campa\u00f1a de la hoy ex alcaldesa y cabildera por la estadidad, Mar\u00eda Elo\u00edsa \u201cMayita\u201d Mel\u00e9ndez Altieri.<\/p>\n<p>\u201cEl truquero no cabe dentro de mi grupo de trabajo. Pero eso es otro cantar. Nosotros vamos a respetar la Ley y vamos a cumplir con la misma\u201d, acot\u00f3.<\/p>","protected":false},"excerpt":{"rendered":"<p>En medio de investigaci\u00f3n de Justicia por supuestamente obligar a empleados a pagar un pr\u00e9stamo que tom\u00f3 para costear parte de su campa\u00f1a electoral. El alcalde de Ponce, Luis Manuel Irizarry Pab\u00f3n asegur\u00f3 el lunes, que no va a renunciar tras los se\u00f1alamientos de una supuesta investigaci\u00f3n de Justicia por un pr\u00e9stamos atribuido a su [&hellip;]<\/p>","protected":false},"author":0,"featured_media":273885,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-186803","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/186803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=186803"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/186803\/revisions"}],"predecessor-version":[{"id":273886,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/186803\/revisions\/273886"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/273885"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=186803"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=186803"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=186803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}