{"id":18673,"date":"2017-05-27T00:00:00","date_gmt":"2017-05-27T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/ahora\/educacion\/politica\/upr\/20170527\/colectivo-nacional-hace-pedido-al-gobernador\/"},"modified":"2025-07-16T16:55:59","modified_gmt":"2025-07-16T16:55:59","slug":"colectivo-nacional-hace-pedido-al-gobernador","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20170527\/colectivo-nacional-hace-pedido-al-gobernador\/","title":{"rendered":"Colectivo Nacional hace pedido al Gobernador"},"content":{"rendered":"<p>El Colectivo Nacional Todos Somos Pueblo solicit\u00f3 el s\u00e1bado al gobernador Ricardo Rossell\u00f3 y a la Legislatura que con prontitud llenen las vacantes en la Junta de Gobierno de la Universidad de Puerto Rico (UPR), para buscar poner fin a la huelga.<\/p>\n<p>&#8216;Agilicen el proceso de confirmaci\u00f3n de las personas identificadas para formar parte de la Junta. Obviamente, si el gobierno de Puerto Rico desea con honestidad que se reabran los portones de nuestra universidad, entonces debe hacer todas las gestiones necesarias, particularmente la Legislatura, y con tal premura como para que haya &#8216;qu\u00f3rum&#8217; en la Junta y se consideren los pre-acuerdos asumidos hasta el momento. De manera, que las clases se pueden iniciar tan pronto el gobierno y la Junta cumplan con lo que les corresponde; pues los estudiantes ya han cumplido con su parte&#8217;, puntualiz\u00f3 el padre Pedro R. Ortiz, portavoz del Colectivo.<\/p><div class=\"notic-content-middle\" id=\"notic-1138100558\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/jackpotdelencantopr.com\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"JP-Monopoly-Teaser-Noticel-728&#215;90\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/13202238\/JP-Monopoly-Teaser-Noticel-728x90-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/13202238\/JP-Monopoly-Teaser-Noticel-728x90-1.jpg 728w, https:\/\/cdn.noticel.com\/2026\/07\/13202238\/JP-Monopoly-Teaser-Noticel-728x90-1-300x37.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/13202238\/JP-Monopoly-Teaser-Noticel-728x90-1-18x2.jpg 18w\" sizes=\"(max-width: 728px) 100vw, 728px\" width=\"728\" height=\"90\"   \/><\/a><\/div>\n<p>&#8216;Tal parece que en Fortaleza y en la Legislatura no tienen prisa porque ellos han expresado que eso del nombramiento de nuevos miembros para la Junta, seguir\u00e1 en la Legislatura su tr\u00e1mite \u2018ordinario&#8217; de nombramientos. No quiero ser \u2018profeta de la calamidad&#8217;, pero me da la impresi\u00f3n que esa notable \u2018paciencia&#8217; es \u2018estancamiento&#8217; en medio de una crisis tan aguda, puede terminar con la no ratificaci\u00f3n de lo acordado en el comit\u00e9 de dialogo por parte de la junta. Ojal\u00e1 y me equivoque porque soy el primero que conf\u00eda en que solo el dialogo \u00e9tico ser\u00e1 la llave que abra los portones de nuestra Universidad&#8217;, a\u00f1adi\u00f3.<\/p>\n<p>De otro lado, el Colectivo reconoci\u00f3 las gestiones hechas por los estudiantes en huelga y su determinaci\u00f3n de ratificar los pre-acuerdos del proceso de di\u00e1logo<\/p>","protected":false},"excerpt":{"rendered":"<p>El Colectivo Nacional Todos Somos Pueblo solicit\u00f3 el s\u00e1bado al gobernador Ricardo Rossell\u00f3 y a la Legislatura que con prontitud llenen las vacantes en la Junta de Gobierno de la Universidad de Puerto Rico (UPR), para buscar poner fin a la huelga. &#8216;Agilicen el proceso de confirmaci\u00f3n de las personas identificadas para formar parte de [&hellip;]<\/p>","protected":false},"author":0,"featured_media":460657,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ep_exclude_from_search":false,"footnotes":""},"categories":[7,2],"tags":[],"class_list":["post-18673","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/18673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=18673"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/18673\/revisions"}],"predecessor-version":[{"id":460659,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/18673\/revisions\/460659"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/460657"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=18673"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=18673"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=18673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}