{"id":18522,"date":"2011-01-11T00:00:00","date_gmt":"2011-01-11T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/deportes\/20110111\/caanen-con-coamo\/"},"modified":"2025-07-16T17:12:35","modified_gmt":"2025-07-16T17:12:35","slug":"caanen-con-coamo","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/deportes\/20110111\/caanen-con-coamo\/","title":{"rendered":"Caanen con Coamo"},"content":{"rendered":"<p><i>Caanen con Coamo<\/i><\/p>\n<p>Los Maratonistas presentar\u00e1n hoy en conferencia de prensa a su nuevo gerente general, el ex jugador Wilhelmus Caanen.<\/p>\n<p>Los Maratonistas de Coamo esperan completar durante el<\/p>\n<p>transcurso de esta semana los acuerdos de trabajo con su<\/p>\n<p>gerente general y su dirigente, seg\u00fan dio a conocer el tenedor de<\/p>\n<p>franquicia del equipo, el Dr. Rael Bernier.<\/p>\n<p>El ex jugador Wilhelmus Caanen es el principal candidato para<\/p>\n<p>tomar las riendas administrativas del equipo en uni\u00f3n al grupo<\/p>\n<p>de trabajo que ya fue completado, de acuerdo con Bernier.<\/p>\n<p>Y la lista de posibles dirigente incluye a dos t\u00e9cnicos que<\/p>\n<p>trabajaron como entrenadores en el pasado torneo: Pedro<\/p>\n<p>Cintr\u00f3n (Ponce) y Juan Cardona (Guaynabo).<\/p>\n<p>\u00abVamos a estar entrevistando a varios coaches esta semana,<\/p>\n<p>cuando ya tengamos trabajando como gerente general y<\/p>\n<p>director de operaciones de campo a Caanen\u00bb, dijo Bernier,<\/p>\n<p>cuyos Maratonistas regresan al torneo del Baloncesto Superior<\/p>\n<p>Nacional (BSN) luego de dos a\u00f1os de ausencia.<\/p>\n<p>Bernier indic\u00f3 que Juan Molina y Alan Col\u00f3n tambi\u00e9n son<\/p>\n<p>candidatos para el puesto de dirigente.<\/p>\n<p>Los Maratonistas, inclusive, comenzar\u00e1n a evaluar con mayor<\/p>\n<p>detenimiento las ofertas de cambios que se han producido y que<\/p>\n<p>involucran a algunos de los principales jugadores del quinteto,<\/p>\n<p>como Alex Galindo y Johwen Villegas, quienes jugaron para<\/p>\n<p>Mayaguez y San Germ\u00e1n, respectivamente, en el pasado torneo.<\/p><div class=\"notic-content-middle\" id=\"notic-3915672775\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/jackpotdelencantopr.com\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"JP-Monopoly-Teaser-Noticel-970&#215;90\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/13202405\/JP-Monopoly-Teaser-Noticel-970x90-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/13202405\/JP-Monopoly-Teaser-Noticel-970x90-1.jpg 970w, https:\/\/cdn.noticel.com\/2026\/07\/13202405\/JP-Monopoly-Teaser-Noticel-970x90-1-300x28.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/13202405\/JP-Monopoly-Teaser-Noticel-970x90-1-768x71.jpg 768w, https:\/\/cdn.noticel.com\/2026\/07\/13202405\/JP-Monopoly-Teaser-Noticel-970x90-1-18x2.jpg 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"90\"   \/><\/a><\/div>\n<p>\u00abNuestra primera opci\u00f3n es quedarnos con esos jugadores<\/p>\n<p>que son nuestras reservas, pero no nos hemos cerrado a nada.<\/p>\n<p>Tenemos ofertas de Mayaguez, San Germ\u00e1n y de Quebradillas,<\/p>\n<p>pero hasta que no tengamos completo nuestro equipo de trabajo<\/p>\n<p>no vamos a tomar decisiones. Eso pudiera ocurrir durante esta<\/p>\n<p>semana\u00bb.<\/p>\n<p>Bernier dijo que todav\u00eda est\u00e1 a la espera de unas asignaciones<\/p>\n<p>de fondos para la instalaci\u00f3n del acondicionador de aire que<\/p>\n<p>necesita la cancha Edwin &#8216;Puruco&#8217; Nolasco para cumplir con las<\/p>\n<p>exigencias del BSN. De lo contrario, el equipo considera jugar<\/p>\n<p>sus partidos locales en Juana D\u00edaz.<\/p>\n<p>\u00abSi no ocurre (la asignaci\u00f3n de fondos) en estas pr\u00f3ximas<\/p>\n<p>semanas, vamos a cuadrar lo de Juana D\u00edaz. Aqu\u00ed hay mucho<\/p>\n<p>entusiasmo, y nos hace falta el baloncesto\u00bb, apunt\u00f3.<\/p>\n<p>Los Maratonistas de Coamo completaron durante el transcurso de esta semana los acuerdos de trabajo con su nuevo gerente general y su dirigente, seg\u00fan dio a conocer el tenedor de franquicia del equipo, el Dr. Rael Bernier, a la oficina de prensa del Baloncesto Superior Nacional (BSN).<\/p>\n<p>El ex jugador Wilhelmus Caanen es el principal candidato para tomar las riendas administrativas del equipo, en uni\u00f3n al grupo de trabajo que ya fue completado, de acuerdo con Bernier.<\/p>\n<p>Noticel supo que Caanen ser\u00e1 presentado esta tarde durante una conferencia de prensa a efectuarse en el restaurant Pi\u00f1a Colada del Hotel Caribe Hilton, en San Juan.<\/p>\n<p>Asimismo, se espera que presenten su nuevo dirigente. La lista de posibles dirigentes incluye a dos t\u00e9cnicos que trabajaron como entrenadores en el pasado torneo: Pedro Cintr\u00f3n (Ponce) y Juan Cardona (Guaynabo).<\/p>\n<p>\u00abVamos a estar entrevistando a varios coaches esta semana, cuando ya tengamos trabajando como gerente general y director de operaciones de campo a Caanen\u00bb, dijo durante el fin de semana Bernier, cuyos Maratonistas regresan al torneo del BSN luego de dos a\u00f1os de ausencia.<\/p>\n<p>Bernier indic\u00f3 que Juan Molina y Alan Col\u00f3n tambi\u00e9n son candidatos para el puesto de dirigente. Los Maratonistas, inclusive, comenzar\u00e1n a evaluar con mayor detenimiento las ofertas de cambios que se han producido y que involucran a algunos de los principales jugadores del quinteto, como Alex Galindo y Johwen Villegas, quienes jugaron paraMayaguez y San Germ\u00e1n, respectivamente, en el pasado torneo.<\/p>\n<p>\u00abNuestra primera opci\u00f3n es quedarnos con esos jugadores que son nuestras reservas, pero no nos hemos cerrado a nada.Tenemos ofertas de Mayaguez, San Germ\u00e1n y de Quebradillas, pero hasta que no tengamos completo nuestro equipo de trabajo no vamos a tomar decisiones. Eso pudiera ocurrir durante esta semana\u00bb, expuso.<\/p>\n<p>Bernier dijo que todav\u00eda est\u00e1 a la espera de unas asignaciones de fondos para la instalaci\u00f3n del acondicionador de aire que necesita la cancha Edwin &#8216;Puruco&#8217; Nolasco para cumplir con las exigencias del BSN.<\/p>\n<p>De lo contrario, el equipo considera jugar sus partidos locales en Juana D\u00edaz.\u00bbSi no ocurre (la asignaci\u00f3n de fondos) en estas pr\u00f3ximas semanas, vamos a cuadrar lo de Juana D\u00edaz. Aqu\u00ed hay mucho entusiasmo, y nos hace falta el baloncesto\u00bb, apunt\u00f3.<\/p>","protected":false},"excerpt":{"rendered":"<p>Caanen con Coamo Los Maratonistas presentar\u00e1n hoy en conferencia de prensa a su nuevo gerente general, el ex jugador Wilhelmus Caanen. Los Maratonistas de Coamo esperan completar durante el transcurso de esta semana los acuerdos de trabajo con su gerente general y su dirigente, seg\u00fan dio a conocer el tenedor de franquicia del equipo, el [&hellip;]<\/p>","protected":false},"author":0,"featured_media":461822,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ep_exclude_from_search":false,"footnotes":""},"categories":[31],"tags":[],"class_list":["post-18522","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/18522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=18522"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/18522\/revisions"}],"predecessor-version":[{"id":461824,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/18522\/revisions\/461824"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/461822"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=18522"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=18522"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=18522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}