{"id":181406,"date":"2022-08-04T17:47:47","date_gmt":"2022-08-04T21:47:47","guid":{"rendered":"https:\/\/www.noticel.com\/la-calle\/policiacas\/20220804\/cargos-por-tentativa-de-feminicidio-contra-joven-que-apunalo-a-su-novia\/"},"modified":"2025-07-12T22:27:37","modified_gmt":"2025-07-12T22:27:37","slug":"causa-para-arresto-contra-joven-que-apunalo-a-su-novia","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/la-calle\/20220804\/causa-para-arresto-contra-joven-que-apunalo-a-su-novia\/","title":{"rendered":"Causa para arresto contra joven que apu\u00f1al\u00f3 a su novia"},"content":{"rendered":"<h3>Los hechos ocurrieron el mi\u00e9rcoles en Carolina.<\/h3>\n<p>La jueza Larisa Ortiz Modesti determin\u00f3 causa para arresto e impuso una fianza de $125, 000 contra Luis Ra\u00fal Nieves O\u2019 Farrill,  imputado de apu\u00f1alar a su novia ayer en el pueblo de Carolina.<\/p>\n<p>La Fiscal\u00eda de Carolina del Departamento de Justicia present\u00f3 hoy cargos de tentativa de feminicidio y violaci\u00f3n a la Ley de Armas contra Nieves O\u2019 Farrill.<\/p>\n<p>Los fiscales Solimar Rosa Rodr\u00edguez y Jes\u00fas Peluyera Berr\u00edos, de la Unidad Especializada de Violencia Dom\u00e9stica, Delitos Sexuales y Maltrato de Menores, representaron al Ministerio P\u00fablico en la vista que se llev\u00f3 a cabo esta tarde en el Tribunal de Primera Instancia de Carolina.<\/p><div class=\"notic-content-middle\" id=\"notic-2121115221\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-970&#215;90\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1.jpg 970w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-300x28.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-768x71.jpg 768w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-18x2.jpg 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"90\"   \/><\/a><\/div>\n<p>La vista preliminar fue se\u00f1alada para el 16 de agosto.<\/p>\n<p>Seg\u00fan la investigaci\u00f3n, el joven de 20 a\u00f1os y residente de Trujillo Alto, utilizando una navaja multiusos, apu\u00f1al\u00f3 en repetidas ocasiones a la v\u00edctima caus\u00e1ndole heridas en varias partes del cuerpo.<\/p>\n<p>La investigaci\u00f3n del lamentable suceso estuvo a cargo del agente de la Unidad de Violencia Dom\u00e9stica del Negociado de la Polic\u00eda, Manuel Cruz Carlo, junto a la Polic\u00eda Municipal de Carolina.<\/p>","protected":false},"excerpt":{"rendered":"<p>Los hechos ocurrieron el mi\u00e9rcoles en Carolina. La jueza Larisa Ortiz Modesti determin\u00f3 causa para arresto e impuso una fianza de $125, 000 contra Luis Ra\u00fal Nieves O\u2019 Farrill, imputado de apu\u00f1alar a su novia ayer en el pueblo de Carolina. La Fiscal\u00eda de Carolina del Departamento de Justicia present\u00f3 hoy cargos de tentativa de [&hellip;]<\/p>","protected":false},"author":24,"featured_media":285409,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12,15],"tags":[],"class_list":["post-181406","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-calle","category-policiacas"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/181406","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=181406"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/181406\/revisions"}],"predecessor-version":[{"id":285410,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/181406\/revisions\/285410"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/285409"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=181406"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=181406"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=181406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}