{"id":17985,"date":"2011-03-30T00:00:00","date_gmt":"2011-03-30T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/ahora\/20110330\/jefe-de-trabajo-no-sabe-cuantos-empleos-generara\/"},"modified":"2025-07-16T18:01:48","modified_gmt":"2025-07-16T18:01:48","slug":"jefe-de-trabajo-no-sabe-cuantos-empleos-generara","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20110330\/jefe-de-trabajo-no-sabe-cuantos-empleos-generara\/","title":{"rendered":"Jefe de Trabajo no sabe cu\u00e1ntos empleos generar\u00e1"},"content":{"rendered":"<p>El secretario del Departamento del Trabajo y Recursos Humanos, MIguel Romero, no pudo determinar la cantidad de empleos que esperan generar con cada una de las estrategias que est\u00e1 implementado el Gobierno y la dependencia que dirige.<\/p>\n<p>La admisi\u00f3n sorprende cuando se la compara con las estad\u00edsticas que se\u00f1alan que es la primera vez en 30 a\u00f1os que Puerto Rico tiene el m\u00e1s bajo indicador de gente trabajando, y porque se supone que cuando una administraci\u00f3n de gobierno planifica solucionar el desempleo debe tener ya una proyeci\u00f3n de la cantidad de nuevos puestos de trabajo que crear\u00e1 al final de la estrategia.<\/p>\n<p>Algunas de las ideas que mencion\u00f3 Romero fueron las Alianzas P\u00fablico Privadas, la estabilizacion fiscal del gobierno y la nueva ley de permisos.<\/p><div class=\"notic-content-middle\" id=\"notic-3723447412\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>Sus respuestas a preguntas de NotiCel se dieron durante el anuncio del proyecto &#8216;Pa&#8217; nuestra gente&#8217;, un proyecto que pretende promover la autogestion y el empresarismo.<\/p>\n<p><img decoding=\"async\" embed-content-articleid=\"664588595\" embed-content-groupid=\"593030475\" embed-content-id=\"664588595\" embed-content-index=\"0\" embed-content-type=\"PHOTO\" src=\"https:\/\/media.noticel.com\/o2com-noti-media-us-east-1\/photo\/2011\/03\/30\/pa_mi_gente_9495062_ver1.0_320_240.jpg\"\/><\/p>\n<p>&#8216;Pa&#8217; mi gente&#8217; comenzar\u00e1 con 30 empresarios, pero Romero resalt\u00f3 que esperan generar 430 kioskos y 800 empleos directos.<\/p>\n<p>Los kioskos funcionar\u00e1n enBarceloneta, Villalba, Loiza, Ponce, Camuy, Cidra, Corozal, San Juan, Fajardo, San Lorenzo, Juncos y Toa Baja, y ser\u00e1n de frutas, vegetales, comida, artesan\u00edas y florister\u00eda, entre otras propuestas.<\/p>","protected":false},"excerpt":{"rendered":"<p>El secretario del Departamento del Trabajo y Recursos Humanos, MIguel Romero, no pudo determinar la cantidad de empleos que esperan generar con cada una de las estrategias que est\u00e1 implementado el Gobierno y la dependencia que dirige. La admisi\u00f3n sorprende cuando se la compara con las estad\u00edsticas que se\u00f1alan que es la primera vez en [&hellip;]<\/p>","protected":false},"author":0,"featured_media":465547,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-17985","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/17985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=17985"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/17985\/revisions"}],"predecessor-version":[{"id":465550,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/17985\/revisions\/465550"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/465547"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=17985"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=17985"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=17985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}