{"id":179804,"date":"2022-06-29T06:44:06","date_gmt":"2022-06-29T10:44:06","guid":{"rendered":"https:\/\/www.noticel.com\/el-tiempo\/20220629\/ciclon-tropical-provoca-desde-hoy-aumento-en-los-vientos\/"},"modified":"2025-07-13T00:49:23","modified_gmt":"2025-07-13T00:49:23","slug":"ciclon-tropical-provoca-desde-hoy-aumento-en-los-vientos","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/el-tiempo\/20220629\/ciclon-tropical-provoca-desde-hoy-aumento-en-los-vientos\/","title":{"rendered":"Cicl\u00f3n tropical provoca desde hoy aumento en los vientos"},"content":{"rendered":"<h3>El cielo tambi\u00e9n se mantendr\u00e1 algo brumoso mientras los vientos alisios arrastran polvo del Sahara hacia el oeste.<\/h3>\n<p>El Potencial Cicl\u00f3n Tropical Dos se ha movido sobre la porci\u00f3n m\u00e1s al sur del Caribe y est\u00e1 ahora al sur de Puerto Rico y de las Islas V\u00edrgenes Americanas. Algunas bandas de lluvia leve podr\u00edan moverse sobre el \u00e1rea hoy, pero el efecto mayor ser\u00e1 un aumento en los vientos del este.<\/p>\n<p>Algunas \u00e1reas costeras observar\u00e1n vientos de 15 a 25 mph con r\u00e1fagas de hasta 30 mph o m\u00e1s en ocasiones durante el d\u00eda. Sin embargo, el cielo tambi\u00e9n se mantendr\u00e1 algo brumoso mientras los vientos alisios arrastran polvo del Sahara hacia el oeste.<\/p>\n<p>Los aguaceros continuar\u00e1n desarroll\u00e1ndose desde las islas hacia el este y sobre terreno m\u00e1s alto, pero las cantidades de lluvia ser\u00e1n menores debido a su movimiento r\u00e1pido. Los aguaceros y posiblemente algunas tronadas aisladas se desarrollar\u00e1n en el oeste e interior de Puerto Rico durante la tarde. Inundaciones urbanas y de riachuelos localizadas a\u00fan son posibles en el \u00e1rea.<\/p>\n<p>Las temperaturas altas de hoy fluctuaran desde los altos 70s en \u00e1reas m\u00e1s altas a los bajos 90s en elevaciones bajas del sur y oeste de la isla.<\/p><div class=\"notic-content-middle\" id=\"notic-1953724795\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>A trav\u00e9s de las aguas locales, se esperan vientos del este entre 15 y 22 nudos con r\u00e1fagas m\u00e1s altas en ocasiones. Las condiciones mar\u00edtimas continuar\u00e1n deterior\u00e1ndose, con oleaje entre seis y ocho pies sobre las aguas mar afuera y el Pasaje de Anegada hoy y esta noche y continuando el jueves. Por tal raz\u00f3n, se han emitido advertencias para los operadores de embarcaciones peque\u00f1as para las aguas mar afuera y el Pasaje de Anegada a medida que el Potencial Cicl\u00f3n Tropical Dos pase bien al sur del \u00e1rea y mantenga oleaje peligroso generado por los vientos.<\/p>\n<p>Existe un riesgo alto de corrientes marinas para la mayor\u00eda de las playas del norte y sureste de Puerto Rico, y las playas de la mitad este de Vieques y Culebra. Existe un riesgo moderado de corrientes marinas para el resto de las playas, excepto por la costa oeste de Puerto Rico desde Rinc\u00f3n hasta Boquer\u00f3n. El riesgo alto de corrientes marinas aumentar\u00e1 en \u00e1rea e intensidad para la mayor\u00eda de las playas durante el resto de la semana.<\/p>\n<p>https:\/\/twitter.com\/NWSSanJuan\/status\/1542086859710513152<\/p>","protected":false},"excerpt":{"rendered":"<p>El cielo tambi\u00e9n se mantendr\u00e1 algo brumoso mientras los vientos alisios arrastran polvo del Sahara hacia el oeste. El Potencial Cicl\u00f3n Tropical Dos se ha movido sobre la porci\u00f3n m\u00e1s al sur del Caribe y est\u00e1 ahora al sur de Puerto Rico y de las Islas V\u00edrgenes Americanas. Algunas bandas de lluvia leve podr\u00edan moverse [&hellip;]<\/p>","protected":false},"author":0,"featured_media":288914,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[18],"tags":[],"class_list":["post-179804","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-el-tiempo"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/179804","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=179804"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/179804\/revisions"}],"predecessor-version":[{"id":288915,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/179804\/revisions\/288915"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/288914"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=179804"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=179804"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=179804"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}