{"id":179468,"date":"2022-06-22T10:40:18","date_gmt":"2022-06-22T14:40:18","guid":{"rendered":"https:\/\/www.noticel.com\/la-calle\/20220622\/drna-insta-a-quienes-celebren-la-noche-de-san-juan-a-no-tirar-basura\/"},"modified":"2025-07-13T01:18:44","modified_gmt":"2025-07-13T01:18:44","slug":"drna-insta-a-quienes-celebren-la-noche-de-san-juan-a-no-tirar-basura","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/la-calle\/20220622\/drna-insta-a-quienes-celebren-la-noche-de-san-juan-a-no-tirar-basura\/","title":{"rendered":"DRNA insta a quienes celebren la Noche de San Juan a no tirar basura"},"content":{"rendered":"<h3>La contaminaci\u00f3n de las arenas y los mares se ha convertido en un verdadero problema, record\u00f3 la secretaria interina.<\/h3>\n<p>La secretaria interina de Recursos Naturales y Ambientales (DRNA), Ana\u00eds Rodr\u00edguez Vega, exhort\u00f3 a las personas que celebrar\u00e1n la Noche de San Juan este pr\u00f3ximo jueves, 23 de junio, en las playas u otros cuerpos de agua que depositen la basura que generen en los zafacones o se la lleven consigo y la coloquen en el zafac\u00f3n m\u00e1s cercano o en el de sus casas.<\/p>\n<p>\u201cLa Noche de San Juan es una larga tradici\u00f3n que todos disfrutamos. Y tambi\u00e9n debemos hacer la tradici\u00f3n de no arrojar basura en las playas, r\u00edos, quebradas y lagos. Los desechos que se dejan, como pl\u00e1stico, latas, vidrio, entre otros, son mortales para las especies marinas, algunas de ellas en peligro de extinci\u00f3n. S\u00f3lo con la activa colaboraci\u00f3n ciudadana tendremos \u00e9xito en la protecci\u00f3n y conservaci\u00f3n de los recursos naturales\u201d, apunt\u00f3 la funcionaria en declaraciones escritas.<\/p>\n<p>Este pr\u00f3ximo jueves 23 de junio de 9:00 de la ma\u00f1ana a 12:30 de la ma\u00f1ana, la ciudadan\u00eda podr\u00e1 disfrutar de esta tradici\u00f3n en los balanearios: Monserrate, en Luquillo; Sun Bay,en Vieques; Seven Seas, Fajardo; Punta Salinas, en Toa Baja; Manuel Nolo Morales, en Dorado; Cerro Gordo, en Vega Alta; Balneario de Boquer\u00f3n, en Cabo Rojo; y Ca\u00f1a Gorda, en Gu\u00e1nica.<\/p>\n<p>La contaminaci\u00f3n de las arenas y los mares se ha convertido en un verdadero problema, asegur\u00f3 la funcionaria. Aunque el Departamento de Recursos Naturales y Ambientales (DRNA), municipios y organizaciones no gubernamentales y de voluntarios limpian regularmente las playas, el problema persiste.<\/p>\n<p>\u201cEs tambi\u00e9n mi obligaci\u00f3n recordarle a la ciudadan\u00eda que no ha desarrollado todav\u00eda conciencia ambiental, que arrojar basura fuera de los zafacones en \u00e1reas p\u00fablicas es una violaci\u00f3n a las leyes ambientales. No hay violaci\u00f3n ambiental peque\u00f1a. Igualmente, solicito a los ba\u00f1istas y nautas a seguir las medidas de seguridad establecidas por la Ley 430 de Navegaci\u00f3n y Seguridad Acu\u00e1tica\u201d, afirm\u00f3 Rodr\u00edguez Vega.<\/p>\n<p>A su vez, anunci\u00f3 que los agentes del Cuerpo de Vigilantes estar\u00e1n activos este pr\u00f3ximo jueves, cuando se celebra la Noche de San Juan, en horario de 6:00 de la tarde hasta las 2:00 de la ma\u00f1ana. Las unidades terrestres y mar\u00edtimas redoblar\u00e1n esfuerzos e intensificar\u00e1n el patrullaje en las costas, a donde miles de personas llegan a celebrar la festividad.<\/p>\n<p>Asimismo, indic\u00f3 que los ba\u00f1istas deben tener cuidado y respetar los nidos de las tortugas marinas y que no se deben acercar a las \u00e1reas demarcadas por los grupos tortugueros.<\/p>\n<p>La titular interina de las agencias ambientales recomend\u00f3 a los ba\u00f1istas:<\/p>\n<p>tener cuidado en el agua para evitar ahogamientos; estar alertas a las condiciones del tiempo y del mar.<\/p><div class=\"notic-content-middle\" id=\"notic-2787833041\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-728&#215;90\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1.jpg 728w, https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1-300x37.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1-18x2.jpg 18w\" sizes=\"(max-width: 728px) 100vw, 728px\" width=\"728\" height=\"90\"   \/><\/a><\/div>\n<p>visitar los balnearios del Programa de Parques Nacionales del DRNA, que son las playas m\u00e1s seguras.<\/p>\n<p>llevarse la basura que genere y disponer de ella correctamente.<\/p>\n<p>no debe tocar alg\u00fan manat\u00ed, tortuga marina u otra especie marina, ni perseguirla o molestarla. Se debe llamar al Cuerpo de Vigilantes al 787-724-5700- si sospecha que alguno de estos animales est\u00e1 en peligro para que se coordine el apoyo de bi\u00f3logos de la agencia. Se debe respetar el espacio donde est\u00e1n los nidos y no acercarse.<\/p>\n<p>se debe respetar las \u00e1reas cercadas donde hay nidos de tinglar.<\/p>\n<p>no se debe da\u00f1ar la vegetaci\u00f3n en las playas, las dunas ni los arrecifes de coral.<\/p>\n<p>las fogatas est\u00e1n prohibidas en los balnearios y \u00e1reas naturales protegidas del DRNA.<\/p>\n<p>los nautas deben apelar a las medidas de seguridad mar\u00edtima; deben tener equipo completo y los ni\u00f1os deben usar salvavidas.<\/p>\n<p>EL DRNA invita a los ciudadanos a comunicarse con el Cuerpo de Vigilantes al 787-230-5550 o al 787-724-5700, de presenciar alg\u00fan evento que involucre a especies en peligro de extinci\u00f3n o amenazadas \u2013manat\u00edes o tortugas marinas- o actividades que pongan en riesgo la vida y seguridad de personas en el mar. Para emergencias en donde la vida o la propiedad est\u00e9n en peligro, recuerden llamar, o enviar mensaje de texto, al 9-1-1.<\/p>","protected":false},"excerpt":{"rendered":"<p>La contaminaci\u00f3n de las arenas y los mares se ha convertido en un verdadero problema, record\u00f3 la secretaria interina. La secretaria interina de Recursos Naturales y Ambientales (DRNA), Ana\u00eds Rodr\u00edguez Vega, exhort\u00f3 a las personas que celebrar\u00e1n la Noche de San Juan este pr\u00f3ximo jueves, 23 de junio, en las playas u otros cuerpos de [&hellip;]<\/p>","protected":false},"author":0,"featured_media":289638,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-179468","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-calle"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/179468","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=179468"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/179468\/revisions"}],"predecessor-version":[{"id":289639,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/179468\/revisions\/289639"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/289638"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=179468"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=179468"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=179468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}