{"id":178330,"date":"2022-05-28T16:12:24","date_gmt":"2022-05-28T20:12:24","guid":{"rendered":"https:\/\/www.noticel.com\/la-calle\/20220528\/encuentran-el-cadaver-de-un-hombre-en-residencia-de-urbanizacion-en-yabucoa\/"},"modified":"2025-07-13T05:07:45","modified_gmt":"2025-07-13T05:07:45","slug":"encuentran-el-cadaver-de-un-hombre-en-residencia-de-urbanizacion-en-yabucoa","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/la-calle\/20220528\/encuentran-el-cadaver-de-un-hombre-en-residencia-de-urbanizacion-en-yabucoa\/","title":{"rendered":"Encuentran el cad\u00e1ver de un hombre en residencia de urbanizaci\u00f3n en Yabucoa"},"content":{"rendered":"<h3>El hombre no ha sido identificado, pero las autoridades apuntan a que tiene entre 35 y 40 a\u00f1os.<\/h3>\n<p>El Negociado de la Polic\u00eda de Puerto Rico inform\u00f3 el hallazgo de un cad\u00e1ver en avanzado estado de descomposici\u00f3n, en el interior de una residencia en la calle Italia de la urbanizaci\u00f3n Jardines de Yabucoa.<\/p>\n<p>Seg\u00fan indica el informe preliminar de los hechos, los uniformados encontraron el cuerpo descompuesto de un hombre John Doe de entre 35 a 40 a\u00f1os.<\/p><div class=\"notic-content-middle\" id=\"notic-3774746763\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>El hombre no ha sido identificado, y la causa de muerte tampoco ha sido determinada.<\/p>\n<p>La agente Ileana Cruz, supervisada por el teniente F\u00e9lix R. Morales, se hicieron cargo de la investigaci\u00f3n. Ser\u00e1 la autopsia, y otras pruebas forenses, lo que determinar\u00e1 que provoc\u00f3 la muerte del hombre.<\/p>","protected":false},"excerpt":{"rendered":"<p>El hombre no ha sido identificado, pero las autoridades apuntan a que tiene entre 35 y 40 a\u00f1os. El Negociado de la Polic\u00eda de Puerto Rico inform\u00f3 el hallazgo de un cad\u00e1ver en avanzado estado de descomposici\u00f3n, en el interior de una residencia en la calle Italia de la urbanizaci\u00f3n Jardines de Yabucoa. Seg\u00fan indica [&hellip;]<\/p>","protected":false},"author":0,"featured_media":292127,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-178330","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-calle"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/178330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=178330"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/178330\/revisions"}],"predecessor-version":[{"id":292128,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/178330\/revisions\/292128"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/292127"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=178330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=178330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=178330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}