{"id":177683,"date":"2022-05-14T06:00:00","date_gmt":"2022-05-14T10:00:00","guid":{"rendered":"https:\/\/www.noticel.com\/?post_type=article&#038;p=177683"},"modified":"2025-07-13T06:04:39","modified_gmt":"2025-07-13T06:04:39","slug":"compania-que-maneja-el-sistema-de-autoexpreso-no-ha-entregado-protocolo-de-ciberseguridad","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20220514\/compania-que-maneja-el-sistema-de-autoexpreso-no-ha-entregado-protocolo-de-ciberseguridad\/","title":{"rendered":"Compa\u00f1\u00eda que maneja el sistema de AutoExpreso no ha entregado protocolo de ciberseguridad"},"content":{"rendered":"<h3>Ante el ataque cibern\u00e9tico el pasado mes de abril.<\/h3>\n<p>El ataque cibern\u00e9tico al sistema de recarga de AutoExpreso del pasado mes de abril parece ser un problema no resuelto a\u00fan, ya que Puerto Rico Innovation &amp; Technology Services (PRITS) asegur\u00f3 en una vista p\u00fablica ante la Comisi\u00f3n de Transportaci\u00f3n de la C\u00e1mara de Representantes, que Professional Account Management (PAM), encargada de manejar el sistema, no ha entregado un protocolo de ciberseguridad.<\/p>\n<p>\u201cLos <em id=\"emphasis-8ef80e918459cf8fffd2b8bc4d2ca256\">hackers<\/em> al entrar al sistema tienen acceso a la informaci\u00f3n. La investigaci\u00f3n la est\u00e1 realizando la compa\u00f1\u00eda de ciberseguridad que contrata el contratista privado PAM\u201d, explic\u00f3 el principal oficial de Seguridad Cibern\u00e9tica (CISO), N\u2019gai Oliveras Arroyo de PRITS.<\/p>\n<p>Asimismo, detall\u00f3 que en la investigaci\u00f3n preliminar la compa\u00f1\u00eda que contrat\u00f3 PAM asegur\u00f3 que \u201cla informaci\u00f3n no fue trastocada y extra\u00edda\u201d. Adem\u00e1s, aclar\u00f3 que el sistema volver\u00e1 a comenzar con un <em id=\"emphasis-63a6283e864ad8a7fec78979b807d795\">backup<\/em> (informaci\u00f3n recopilada hasta el d\u00eda que sucedi\u00f3 el ataque).<\/p>\n<p>En cuanto al tema de ciberseguridad, la directora ejecutiva de PRITS, Nannette Mart\u00ednez Ortiz asegur\u00f3 que han estado trabajado en una pol\u00edtica p\u00fablica desde principios de a\u00f1o para exigir que todo contratista tenga un protocolo de manejo de incidentes y planes de continuidad de servicio que consideren la implementaci\u00f3n de todos los controles y medidas necesarias para asegurar la integridad, disponibilidad y confidencialidad de los datos que reciben y almacenan los sistemas del Gobierno de Puerto Rico.<\/p>\n<p>\u201cSe supone que PAM le entregue el protocolo al personal de tecnolog\u00eda de la Autoridad de Carretera y Transportaci\u00f3n (ACT)\u201d, dijo Mart\u00ednez Ortiz, quien  a su vez, se\u00f1al\u00f3 que PAM no se ha puesto en cumplimiento con la pol\u00edtica p\u00fablica de PRITS.<\/p>\n<p>De igual manera, el director ejecutivo de la Autoridad de Carreteras y Transportaci\u00f3n (ACT), Edwin Gonz\u00e1lez Montalvo, dijo que no han recibido ning\u00fan protocolo por parte de PAM.<\/p>\n<p>\u201cDe este incidente, se est\u00e1n revisando todos los protocolos dentro de la ACT e indicamos que la compa\u00f1\u00eda PAM nos dijo que el <em id=\"emphasis-aff70b08edd69cd5e0bf04e81ac6127e\">backup<\/em> se hace a diario\u201d, coment\u00f3 el ingeniero.<\/p>\n<p>Gonz\u00e1lez Montalvo indic\u00f3 que el sistema del operador privado que maneja AutoExpreso s\u00ed ha logrado restablecer el sistema, y se encuentra actualmente realizando pruebas al mismo y procesando las transacciones recolectadas por los sistemas de las plazas de peaje desde el comienzo del incidente.<\/p>\n<p><strong id=\"strong-5c581bfe77551f4ebe9c07890744f0cd\">Informaci\u00f3n de los consumidores de AutoExpreso<\/strong><\/p>\n<p>En cuanto a si la informaci\u00f3n de los consumidores ha sido afectadas o comprometidas, el ingeniero se\u00f1al\u00f3 que hay que esperar que la investigaci\u00f3n termine.<\/p>\n<p>\u201cSeg\u00fan lo que nos ha indicado PAM, no hay evidencia alguna. Hay que responsablemente esperar que termine la investigaci\u00f3n\u201d, expres\u00f3 el ingeniero.<\/p><div class=\"notic-content-middle\" id=\"notic-805302736\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>De igual manera indic\u00f3 que la ACT le ha dado prioridad a robustecer el sistema de AutoExpreso. El ingeniero anunci\u00f3 que la ACT lanz\u00f3 un Request for Proposal (RFP) para la modernizaci\u00f3n del sistema de Roadside System para estos fines.<\/p>\n<p>\u201cAl momento la ACT se encuentra evaluando las propuestas recibidas y espera adjudicar la subasta durante verano de 2022. Adem\u00e1s, hay que aclarar que PAM entr\u00f3 en el 2018 y su contrato es mes a mes\u201d, dijo el director ejecutivo de la ACT.<\/p>\n<p>\u201cHay mucho espacio para mejorar y lo que buscamos es el mejor beneficio y valor para el pueblo de Puerto Rico. La compa\u00f1\u00eda que provea el mejor valor para el pueblo puertorrique\u00f1o ser\u00e1 la que gane el proceso\u201d, sostuvo Gonz\u00e1lez Montalvo.<\/p>\n<p>Por su parte, el presidente de PAM, Tim Wendler, garantiz\u00f3 que el <em id=\"emphasis-13a44c09da9035793bbddb42a17e9a6e\">backup<\/em> del sistema se hace a diario.<\/p>\n<p>\u201cActualmente, no tenemos evidencia de que ninguna informaci\u00f3n de los usuarios fue filtrada\u201d, asegur\u00f3.<\/p>\n<p>Esta conversaci\u00f3n se dio en la Vista P\u00fablica de la  Comisi\u00f3n de Transportaci\u00f3n, Infraestructura y Obras P\u00fablicas que preside el representante Jos\u00e9 A. D\u00edaz Collazo, sobre la Resoluci\u00f3n Conjunta de la C\u00e1mara 318.<\/p>\n<p>La R.C. de la C. 18 busca ordenar al Departamento de Transportaci\u00f3n y Obras P\u00fablicas (DTOP) eliminar toda multa y costo del peaje por concepto del transitar sin balance por las estaciones de peaje de la Isla otorgadas a partir del mes de abril del a\u00f1o 2022, debido al ataque cibern\u00e9tico que ha sufrido el sistema de AutoExpreso y hasta su culminaci\u00f3n; que anuncien y establezcan cual ser\u00e1 el protocolo y los pr\u00f3ximos pasos a seguir para que los ciudadanos puedan hacer las reclamaciones por cobros indebidos en sus cuentas; adjudicar un cr\u00e9dito a las cuentas de las personas que pagaron dichas multas; investigar si la base de datos del sistema sufri\u00f3 percances en la informaci\u00f3n confidencial del conductor.<\/p>\n<p><strong id=\"strong-82398db86ecc9211ef83abd2b8256acb\">Lea tambi\u00e9n:<\/strong><\/p>\n<p><a href=\"https:\/\/noticel.com\/en\/la-calle\/20220419\/sistema-de-autoexpreso-sufre-ataque-cibernetico\/\" id=\"link-3469ab1a478af8ce0a3ed160a34e0a72\">Sistema de AutoExpreso y la UPR sufren ataque cibern\u00e9tico<\/a><\/p>\n<p><a href=\"https:\/\/noticel.com\/en\/ahora\/20220505\/aseguran-sistema-autoexpreso-se-ha-podido-reconfigurar-a-base-de-back-ups\/\" id=\"link-984c21893e63c1c0b67b96f60a0dcd7f\">Aseguran sistema AutoExpreso se ha podido reconfigurar a base de \u201cback up\u2019s\u201d<\/a><\/p>\n<p><a href=\"https:\/\/noticel.com\/en\/legislatura\/ahora\/top-stories\/gobierno\/20220427\/camara-aprueba-eliminar-multas-de-autoexpreso-expedidas-desde-1-de-julio-2021\/\" id=\"link-1bc3fceb9f1f0ae37350e2ee4b3c3fe5\">C\u00e1mara aprueba eliminar multas de AutoExpreso expedidas desde 1 de julio 2021<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Ante el ataque cibern\u00e9tico el pasado mes de abril. El ataque cibern\u00e9tico al sistema de recarga de AutoExpreso del pasado mes de abril parece ser un problema no resuelto a\u00fan, ya que Puerto Rico Innovation &amp; Technology Services (PRITS) asegur\u00f3 en una vista p\u00fablica ante la Comisi\u00f3n de Transportaci\u00f3n de la C\u00e1mara de Representantes, que [&hellip;]<\/p>","protected":false},"author":0,"featured_media":293518,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[5,2],"tags":[],"class_list":["post-177683","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-legislatura","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/177683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=177683"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/177683\/revisions"}],"predecessor-version":[{"id":293519,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/177683\/revisions\/293519"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/293518"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=177683"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=177683"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=177683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}