{"id":17691,"date":"2017-10-09T00:00:00","date_gmt":"2017-10-09T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/el-tiempo\/huracanes\/la-calle\/transito\/20171009\/cae-otro-poste-y-deja-carretera-intransitable\/"},"modified":"2025-07-16T18:39:04","modified_gmt":"2025-07-16T18:39:04","slug":"cae-otro-poste-y-deja-carretera-intransitable","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/la-calle\/20171009\/cae-otro-poste-y-deja-carretera-intransitable\/","title":{"rendered":"Cae otro poste y deja carretera intransitable"},"content":{"rendered":"<p><i>El tramo es en Bayam\u00f3n.<\/i><\/p>\n<p>Un poste y tendido electrico cayeron en la carretera 174 en Bayam\u00f3n dejando esta v\u00eda complementamente obstruida e intransitable, seg\u00fan inform\u00f3 la Polic\u00eda de Puerto Rico.<\/p><div class=\"notic-content-middle\" id=\"notic-555450021\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-728&#215;90\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1.jpg 728w, https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1-300x37.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1-18x2.jpg 18w\" sizes=\"(max-width: 728px) 100vw, 728px\" width=\"728\" height=\"90\"   \/><\/a><\/div>\n<p>Como parte de esta ca\u00edda, un veh\u00edculo result\u00f3 con da\u00f1os menores, no obstante ninguna persona result\u00f3 herida.<\/p>\n<p>Al momento, la Uniformada recomend\u00f3 a la ciudadan\u00eda tomar v\u00edas alternas como los son la carretera #167, la carretera #5 y la carretera #2.<\/p>","protected":false},"excerpt":{"rendered":"<p>El tramo es en Bayam\u00f3n. Un poste y tendido electrico cayeron en la carretera 174 en Bayam\u00f3n dejando esta v\u00eda complementamente obstruida e intransitable, seg\u00fan inform\u00f3 la Polic\u00eda de Puerto Rico. Como parte de esta ca\u00edda, un veh\u00edculo result\u00f3 con da\u00f1os menores, no obstante ninguna persona result\u00f3 herida. Al momento, la Uniformada recomend\u00f3 a la [&hellip;]<\/p>","protected":false},"author":0,"featured_media":467864,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[18,19,12],"tags":[],"class_list":["post-17691","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-el-tiempo","category-huracanes","category-la-calle"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/17691","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=17691"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/17691\/revisions"}],"predecessor-version":[{"id":467867,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/17691\/revisions\/467867"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/467864"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=17691"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=17691"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=17691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}