{"id":176156,"date":"2022-04-07T05:45:00","date_gmt":"2022-04-07T09:45:00","guid":{"rendered":"https:\/\/www.noticel.com\/?post_type=article&#038;p=176156"},"modified":"2025-07-13T08:21:28","modified_gmt":"2025-07-13T08:21:28","slug":"sin-nuevos-hallazgos-la-vista-ocular-de-la-camara-en-bahia-jobos","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20220407\/sin-nuevos-hallazgos-la-vista-ocular-de-la-camara-en-bahia-jobos\/","title":{"rendered":"Sin nuevos hallazgos la vista ocular de la C\u00e1mara en Bah\u00eda Jobos"},"content":{"rendered":"<h3>Muchas preguntas, pocas respuestas, e incluso insultos, fue el saldo del recorrido de una veintena de representantes.<\/h3>\n<p>Una veintena de representantes llegaron ayer hasta Salinas para celebrar una vista ocular de la Comisi\u00f3n de la C\u00e1mara de Representantes y auscultar lo que se ha denominando como un \u00bbcrimen ambiental\u00bb en la reserva natural Bah\u00eda Jobos.<\/p>\n<p>Sin embargo, no fueron muchos los hallazgos que all\u00ed se extrajeron.<\/p>\n<p>LUMA Energy hab\u00eda confirmado hace semanas que no hab\u00edan cortado la electricidad a las propiedades con conexiones irregulares. Tambi\u00e9n se conoc\u00eda que muchos de los hu\u00e9spedes de los \u00abcampers\u00bb tienen documentaci\u00f3n ilegal y tal como adelant\u00f3 <a href=\"https:\/\/noticel.com\/en\/top-stories\/gobierno\/20220406\/los-20-propietarios-en-salinas-que-drna-tiene-en-la-mira\/\" id=\"link-53fd715c800605c605d30f4073c49f65\">este diario digital<\/a>, el Departamento de Recursos Naturales ten\u00eda en la mira 20 propietarios que estaban en incumplimiento con los reglamentos de construcci\u00f3n, permisos y planificaci\u00f3n.<\/p>\n<p>A a pesar de que surgieron muchas preguntas en el tramo, la mayor\u00eda se quedaron sin respuestas, o al menos, se espera que sean contestadas en la vista p\u00fablica de la Comisi\u00f3n de Recursos Naturales, pautada para el lunes 18 de abril.<\/p>\n<p>En cambio, fuertes intercambios de palabras entre el presidente de la C\u00e1mara de Representantes, Rafael \u00bb&#8217;Tatito\u00bb Hern\u00e1ndez Monta\u00f1ez, el representante Luis \u00bbNarmito\u00bb Ortiz Lugo y el ambientalista Eliezer Molina, acapararon la atenci\u00f3n de los presentes.<\/p>\n<p>Hasta all\u00ed lleg\u00f3 tambi\u00e9n la secretaria interina del Departamento de Recursos Naturales y Ambientales (DRNA), Ana\u00eds Rodr\u00edguez Vega  junto a vigilantes de la agencia, representantes de LUMA Energy, de la Autoridad de Acueductos de Alcantarillado (AAA), la Oficina de Gerencia y Permisos (OGPe) y la alcaldesa del municipio Karilyn Bonilla.<\/p>\n<p>Muchas preguntas fueron dirigidas a DRNA, y a OGPe,  pero muy pocas a la alcaldesa. Seg\u00fan public\u00f3<a href=\"https:\/\/noticel.com\/en\/ahora\/top-stories\/20220405\/desde-el-2014-municipio-de-salinas-endoso-permiso-de-electricidad-para-un-camper-en-zona-protegida\/\" id=\"link-ce4c86f39eb8c9895e461f267d931a80\"> NotiCel<\/a><strong id=\"strong-d1fe918ae1f024ccdcda0cb66dc91a15\">, <\/strong>el municipio ha cedido permisos para instalar servicios el\u00e9ctricos en \u00abcampers\u00bb en la Bah\u00eda Jobos desde el 2014.<\/p>\n<p><iframe loading=\"lazy\" title=\"C\u00e1mara realiza vista ocular en Salinas para constatar da\u00f1os a Reserva Natural\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/AarbqFc8euM?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>En cuanto a la informaci\u00f3n brindada por OGPe, confirm\u00f3 que hay permisos falsificados que ellos no otorgaron, ya que desde el 2017 la tarea se le deleg\u00f3 al Consorcio CCVS (Cayey, Coamo, Villalba y Salinas).<\/p>\n<p>\u201cNosotros hicimos una certificaci\u00f3n de que esos documentos fueron falsificados, y aunque aparece un permiso, este fue falsificado\u201d, asegur\u00f3 el secretario auxiliar de OGPe, Gabriel Hern\u00e1ndez.<\/p>\n<p>Mientras, el presidente de la C\u00e1mara de Representantes describi\u00f3 los trabajos de la vista ocular como positivos, por entender que los legisladores all\u00ed presentes llegar\u00e1n a la vista p\u00fablica de la comisi\u00f3n con preguntas m\u00e1s dirigidas.<\/p>\n<p>\u201cTitular o no titular, aqu\u00ed se ha dado un crimen ambiental, de eso no hay duda. Ahora podemos hacer preguntas mas claras para tomar acciones contundentes\u201d, manifest\u00f3 el l\u00edder cameral.<\/p>\n<p>Hern\u00e1ndez Monta\u00f1ez coment\u00f3 que en la vista qued\u00f3 demostrado que hay \u00abdejadez\u00bb en el proceso de las querellas, que se le puede atribuir a la falta de recursos del DRNA.<\/p>\n<p>\u201cNo hay duda de que hay dejadez en el proceso. Hay un volumen gigante de radicaci\u00f3n de querellas de ciudadanos y los propios oficiales, pero parte del problema que podemos tener es la dejadez de los recursos, particularmente en el Departamento Legal (de DRNA)\u00bb, sostuvo el presidente de la C\u00e1mara.<\/p>\n<p><strong id=\"strong-f33a370c0b323db9404203892edbf940\">Momento tenso<\/strong><\/p>\n<p>En medio de los trabajos de la vista ocular, el activista ambiental, Eliezer Molina, cuestion\u00f3 la pericia de los representantes para delimitar qu\u00e9 es una Reserva Natural y critic\u00f3 que no citaran a la vista a un agrimensor, perito en la materia, que realiz\u00f3 en el 2016 un estudio de t\u00edtulos del lugar.<\/p>\n<p><iframe loading=\"lazy\" title=\"Aguantan a &#039;Tatito&#039; Hern\u00e1ndez para evitar trifulca con Eliezer Molina\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/gGK30OUgU0U?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>\u201cNinguno de ustedes tiene la pericia para delimitar qu\u00e9 punto es o no es de una reserva federal\u00bb, cuestion\u00f3 Molina, quien le reclam\u00f3 al presidente cameral que la celebraci\u00f3n de la vista ocular respond\u00eda a la presi\u00f3n que hab\u00eda hecho \u00e9l y otros ambientalistas denunciando las irregularidades en el lugar.<\/p><div class=\"notic-content-middle\" id=\"notic-4237302741\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>\u00bbEst\u00e1s aqu\u00ed por m\u00ed, porque usted es un cobarde\u201d, manifest\u00f3 Molina.<\/p>\n<p>Ante estas expresiones, el presidente cameral solicit\u00f3 que detuvieran moment\u00e1neamente el recorrido y le grit\u00f3 a Molina \u00abcharlat\u00e1n\u00bb. Varias representantes tuvieron que aguantarlo para evitar un encontronazo mayor.<\/p>\n<p>Asimismo, el tambi\u00e9n excandidato a la gobernaci\u00f3n pregunt\u00f3 por el representante Luis \u00abNarmito\u00bb Ortiz Lugo y le cuestion\u00f3 si \u00e9l era \u00bbresponsable por lo que tiene que ver Acueductos aqu\u00ed\u00bb, en referencia a las autorizaciones que se concedieron para conexiones de agua algunas de las instalaciones en el lugar.<\/p>\n<p>Durante el intercambio de palabras, Ortiz Lugo mand\u00f3 a Molina \u00abpa&#8217;l cara&#8230;\u00bb.<\/p>\n<p>\u201cTe puedes ir pal cara.. t\u00fa\u201d, le replic\u00f3 Molina a Ortiz Lugo.<\/p>\n<p><strong id=\"strong-24e33d1c481d3c0603d8dfa4c6a2da93\">Querella federal<\/strong><\/p>\n<p>Al enfriarse la situaci\u00f3n, la vista ocular continu\u00f3 y el l\u00edder cameral adelant\u00f3 que se tomar\u00e1 acci\u00f3n federal contra los responsables de este crimen ambiental.<\/p>\n<p>\u201cVamos a radicar querella a nivel federal tan pronto culmine el proceso. Toda persona que ha cometido una ilegalidad ser\u00e1 referida\u201d, advirti\u00f3 Hern\u00e1ndez Monta\u00f1ez.<\/p>\n<p>Hern\u00e1ndez Monta\u00f1ez revel\u00f3 que para las vistas p\u00fablicas de la Comisi\u00f3n de Recursos Naturales tambi\u00e9n estar\u00e1n citados los exsecretarios del DRNA, Rafael Machargo y Tania V\u00e1zquez.<\/p>\n<p>\u201cVamos a tener que referir al propio departamento por incumplimiento, \u00bfqui\u00e9n en el departamento? Eso lo veremos. Qui\u00e9nes son los nombres, qui\u00e9nes son las personas, que, aunque hayan renunciado a sus cargos no los exime de sus actos criminales\u201d, declar\u00f3 el presidente cameral.<\/p>\n<p>La primera vista p\u00fablica de la Comisi\u00f3n de Recursos Naturales para atender este asunto estaba pautada para este lunes 4 de abril, pero, debido a que la secretaria interina del DRNA llevaba apenas d\u00edas en su puesto, la pospusieron para el 18 de abril.<\/p>\n<p>Para la Vista Ocular fueron invitados todos los representantes, pero solo llegaron alrededor de 20 legisladores. El portavoz del Partido Nuevo Progresista (PNP), Carlos &#8216;Johnny&#8217; M\u00e9ndez, fue uno de los ausentes.<\/p>\n<p><strong id=\"strong-71a7f13ffb4bf98f3ad6c4793933630c\">Lea tambi\u00e9n:<\/strong><\/p>\n<p><a href=\"https:\/\/noticel.com\/en\/legislatura\/ahora\/top-stories\/20220406\/documentacion-ilegal-incumplimiento-a-leyes-crimen-ambiental-y-mas-en-la-bahia-jobos-de-salinas\/\" id=\"link-e708246aa9b490555ea0637f73fd5332\">Documentaci\u00f3n ilegal, incumplimiento a leyes, crimen ambiental y m\u00e1s en la Bah\u00eda Jobos de Salinas<\/a><\/p>\n<p><a href=\"https:\/\/noticel.com\/en\/ahora\/top-stories\/20220406\/vigilante-de-recursos-naturales-intenta-suicidarse-en-oficina-del-barrio-playa-de-salinas\/\" id=\"link-748361fbfce7eec438647279f969d923\">Vigilante de Recursos Naturales intenta suicidarse en oficina del Barrio Playa de Salinas<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Muchas preguntas, pocas respuestas, e incluso insultos, fue el saldo del recorrido de una veintena de representantes. Una veintena de representantes llegaron ayer hasta Salinas para celebrar una vista ocular de la Comisi\u00f3n de la C\u00e1mara de Representantes y auscultar lo que se ha denominando como un \u00bbcrimen ambiental\u00bb en la reserva natural Bah\u00eda Jobos. [&hellip;]<\/p>","protected":false},"author":0,"featured_media":296781,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[5,2],"tags":[],"class_list":["post-176156","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-legislatura","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/176156","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=176156"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/176156\/revisions"}],"predecessor-version":[{"id":296782,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/176156\/revisions\/296782"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/296781"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=176156"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=176156"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=176156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}