{"id":176089,"date":"2022-04-05T16:57:57","date_gmt":"2022-04-05T20:57:57","guid":{"rendered":"https:\/\/www.noticel.com\/ahora\/top-stories\/20220405\/alcaldesa-de-salinas-insiste-no-tiene-que-ver-con-construcciones-en-bahia-jobos\/"},"modified":"2025-07-13T08:28:09","modified_gmt":"2025-07-13T08:28:09","slug":"alcaldesa-de-salinas-insiste-no-tiene-que-ver-con-construcciones-en-bahia-jobos","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20220405\/alcaldesa-de-salinas-insiste-no-tiene-que-ver-con-construcciones-en-bahia-jobos\/","title":{"rendered":"Alcaldesa de Salinas insiste no tiene que ver con construcciones en Bah\u00eda Jobos"},"content":{"rendered":"<h3>A pesar de la existencia de una carta en la que el municipio endosa la instalaci\u00f3n de energ\u00eda el\u00e9ctrica en uno de los \u00bbcampers\u00bb.<\/h3>\n<p>Aunque existe una carta que evidencia que desde el 2014 el municipio de Salinas conoc\u00eda sobre solicitudes de instalaci\u00f3n de energ\u00eda el\u00e9ctrica en la zona de la Bah\u00eda Jobos, la alcaldesa de Salinas, Karilyn Bonilla Col\u00f3n, asegur\u00f3 que la misiva no consist\u00eda en una autorizaci\u00f3n final para la construcci\u00f3n.<\/p>\n<p>En declaraciones escritas, la primera ejecutiva municipal tampoco confirm\u00f3 si el \u00e1rea en discusi\u00f3n forma parte de la reserva natural y acus\u00f3 una vez m\u00e1s al Departamento de Recursos Naturales y Ambientales (DRNA) de permitir dichas construcciones a pesar de ser el custodio de esos terrenos.<\/p>\n<p>Seg\u00fan la carta, a la que NotiCel tuvo acceso, la secretaria municipal para esa fecha, Mignelia Reyes Santiago, expres\u00f3 por escrito no tener objeci\u00f3n con que se le instalara servicio de energ\u00eda el\u00e9ctrica a uno de los \u00abcampers\u00bb.<\/p>\n<p>\u00abEl Municipio de Salinas no tiene objeci\u00f3n alguna en que el Sr. \u00c1ngel Cruz Hern\u00e1ndez obtenga los permisos pertinentes para la instalaci\u00f3n del Servicio de Energ\u00eda El\u00e9ctrica, en un camper, el mismo se encuentra ubicado en la Finca La Cuarta, \u00e1rea denominada Los Indios en la Comunidad Las Mareas en Salinas\u00bb, dice la misiva.<\/p>\n<p><strong id=\"strong-6ccb20be7db82f3645befd15b35259d6\">Nota relacionada: <\/strong><a href=\"https:\/\/noticel.com\/en\/ahora\/top-stories\/20220405\/desde-el-2014-municipio-de-salinas-endoso-permiso-de-electricidad-para-un-camper-en-zona-protegida\/\" id=\"link-6e4686d3ad8f17af338c3a3287423a29\">Desde el 2014 municipio de Salinas endos\u00f3 permiso de electricidad para un camper en zona protegida<\/a><\/p>\n<p>En declaraciones escritas, la ejecutiva municipal dijo que, como parte de sus funciones, la Oficina de Secretar\u00eda Municipal de Salinas emite cartas, a solicitud de los ciudadanos, en las que expresa que el municipio no tiene objeci\u00f3n a que se conecten los servicios b\u00e1sicos.<\/p>\n<p>\u201cSin embargo, es importante aclarar que dicha carta no significa que el municipio endosa de ninguna manera que se violente la ley y los reglamentos, sino que el mismo est\u00e1 condicionado a que se cumpla con los requerimientos de las agencias pertinentes y con todos los requisitos de ley y m\u00e1s a\u00fan que de no cumplirse con ello, el mismo queda sin efecto.\u201d, dijo la alcaldesa en un comunicado de prensa.<\/p><div class=\"notic-content-middle\" id=\"notic-3456654196\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-970&#215;90\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1.jpg 970w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-300x28.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-768x71.jpg 768w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-18x2.jpg 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"90\"   \/><\/a><\/div>\n<p><iframe loading=\"lazy\" title=\"Fr\u00e1gil ecosistema en peligro: la controversia ambiental en Salinas\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/kcQ37oZgOj4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>Bonilla Col\u00f3n, quien ocupa la poltrona municipal desde el 2013, dijo que, en este caso en particular, el permiso finalmente no fue otorgado por la Oficina de Gerencia de Permisos (OGPE), al tiempo que volvi\u00f3 responsabilizar al DRNA por permitir que se siguiera construyendo.<\/p>\n<p>\u201cLo importante en este caso es que, a pesar de no tener permiso, seg\u00fan el propio informe sometido por el Departamento de Justicia, el Cuerpo de Vigilantes del Departamento de Recursos Naturales y Ambientales (DRNA) intervino en dicho caso en el 2015 por violaciones ambientales, (pero) permitieron la instalaci\u00f3n de un camper, donde se construy\u00f3 pozo s\u00e9ptico y una verja\u201d, sostuvo la alcaldesa.<\/p>\n<p>La primera ejecutiva de Salinas agreg\u00f3 que este caso es \u201cotro ejemplo de la falta de diligencia del DRNA, ya que teniendo conocimiento de las violaciones desde el verano del 2015 y el DRNA, encargado de la Reserva Estuarina y de Investigaci\u00f3n Bah\u00eda Jobos en Las Mareas, permiti\u00f3 que el predio se desarrollara\u201d.<\/p>\n<p>\u201cCon la informaci\u00f3n que tenemos disponible en el municipio en estos momentos, no podemos indicar si el predio ubica o no en la reserva, ya que la demarcaci\u00f3n siempre ha sido responsabilidad del DRNA\u201d, concluy\u00f3.<\/p>\n<p>Se espera que ma\u00f1ana, mi\u00e9rcoles, la C\u00e1mara de Representantes celebre una vista ocular en Comisi\u00f3n Total en la Bah\u00eda de Salinas en la cual est\u00e1n citados todos los representantes al igual que DRNA, LUMA, AAA y la alcaldesa de Salinas.<\/p>\n<p>Vea la carta aqu\u00ed:<\/p>","protected":false},"excerpt":{"rendered":"<p>A pesar de la existencia de una carta en la que el municipio endosa la instalaci\u00f3n de energ\u00eda el\u00e9ctrica en uno de los \u00bbcampers\u00bb. Aunque existe una carta que evidencia que desde el 2014 el municipio de Salinas conoc\u00eda sobre solicitudes de instalaci\u00f3n de energ\u00eda el\u00e9ctrica en la zona de la Bah\u00eda Jobos, la alcaldesa [&hellip;]<\/p>","protected":false},"author":0,"featured_media":296925,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-176089","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/176089","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=176089"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/176089\/revisions"}],"predecessor-version":[{"id":296926,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/176089\/revisions\/296926"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/296925"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=176089"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=176089"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=176089"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}