{"id":172911,"date":"2022-01-19T14:12:15","date_gmt":"2022-01-19T18:12:15","guid":{"rendered":"https:\/\/www.noticel.com\/estados-unidos\/mundo\/20220119\/universidad-de-michigan-acepta-pagar-490-millones-a-victimas-de-abusos-sexuales\/"},"modified":"2025-07-14T08:10:05","modified_gmt":"2025-07-14T08:10:05","slug":"universidad-de-michigan-acepta-pagar-490-millones-a-victimas-de-abusos-sexuales","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/estados-unidos\/20220119\/universidad-de-michigan-acepta-pagar-490-millones-a-victimas-de-abusos-sexuales\/","title":{"rendered":"Universidad de Michigan acepta pagar $490 millones a v\u00edctimas de abusos sexuales"},"content":{"rendered":"<h3>Unas 1,050 personas acusaron al fallecido m\u00e9dico deportivo Robert Anderson de haber abusado de ellas durante ex\u00e1menes f\u00edsicos.<\/h3>\n<p>La Universidad de Michigan acept\u00f3 pagar $490 millones a unas 1,000 v\u00edctimas de abusos sexuales por parte de un m\u00e9dico deportivo contratado por este centro, que falleci\u00f3 en 2008, en el marco de un acuerdo judicial anunciado este mi\u00e9rcoles.<\/p>\n<p>Uno de los abogados de las v\u00edctimas, Jamie White, citado por medios de comunicaci\u00f3n locales, explic\u00f3 que el acuerdo fue alcanzado el martes por la noche, tras 15 meses de mediaci\u00f3n entre ambas partes.<\/p>\n<p>El pacto debe ahora ser aprobado por un juez, los propios denunciantes y la junta directiva de la universidad.<\/p>\n<p>Con este arreglo se resuelven las denuncias y pleitos interpuestos por unas 1,050 personas, que han acusado al fallecido m\u00e9dico Robert Anderson de haber abusado de ellas durante ex\u00e1menes f\u00edsicos.<\/p>\n<p>Anderson trabaj\u00f3 para la universidad entre 1966 y 2003, pero las revelaciones sobre su conducta no se hicieron p\u00fablicas hasta 2020.<\/p><div class=\"notic-content-middle\" id=\"notic-3738518899\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>Durante a\u00f1os, las v\u00edctimas se quejaron del comportamiento del m\u00e9dico a sus entrenadores y responsables de la universidad sin que se adoptaran medidas.<\/p>\n<p>Otro de los abogados de los denunciantes, Parker Stinar, indic\u00f3 en un comunicado que \u00abeste acuerdo hist\u00f3rico se ha logrado porque los supervivientes de abusos sexuales rechazaron callarse y exigieron rendici\u00f3n de cuentas por parte de su abusador, Robert Anderson, y de la Universidad de Michigan\u00bb.<\/p>\n<p>Por su parte, el presidente de la junta directiva de ese centro educativo, Jordan Acker, expres\u00f3 en otro comunicado su esperanza de que con este arreglo comience el proceso para que las v\u00edctimas curen sus heridas.<\/p>\n<p>Este es uno de los mayores esc\u00e1ndalos de abusos sexuales en una universidad en EE.UU, tras los ocurridos en la \u00faltima d\u00e9cadas en la Universidad Estatal de Pensilvania, la Universidad del Sur de California o la Universidad Estatal de Ohio.<\/p>","protected":false},"excerpt":{"rendered":"<p>Unas 1,050 personas acusaron al fallecido m\u00e9dico deportivo Robert Anderson de haber abusado de ellas durante ex\u00e1menes f\u00edsicos. La Universidad de Michigan acept\u00f3 pagar $490 millones a unas 1,000 v\u00edctimas de abusos sexuales por parte de un m\u00e9dico deportivo contratado por este centro, que falleci\u00f3 en 2008, en el marco de un acuerdo judicial anunciado [&hellip;]<\/p>","protected":false},"author":0,"featured_media":303971,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[16,17],"tags":[],"class_list":["post-172911","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estados-unidos","category-mundo"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/172911","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=172911"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/172911\/revisions"}],"predecessor-version":[{"id":303972,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/172911\/revisions\/303972"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/303971"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=172911"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=172911"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=172911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}