{"id":172893,"date":"2022-01-19T05:54:00","date_gmt":"2022-01-19T09:54:00","guid":{"rendered":"https:\/\/www.noticel.com\/?post_type=article&#038;p=172893"},"modified":"2025-07-14T08:24:27","modified_gmt":"2025-07-14T08:24:27","slug":"lo-que-sigue-ahora-en-la-quiebra-publica-mas-unica-del-mundo-2","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20220119\/lo-que-sigue-ahora-en-la-quiebra-publica-mas-unica-del-mundo-2\/","title":{"rendered":"Lo que sigue ahora en la quiebra p\u00fablica m\u00e1s \u00fanica del mundo"},"content":{"rendered":"<h3>La Junta de Supervisi\u00f3n Fiscal tiene pendientes unos 60 d\u00edas de actividad intensa, incluyendo volver a la Legislatura, para que el Plan de Ajuste de Deuda comience a ejecutarse.<\/h3>\n<p>Como adelant\u00f3 en un escrito la semana pasada, la jueza de quiebras Laura Taylor Swain confirm\u00f3 ayer el Plan de Ajuste de Deuda (PAD) del gobierno central, lo que pone fin a la fase de negociaci\u00f3n de la quiebra p\u00fablica m\u00e1s grande del mercado de Estados Unidos, pero abre un periodo de cumplimiento y reformas que mantendr\u00e1 a la Junta de Supervisi\u00f3n Fiscal (JSF) activa y en control de las finanzas del gobierno por al menos tres a\u00f1os m\u00e1s.<\/p>\n<p>El presidente de la JSF, David Skeel, y su directora ejecutiva, Natalie Jaresko, se presentaron ayer en \u00e1nimo celebratorio y con las emociones a flor de piel por lo que entienden es el logro m\u00e1s significativo dentro de un proceso de quiebra \u00absin precedente\u00bb y \u00abel m\u00e1s \u00fanico\u00bb del mundo.<\/p>\n<p>La confianza de los miembros del ente fiscal tiene contrapeso en las advertencias que se han lanzado de que el recorte no fue suficiente y que una segunda quiebra se va a materializar tan pronto como en los pr\u00f3ximos cinco a\u00f1os. A esto, Jaresko ripost\u00f3 que los recortes profundos en los recursos disponibles para el gobierno se acaban este a\u00f1o y que el pr\u00f3ximo presupuesto, as\u00ed como el pr\u00f3ximo Plan Fiscal, trae \u00abaumento sustancial en el gasto p\u00fablico\u00bb porque, con el PAD, el pago de deuda se redujo de $3,900 millones anuales a $1,500 millones.<\/p>\n<p>Pero, mientras ese desarrollo todav\u00eda permanece en el campo de lo futuro e incierto, la confirmaci\u00f3n del PAD por parte de la jueza Swain no significa un punto final, sino el disparo de salida para eventos significativos que deben suceder en los pr\u00f3ximos 60 d\u00edas y que significan realmente la puesta en vigor del Plan.<\/p>\n<p>La jueza aprob\u00f3 el Plan haciendo referencia a su \u00abfecha de efectividad\u00bb sin decir cu\u00e1l es exactamente esa fecha porque es la Junta la que toma esa autorizaci\u00f3n y la materializa. En la conferencia ayer, Jaresko plante\u00f3 que la meta del ente es que el PAD entre en vigor el 15 de marzo.<\/p>\n<p>Seg\u00fan explicaron, as\u00ed se ve el futuro inmediato del PAD:<\/p>\n<p>-Para el 27 de enero la JSF debe certificar un nuevo Plan Fiscal que integra las disposiciones finales del PAD. De hecho, una de las cr\u00edticas que la jueza descart\u00f3 para aprobar el PAD es que el Plan Fiscal vigente hoy no es compatible con la propuesto, por lo que la jueza estar\u00eda diciendo, como en efecto dijo, que el PAD es consistente con el Plan Fiscal cuando, en realidad este documento requiere cambios para ajustarlo completamente al PAD aprobado.<\/p>\n<p>-Luego de eso, la JSF tiene que ir al Gobernador y a la Legislatura con enmiendas al presupuesto vigente para hacerlo compatible con el PAD y con el Plan Fiscal, principalmente porque, a la fecha de efectividad, ocurren pagos a los bonistas que hay que integrar al presupuesto. Una vez modificado para incluir el pago a la deuda que no se hace desde que se declar\u00f3 la quiebra hace poco m\u00e1s de cuatro a\u00f1os, el presupuesto se convertir\u00eda en el primero de los cuatro presupuestos balanceados corridos que hay que tener como una de las condiciones para la expiraci\u00f3n de la misi\u00f3n de la JSF, seg\u00fan Skeel.<\/p><div class=\"notic-content-middle\" id=\"notic-2784704722\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>-Despu\u00e9s de la aprobaci\u00f3n del Plan Fiscal y la enmienda al presupuesto, la JSF ha fijado el 15 de marzo como la fecha de efectividad real del PAD. Ese d\u00eda perfila tan potencialmente ca\u00f3tico como hist\u00f3rico ya que deben ocurrir: 1) los intercambios de bonos viejos con los nuevos bajo el Plan, 2) los primeros pagos a bonistas, 3) inicio de la cotizaci\u00f3n de Seguro Social para maestros y jueces, 4) congelamiento en los sistemas de retiro de jueces y maestros, 5) desembolso de $1,200 millones para restablecer los balances en las cuentas bajo el sistema Retiro 2000 a 50,000 empleados y 6) pago de $2,600 a los empleados bajo la Ley 1 de retiro.<\/p>\n<p>-Ya con el PAD corriendo, la Junta planifica embarcarse en la otra reestructuraci\u00f3n sustancial que le queda, la de la Autoridad de Energ\u00eda El\u00e9ctrica (AEE), con la presentaci\u00f3n de un Plan de Ajuste de Deuda para esa corporaci\u00f3n p\u00fablica a fines de marzo. Para esta reestructuraci\u00f3n, la JSF tiene que volver a la Legislatura, como lo hizo para el ajuste del gobierno central. Las otras dos reestructuraciones que restar\u00edan ser\u00edan la de la Autoridad de Carreteras y Transportaci\u00f3n y la de la Universidad de Puerto Rico. Esta \u00faltima, Jaresko la dej\u00f3 enteramente en manos del gobierno. \u00abNo estamos en el asiento del chofer\u00bb para esa reestructuraci\u00f3n, dijo.<\/p>\n<p>La agenda de la Junta para el resto del 2022 es una mezcla de finalizar las reestructuraciones pendientes y moverse a enfocarse completamente en lo que hasta ahora ha sido su tarea menos desarrollada: conseguir que el gobierno inicie y complete \u00abreformas estructurales\u00bb.<\/p>\n<p>Esto va desde \u00abasegurarse que la responsabilidad fiscal est\u00e1 inculcada a lo largo de todo el gobierno\u00bb, seg\u00fan Jaresko, hasta cambios que el gobierno ha resistido hasta ahora como el desarrollo de la Oficina del Principal Oficial Financiero, la reforma en el servicio p\u00fablico para desarrollar a los empleados p\u00fablicos a base del m\u00e9rito en vez de las conexiones pol\u00edticas, flexibilizaci\u00f3n en el \u00e1rea de permisos, transformaci\u00f3n de la red el\u00e9ctrica, uso de fondos de reconstrucci\u00f3n y cambios en el sistema de ayuda de beneficiencia (welfare).<\/p>\n<p>\u00abComo m\u00ednimo, la Junta va a estar por aqu\u00ed por tres a\u00f1os m\u00e1s\u00bb, puntualiz\u00f3 Skeel.<\/p>\n<p>Nota relacionada:<a href=\"https:\/\/noticel.com\/en\/la-junta-de-control-fiscal\/tribunales\/ahora\/top-stories\/20220112\/swain-el-plan-de-ajuste-de-deuda-con-algunas-modificaciones-es-adecuado\/\" id=\"link-bc75e8fed7efbd53c6e18381ee11ff60\" target=\"_blank\"><strong id=\"strong-5cfe8cb903e70c799fe4ea92fb78a626\"> <\/strong>Swain: \u00abEl Plan de Ajuste de Deuda, con algunas modificaciones, es adecuado\u00bb <\/a><\/p>\n<p><strong id=\"strong-1f5ef57c77adbe98a64e131be7c106de\">Vea aqu\u00ed los documentos oficiales:<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>La Junta de Supervisi\u00f3n Fiscal tiene pendientes unos 60 d\u00edas de actividad intensa, incluyendo volver a la Legislatura, para que el Plan de Ajuste de Deuda comience a ejecutarse. Como adelant\u00f3 en un escrito la semana pasada, la jueza de quiebras Laura Taylor Swain confirm\u00f3 ayer el Plan de Ajuste de Deuda (PAD) del gobierno [&hellip;]<\/p>","protected":false},"author":0,"featured_media":304007,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-172893","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/172893","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=172893"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/172893\/revisions"}],"predecessor-version":[{"id":304008,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/172893\/revisions\/304008"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/304007"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=172893"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=172893"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=172893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}