{"id":172838,"date":"2022-01-18T05:45:00","date_gmt":"2022-01-18T09:45:00","guid":{"rendered":"https:\/\/www.noticel.com\/?post_type=article&#038;p=172838"},"modified":"2025-07-15T04:17:12","modified_gmt":"2025-07-15T04:17:12","slug":"hacienda-reporta-alza-en-recaudos-para-noviembre-y-el-presente-ano-fiscal","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20220118\/hacienda-reporta-alza-en-recaudos-para-noviembre-y-el-presente-ano-fiscal\/","title":{"rendered":"Hacienda reporta alza en recaudos para noviembre y el presente a\u00f1o fiscal"},"content":{"rendered":"<h3>Los ingresos durante ese mes en el 2021 alcanzaron $758.1 millones, lo que excede lo recaudado durante el mismo mes del a\u00f1o fiscal 2020.<\/h3>\n<p>Los ingresos al Fondo General mantuvieron su ritmo de recuperaci\u00f3n en noviembre pasado, superando tanto el comparable del mismo mes del a\u00f1o anterior, como el recaudo acumulado durante los primeros cinco meses del pasado a\u00f1o fiscal, inform\u00f3 el Departamento de Hacienda.<\/p>\n<p>Los ingresos durante el mes de noviembre de 2021 alcanzaron $758.1 millones, lo que excede lo recaudado durante el mismo mes del a\u00f1o fiscal 2020, en $102.1\u00a0millones o un 15.6%, y en $88 millones la proyecci\u00f3n.<\/p>\n<p>El recaudo acumulado durante los primeros cinco meses del a\u00f1o fiscal 2022 totaliz\u00f3, por otra parte, $3,274.1 millones, superando por $531.9 millones lo proyectado en el Plan Fiscal certificado por la Junta de Supervisi\u00f3n Fiscal (JSF). El incremento equivale al 19.4%.<\/p>\n<p>\u201cLos ingresos netos al Fondo General durante estos primeros cinco meses reflejan un repunte de la econom\u00eda. Estos superan en $500 millones lo recaudado durante el mismo periodo del a\u00f1o fiscal previo o 14.2%. Estamos experimentando signos de un rebote, cercano a los niveles de recaudos en el a\u00f1o fiscal 2020, antes de la contracci\u00f3n experimentada al inicio de la crisis por la pandemia del COVID-19. Sin embargo, debemos estar alertas ante la aparici\u00f3n de la variante \u00f3micron, y el impacto que pudiera acarrear\u201d, sostuvo el secretario de Hacienda, Francisco Par\u00e9s Alicea, al comentar los resultados.<\/p>\n<p>Todos los renglones de ingresos, con excepci\u00f3n de los recaudos por el arbitrio a las for\u00e1neas, registraron alzas durante los meses transcurridos -hasta noviembre-, del presente a\u00f1o fiscal. El alza mayor se registr\u00f3 en las contribuciones de corporaciones, seguidas de las corporaciones de individuos.<\/p>\n<p>En el primer caso los recaudos totalizaron $744 millones, que fueron $25.2 millones m\u00e1s que durante el mismo periodo del fiscal anterior, pero $177 millones por encima de la proyecci\u00f3n que se hizo.<\/p>\n<p><strong id=\"strong-60855f76e6754708d111fd6c426aef2b\">Lea tambi\u00e9n:<\/strong> <a href=\"https:\/\/noticel.com\/en\/ahora\/gobierno\/top-stories\/20211128\/recaudos-de-hacienda-andan-por-debajo-del-pasado-ano-fiscal\/\" id=\"link-b3aad4709d1a6b2eed3c562cdebb2a44\">Recaudos de Hacienda andan por debajo del pasado a\u00f1o fiscal<\/a><\/p>\n<p>En el caso de las contribuciones de individuos, el ingreso total fue de $813.4 millones, que fueron $33.6 millones menos que el a\u00f1o anterior, pero $141.8 millones sobre la proyecci\u00f3n.<\/p><div class=\"notic-content-middle\" id=\"notic-1328086284\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-970&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1.jpg 970w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-300x77.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-768x198.jpg 768w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-18x5.jpg 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"250\"   \/><\/a><\/div>\n<p>Durante el mes de noviembre las contribuciones de las corporaciones totalizaron $109.6 millones, que fueron $64 millones m\u00e1s que el mismo mes del 2020, y $48 millones por sobre las proyecciones.<\/p>\n<p>Las de individuos alcanzaron $190.1 millones, que son $44.3 millones m\u00e1s que en el 2020, y $53 millones por encima de la proyecci\u00f3n. Sobre el particular el Secretario indic\u00f3 que estos resultados son consistentes con la recuperaci\u00f3n de aproximadamente 45 mil empleos en noviembre de 2021, respecto al 2020.<\/p>\n<p>A estos renglones sigui\u00f3 en magnitud de aumento el Impuesto sobre Ventas y Uso (IVU). Est\u00e9 alcanz\u00f3 en noviembre $190.1 millones, superando los ingresos recibidos en el 2020 por $26.5 millones. Durante el periodo acumulado del a\u00f1o fiscal el ingreso alcanz\u00f3, mientras tanto, $810.6 millones, lo que represent\u00f3 $103.3 millones m\u00e1s que lo que se acumul\u00f3 en el fiscal 2021, equivalente a 14.6%.<\/p>\n<p>Destac\u00f3 el titular de Hacienda que la proyecci\u00f3n anual para el a\u00f1o fiscal 2022 considerada en el Plan Fiscal, fue de una reducci\u00f3n de -4.3%, lo que supon\u00eda una base estimada para el a\u00f1o fiscal de $2,341 millones. Lo recaudado durante ese periodo super\u00f3 en $122 millones la previsi\u00f3n (5.2%)<\/p>\n<p>Atribuy\u00f3 este incremento al rebote de la demanda por consumo de bienes y servicios, despu\u00e9s del punto m\u00e1s cr\u00edtico de la pandemia. \u201cLos servicios de alimentos han experimentado un crecimiento durante el periodo de estos cinco meses, de 43.3%. As\u00ed tambi\u00e9n, el sector de comercio al detal, principal recaudador del IVU, creci\u00f3 a un ritmo de 3% en relaci\u00f3n con el mismo periodo del a\u00f1o fiscal 2021\u201d.<\/p>\n<p>Celebr\u00f3 tambi\u00e9n Par\u00e9s Alicea el incremento en el segmento de ventas en l\u00ednea sujetas al IVU, que retienen los agentes voluntarios y facilitadores de mercado. Durante los primeros cinco meses del a\u00f1o corriente estas ventas representaron el 16.3%, del total de ventas al por menor y totalizaron $75.6\u00a0millones. Ese crecimiento en la participaci\u00f3n de esta modalidad de comercio equivale a 4.6 puntos porcentuales sobre el a\u00f1o anterior.<\/p>\n<p>Respecto al arbitrio a for\u00e1neas (Ley 154-2010), estos totalizaron $55.3 millones en noviembre, lo cual representa una deficiencia de $45.6 millones respecto a la la proyecci\u00f3n. Para el periodo acumulado hasta noviembre los recaudos para totalizaron $577.7 millones, para una reducci\u00f3n de $41.6 millones en comparaci\u00f3n con los recaudos para el mismo periodo en el a\u00f1o fiscal 2021.<\/p>\n<p>\u201cCabe se\u00f1alar\u201d, explic\u00f3 el Secretario en sus declaraciones escritas,  \u201cque una de las principales recaudadoras de este rengl\u00f3n lleg\u00f3 a su tope en julio, ya que existe un m\u00e1ximo anual de $375 millones del impuesto que estas entidades deben pagar. El periodo contributivo para este arbitrio es de enero a diciembre, lo que implica un cambio en la distribuci\u00f3n esperada de recaudos. Esto ya que, a diferencia del a\u00f1o pasado en que la entidad culmin\u00f3 en agosto, se reduce el flujo por ingresos de esta para el periodo de agosto al presente. A partir de febrero se espera se reanuden estos pagos y pueda compensarse esta insuficiencia\u201d.<\/p>","protected":false},"excerpt":{"rendered":"<p>Los ingresos durante ese mes en el 2021 alcanzaron $758.1 millones, lo que excede lo recaudado durante el mismo mes del a\u00f1o fiscal 2020. Los ingresos al Fondo General mantuvieron su ritmo de recuperaci\u00f3n en noviembre pasado, superando tanto el comparable del mismo mes del a\u00f1o anterior, como el recaudo acumulado durante los primeros cinco [&hellip;]<\/p>","protected":false},"author":0,"featured_media":304337,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[22,2],"tags":[],"class_list":["post-172838","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/172838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=172838"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/172838\/revisions"}],"predecessor-version":[{"id":304338,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/172838\/revisions\/304338"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/304337"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=172838"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=172838"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=172838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}