{"id":170973,"date":"2021-11-28T14:01:00","date_gmt":"2021-11-28T18:01:00","guid":{"rendered":"https:\/\/www.noticel.com\/mundo\/20211128\/impresionantes-imagenes-del-poderoso-terremoto-de-magnitud-7-5-en-peru\/"},"modified":"2025-07-15T08:57:52","modified_gmt":"2025-07-15T08:57:52","slug":"impresionantes-imagenes-del-poderoso-terremoto-de-magnitud-7-5-en-peru","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/mundo\/20211128\/impresionantes-imagenes-del-poderoso-terremoto-de-magnitud-7-5-en-peru\/","title":{"rendered":"Impresionantes im\u00e1genes del poderoso terremoto de magnitud 7.5 en Per\u00fa"},"content":{"rendered":"<h3>Al momento no se han reportado muertos, pero s\u00ed heridos y m\u00faltiples da\u00f1os.<\/h3>\n<p>Al menos dos personas resultaron heridas y otras 40 damnificadas en la madrugada de este domingo en Per\u00fa por el terremoto de 7.5 grados en la escala de Richter, que se pudo sentir en gran parte del pa\u00eds y de Sudam\u00e9rica, seg\u00fan inform\u00f3 en el Centro de Operaciones de Emergencia Nacional (COEN).<\/p>\n<p>El terremoto ocurrido a las 5:52 hora local tambi\u00e9n destruy\u00f3 al menos una iglesia y siete viviendas, mientras que otros once inmuebles tambi\u00e9n sufrieron desperfectos.<\/p>\n<p>https:\/\/twitter.com\/the_Lunatic22\/status\/1465014809909465099<\/p>\n<p>Los da\u00f1os se concentran en varios municipios de la regi\u00f3n de Amazonas, en el norte de Per\u00fa, pr\u00f3ximos al epicentro del terremoto, ubicado a 98 kil\u00f3metros al este de la localidad de Santa Mar\u00eda de Nieva, donde el terremoto se sinti\u00f3 con una intensidad muy fuerte.<\/p>\n<p>All\u00ed, medios locales reportan el derrumbe de la iglesia de origen colonial de Jalca Grande, ubicada en el distrito de La Jalca, mientras que en varias provincias de Amazonas como en otras de los vecinos departamentos de Loreto y San Mart\u00edn el suministro el\u00e9ctrico ha quedado cortado.<\/p>\n<p>De igual modo, a trav\u00e9s de las redes sociales se difundieron im\u00e1genes de miembros de una familia que fueron rescatados con vida de una residencia que colaps\u00f3 en un anexo de La Jalca, Chachapoyas.<\/p>\n<p>https:\/\/twitter.com\/claudiacisneros\/status\/1465014897603801090<\/p>\n<p>\u00abToda mi solidaridad con el pueblo de Amazonas ante el fuerte sismo ocurrido. He dispuesto que los ministerios y diferentes instancias del Ejecutivo desplieguen acciones inmediatas\u00bb, manifest\u00f3 en redes sociales el presidente de Per\u00fa, Pedro Castillo.<\/p>\n<p>\u00abNo est\u00e1n solos, hermanos. Apoyaremos a los afectados y actuaremos frente a los da\u00f1os materiales\u00bb, apostill\u00f3 el gobernante peruano.<\/p>\n<p>Desde primera hora de la ma\u00f1ana, la primera ministra, Mirtha V\u00e1squez, se encuentra en las instalaciones del COEN para seguir de cerca la evaluaci\u00f3n de da\u00f1os y la atenci\u00f3n de la emergencia.<\/p>\n<p>Dada la proximidad del epicentro del terremoto con Ecuador, tambi\u00e9n se registraron da\u00f1os en viviendas en los cantones ecuatorianos de Zamora y Loja, con varios inmuebles afectados y una iglesia colapsada.<\/p>\n<p>El terremoto se origin\u00f3 a una gran profundidad terrestre de 131 kil\u00f3metros, lo que redujo su poder de destrucci\u00f3n en la superficie pero amplific\u00f3 el alcance de su onda s\u00edsmica a una amplia \u00e1rea geogr\u00e1fica e hizo que se sintiese en la capital Lima.<\/p>\n<p>Esta circunstancia hizo tambi\u00e9n que la primera alerta del terremoto ofrecida por el Servicio Geol\u00f3gico de Estados Unidos situase inicialmente el epicentro cerca de la localidad costera de Barranca, a unos 1,000 kil\u00f3metros de la ubicaci\u00f3n real del movimiento tel\u00farico.<\/p>\n<p>El Per\u00fa se encuentra ubicado en la zona denominada Cintur\u00f3n de Fuego del Pac\u00edfico, donde se registra aproximadamente el 85% de la actividad s\u00edsmica mundial.<\/p>\n<p>Varios ciudadanos captaron en v\u00eddeos el cismo y los da\u00f1os que provoc\u00f3, im\u00e1genes que r\u00e1pido se propagaron por las redes sociales.<\/p>\n<p>https:\/\/twitter.com\/mondoterremoti\/status\/1465003773647065099<\/p>","protected":false},"excerpt":{"rendered":"<p>Al momento no se han reportado muertos, pero s\u00ed heridos y m\u00faltiples da\u00f1os. Al menos dos personas resultaron heridas y otras 40 damnificadas en la madrugada de este domingo en Per\u00fa por el terremoto de 7.5 grados en la escala de Richter, que se pudo sentir en gran parte del pa\u00eds y de Sudam\u00e9rica, seg\u00fan [&hellip;]<\/p>","protected":false},"author":0,"featured_media":321367,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ep_exclude_from_search":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-170973","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/170973","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=170973"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/170973\/revisions"}],"predecessor-version":[{"id":321372,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/170973\/revisions\/321372"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/321367"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=170973"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=170973"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=170973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}