{"id":170756,"date":"2021-11-23T05:45:00","date_gmt":"2021-11-23T09:45:00","guid":{"rendered":"https:\/\/www.noticel.com\/?post_type=article&#038;p=170756"},"modified":"2025-07-15T09:31:52","modified_gmt":"2025-07-15T09:31:52","slug":"imputado-en-caso-de-pruebas-covid-19-quiere-entregarse-pero-demanda-a-osaj-por-negarle-fianza","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20211123\/imputado-en-caso-de-pruebas-covid-19-quiere-entregarse-pero-demanda-a-osaj-por-negarle-fianza\/","title":{"rendered":"Imputado en caso de pruebas covid-19 quiere entregarse, pero demanda a OSAJ por negarle fianza"},"content":{"rendered":"<h3>Aaron Vick alega ser v\u00edctima de discrimen porque reside fuera de Puerto Rico y recurre al Tribunal Federal para remedios.<\/h3>\n<p>Aaron Vick, involucrado en el esquema de la transacci\u00f3n de $38 millones que la empresa de construcci\u00f3n <em id=\"emphasis-e5f6ef3c9402a63ecb0bf20485ff13d0\">APEX General Contractors<\/em> intent\u00f3 completar con el Gobierno de Puerto Rico para proveer pruebas de detecci\u00f3n r\u00e1pida del covid-19 a principios de la pandemia, demand\u00f3 por discrimen a la Oficina de Servicios con Antelaci\u00f3n a Juicio (OSAJ), a la vez que consign\u00f3 que tramita entregarse a las autoridades.<\/p>\n<p>La relaci\u00f3n de Vick con el licenciado Juan Maldonado de Jes\u00fas, a quien conoc\u00eda desde que prove\u00eda contratos a trav\u00e9s de la empresa <em id=\"emphasis-999089fdd62888f18fd23ef513eed12c\">Fortress Maritime<\/em> cuando el abogado era director ejecutivo de la Autoridad de Transporte Mar\u00edtimo (ATM), se torn\u00f3 en un asunto penal el 4 de noviembre pasado, cuando fiscales de la Oficina del Panel del Fiscal Especial Independiente (OPFEI) presentaron cargos a ambos por la venta de las pruebas. La transacci\u00f3n no se complet\u00f3 cuando el <em id=\"emphasis-8d1ce57090000734d384bf5cfbd47a76\">Oriental Bank<\/em> la detuvo por cumplir con sus alertas internas de seguridad y detecci\u00f3n de fraude.<\/p>\n<p>Maldonado de Jes\u00fas compareci\u00f3 a vista, se encontr\u00f3 causa para su arresto y prest\u00f3 fianza de $250,000 de manera diferida a trav\u00e9s de OSAJ. Por su parte, a Vick le presentaron los cargos en ausencia y le impusieron $200,000 de fianza. La demanda suscrita por los abogados Guillermo Ramos Lui\u00f1a y Leonardo Aldridge plantea que Vick ha estado tramitando entregarse a las autoridades, pero la OSAJ le ha negado el beneficio de la fianza diferida por ser residente del estado de Virginia.<\/p>\n<p>La reclamaci\u00f3n judicial divulga que Vick se mud\u00f3 al \u00e1rea de Virginia Beach con su esposa y estableci\u00f3 un negocio all\u00e1 en diciembre de 2020, despu\u00e9s de que el Departamento de Justicia le notificara que no iba a recomendar la designaci\u00f3n de un fiscal especial independiente en su contra. El documento revela tambi\u00e9n que hubo una investigaci\u00f3n de la transacci\u00f3n por parte de la Oficina del Inspector General del Departamento de Salud federal, con la que el contratista cooper\u00f3 y que supuestamente tambi\u00e9n lo exoner\u00f3.<\/p>\n<p>\u00ab(Vick) cumple con todos los criterios que presenta OSAJ para que su fianza sea diferida, igual que la de Maldonado&#8230; (pero) OSAJ ha tomado la posici\u00f3n de no recomendar que la fianza sea diferida porque entienden que no podr\u00eda supervisarlo adecuadamente durante su libertad previa al juicio solamente basado en que no es un residente de Puerto Rico&#8230; (Vick) no tiene los medios financieros para prestar la fianza de $200,000 que fue impuesta en ausencia y tiene derecho al mismo trato que recibe su coimputado, quien es residente de Puerto Rico\u00bb, argumentaron los abogados en la demanda en la que piden una orden del tribunal concluyendo que se le est\u00e1n violando derechos constitucionales al contratista y prohibiendo que la directora de OSAJ, Janette Rodr\u00edguez, se reh\u00fase a recomendar la fianza diferida bas\u00e1ndose en la residencia fuera de Puerto Rico.<\/p>\n<p>La base legal del reclamo es que los servicios de OSAJ responden a un derecho constitucional que tienen los imputados en Puerto Rico a estar en libertad mientras se procesa su caso, el cual se le est\u00e1 violentando a Vick solo por vivir fuera de Puerto Rico. Excepto por el hecho de que uno vive aqu\u00ed y otro vive afuera, no hay ninguna diferencia en las circunstancias entre Maldonado y Vick, argumentan los representantes legales.<\/p>\n<p>En lo que es un eco de argumentos que ya la abogada de Maldonado, Mayra L\u00f3pez Mulero, present\u00f3 en la vista de causa para arresto sin que esto persuadiera al tribunal, los abogados de Vick comentan en la demanda que \u00abinteresantemente, ning\u00fan oficial del Gobierno de Puerto Rico fue imputado (por la transacci\u00f3n), lo cual levanta numerosas preocupaciones y preguntas sobre la capacidad y jurisdicci\u00f3n (de la OPFEI) para presentar cardos a dos ciudadanos privados y acerca de la propiedad de esos cargos\u00bb.<\/p>\n<p>Las denuncias presentadas a Vick y Maldonado, que NotiCel obtuvo, reflejan que varios de los testigos en el caso son, precisamente, los funcionarios p\u00fablicos que intervinieron en la otorgaci\u00f3n \u00ab<em id=\"emphasis-62ec7f69cb35d4fc71fc311ea0cbdc24\">fast track<\/em>\u00bb del contrato a APEX por unas pruebas que, se revel\u00f3 luego, no iban a poder producir porque contaban con un manufacturero y suplidores que estaban haciendo representaciones falsas sobre su capacidad para entregar las pruebas en la cantidad, calidad y tiempo requerido.<\/p><div class=\"notic-content-middle\" id=\"notic-743229874\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>La participaci\u00f3n de Vick ocurre porque la autoriz\u00f3 a Maldonado a usar su firma digital para colocarla en los documentos que APEX someti\u00f3 al gobierno.<\/p>\n<p>La vista preliminar, que estaba pautada para este pasado lunes, 22 de noviembre, fue pospuesta para el 20 de enero pr\u00f3ximo.<\/p>\n<p>Para ver la demanda, pulse aqu\u00ed.<\/p>\n<p>Vea:<\/p>\n<p><a href=\"https:\/\/noticel.com\/en\/gobierno\/ahora\/top-stories\/20200422\/excontratista-de-atm-autorizo-el-uso-de-su-firma-en-transaccion-del-millon-de-pruebas\/\" id=\"link-0ca9b323a36ddf4191138095874c637a\" target=\"_blank\">Excontratista de ATM autoriz\u00f3 el uso de su firma en transacci\u00f3n del mill\u00f3n de pruebas <\/a><\/p>\n<p><a href=\"https:\/\/noticel.com\/en\/tribunales\/ahora\/top-stories\/20211108\/los-funcionarios-publicos-son-los-testigos-en-el-caso-criminal-por-pruebas-de-covid-19\/\" id=\"link-b8b40acbcd8d74ed0fb1442798b91f4a\" target=\"_blank\">Los funcionarios p\u00fablicos son los testigos en el caso criminal por pruebas de covid-19 <\/a><\/p>\n<p><a href=\"https:\/\/noticel.com\/en\/ahora\/gobierno\/politica\/top-stories\/20200513\/los-vinculos-de-juan-maldonado-en-su-trayectoria-por-el-gobierno\/\" id=\"link-83786f91875436dbb9cbaf359957fd35\" target=\"_blank\">Los v\u00ednculos de Juan Maldonado en su trayectoria por el Gobierno<\/a><\/p>\n<p><a href=\"https:\/\/noticel.com\/en\/ahora\/20211104\/causa-para-arresto-contra-juan-maldonado-y-aaron-vick-en-caso-por-venta-de-pruebas-de-covid-19\/\" id=\"link-d78869e31a6b457540916d1e9c619081\" target=\"_blank\">Causa para arresto contra Juan Maldonado y Aaron Vick en caso por venta de pruebas de Covid-19 <\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Aaron Vick alega ser v\u00edctima de discrimen porque reside fuera de Puerto Rico y recurre al Tribunal Federal para remedios. Aaron Vick, involucrado en el esquema de la transacci\u00f3n de $38 millones que la empresa de construcci\u00f3n APEX General Contractors intent\u00f3 completar con el Gobierno de Puerto Rico para proveer pruebas de detecci\u00f3n r\u00e1pida del [&hellip;]<\/p>","protected":false},"author":0,"featured_media":323571,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[13,2],"tags":[],"class_list":["post-170756","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tribunales","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/170756","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=170756"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/170756\/revisions"}],"predecessor-version":[{"id":323573,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/170756\/revisions\/323573"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/323571"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=170756"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=170756"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=170756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}