{"id":170542,"date":"2021-11-17T12:58:00","date_gmt":"2021-11-17T16:58:00","guid":{"rendered":"https:\/\/www.noticel.com\/ahora\/legislatura\/20211117\/delegacion-del-pip-explica-la-razon-de-su-voto-en-contra-a-la-reforma-laboral\/"},"modified":"2025-07-15T09:57:35","modified_gmt":"2025-07-15T09:57:35","slug":"delegacion-del-pip-explica-la-razon-de-su-voto-en-contra-a-la-reforma-laboral","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20211117\/delegacion-del-pip-explica-la-razon-de-su-voto-en-contra-a-la-reforma-laboral\/","title":{"rendered":"Delegaci\u00f3n del PIP explica la raz\u00f3n de su voto en contra a la Reforma Laboral"},"content":{"rendered":"<h3>La delegaci\u00f3n defendi\u00f3 su postura de votarle en contra a las enmiendas a la Reforma Laboral y dijo que no tuvieron acceso a las enmiendas.<\/h3>\n<p>La delegaci\u00f3n del Partido Independentista Puertorrique\u00f1o (PIP), compuesta por la senadora Mar\u00eda de Lourdes Santiago Negr\u00f3n y el representante Denis Marquez Lebr\u00f3n, explicaron que su voto en contra a las enmiendas a la Reforma Laboral fue por la falta de transparencia y cambios a \u00faltima hora sin consulta previa.<\/p>\n<p>La senadora desminti\u00f3 al presidente del Senado, Jos\u00e9 Luis Dalmau Santiago, al indicar que tuvo acceso al informe de conferencia de la medida 15 minutos antes de llevarse a cabo la votaci\u00f3n, cuando el presidente senatorial dijo que hab\u00edan recibido el documento el viernes.<\/p>\n<p>\u201cLo que dice Jos\u00e9 Luis Dalmau es mentira. Yo no tuve acceso a la medida hasta que se firma el informe de conferencia, y tengo la impresi\u00f3n de que tampoco la ten\u00edan las otras delegaciones\u201d, sostuvo Santiago Negr\u00f3n.<\/p>\n<p>La senadora fue quien present\u00f3 la reconsideraci\u00f3n al Proyecto de la C\u00e1mara 3, luego de que la medida fuera avalada por el Senado. Luego, los senadores Thomas Rivera Schatz y Ana Irma Rivera Lassen se unieron a la petici\u00f3n.<\/p>\n<p>Ante esto, el presidente de la C\u00e1mara de Representantes, Rafael \u00abTatito\u00bb Hern\u00e1ndez moviliz\u00f3 a su delegaci\u00f3n del Partido Popular Democr\u00e1tico (PPD) para que la medida fuera aprobada en la C\u00e1mara Baja.<\/p>\n<p>Asimismo, el l\u00edder cameral tild\u00f3 de \u00abtraidores\u00bb a la delegaci\u00f3n del PIP por darle la espalda a la medida.<\/p>\n<p>\u201cNo soy una chapucera y no soy una irresponsable. Contrario a ellos, creemos que uno debe leer los proyectos. El hemiciclo no puede ser un matadero donde llegan los corderos a sus sacrificios\u201d, manifest\u00f3 la senadora. \u201cCreo que es importante que el pa\u00eds sepa que as\u00ed es como legisla la mayor\u00eda del PPD. Ah\u00ed no hay conciencia, no hay responsabilidad, donde le dicen que vayan ah\u00ed van\u00bb, abund\u00f3.<\/p>\n<p>De igual manera, el representante Marquez Lebr\u00f3n destac\u00f3 que ser\u00eda irresponsable de su parte votar a favor a un proyecto donde se le a\u00f1adieron sobre 20 p\u00e1ginas.<\/p>\n<p>\u201cEstamos rechazando la forma y manera en que se realiz\u00f3 esto. A nosotros nadie en la legislatura nos puede cuestionar a nosotros nuestro compromiso con la clase trabajadora. Tenemos un compromiso no solo en la legislatura pero en la calle tambi\u00e9n\u00bb, expres\u00f3 Marquez Lebr\u00f3n.<\/p>\n<p>\u201cHay cosas positivas en ese proyecto que respaldamos, pero hay asuntos que tienen que ver con la clase trabajadora que no est\u00e1n claros\u00bb, abund\u00f3 el legislador.<\/p>\n<p>Dentro de los cambios que no favorecen es que las horas extra dobles desaparecen del proyecto y lo \u00fanico permanece ahora es en el asunto del \u00abflexi-time\u00bb.<\/p>\n<p>Adem\u00e1s, en el bono de Navidad, incluyen unas nuevas definiciones de patrono y de microempresas, que, en el corto tiempo previsto, no pudieron evaluarlas.<\/p>\n<p>\u201cEra imposible votarle a favor de este proyecto de ley sin tener el tiempo de evaluarlo\u00bb, reiter\u00f3 Marquez Lebr\u00f3n.<\/p>\n<p>El representante le vot\u00f3 en contra a la medida, luego de solicitarle al presidente cameral abstenerse del proyecto, solicitud que fue denegada.<\/p>\n<p>La medida fue aprobada en C\u00e1mara con 29 a favor, compuestos por la delegaci\u00f3n del Partido Popular Democr\u00e1tico (PPD), el MVC y la representante de Proyecto Dignidad, Lissie Burgos Mu\u00f1iz.<\/p>\n<p>En el Senado la medida se dej\u00f3 en suspenso, ya que la moci\u00f3n de reconsideraci\u00f3n de Negr\u00f3n Santiago no fue a votaci\u00f3n. Sin embargo, el presidente del Senado adelant\u00f3 que le estar\u00eda solicitando al gobernador, Pedro Pierluisi Urrutia, una sesi\u00f3n extraordinaria para atender la medida.<\/p>\n<p><strong id=\"strong-4f1c3f612c8f758780359f4afba40027\">Lea tambi\u00e9n:<\/strong><\/p>\n<p><a href=\"https:\/\/noticel.com\/en\/legislatura\/ahora\/20211116\/camara-aprueba-enmiendas-a-la-reforma-laboral\/\" id=\"link-73235f6c555a4f195d00d34655f98274\">C\u00e1mara aprueba enmiendas a la Reforma Laboral<\/a><\/p>\n<p><a href=\"https:\/\/noticel.com\/en\/ahora\/20211116\/queda-en-suspenso-la-reforma-laboral\/\" id=\"link-99fbb5aaef71a2a09579d4102b8a840c\">Queda en suspenso la Reforma Laboral en el Senado<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>La delegaci\u00f3n defendi\u00f3 su postura de votarle en contra a las enmiendas a la Reforma Laboral y dijo que no tuvieron acceso a las enmiendas. La delegaci\u00f3n del Partido Independentista Puertorrique\u00f1o (PIP), compuesta por la senadora Mar\u00eda de Lourdes Santiago Negr\u00f3n y el representante Denis Marquez Lebr\u00f3n, explicaron que su voto en contra a las [&hellip;]<\/p>","protected":false},"author":0,"featured_media":325251,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[5,2],"tags":[],"class_list":["post-170542","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-legislatura","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/170542","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=170542"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/170542\/revisions"}],"predecessor-version":[{"id":325253,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/170542\/revisions\/325253"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/325251"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=170542"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=170542"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=170542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}