{"id":170138,"date":"2021-11-08T05:45:00","date_gmt":"2021-11-08T09:45:00","guid":{"rendered":"https:\/\/www.noticel.com\/?post_type=article&#038;p=170138"},"modified":"2025-07-15T10:41:59","modified_gmt":"2025-07-15T10:41:59","slug":"los-funcionarios-publicos-son-los-testigos-en-el-caso-criminal-por-pruebas-de-covid-19","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20211108\/los-funcionarios-publicos-son-los-testigos-en-el-caso-criminal-por-pruebas-de-covid-19\/","title":{"rendered":"Los funcionarios p\u00fablicos son los testigos en el caso criminal por pruebas de covid-19"},"content":{"rendered":"<h3>La lista de testigos de los fiscales especiales independientes est\u00e1 llena de funcionarios que inicialmente fueron referidos para investigaci\u00f3n por posible comisi\u00f3n de delitos.<\/h3>\n<p>Cuando la Oficina de Panel del Fiscal Especial Independiente (OPFEI) revel\u00f3 sus acusaciones por el tr\u00e1mite que sigui\u00f3 una compa\u00f1\u00eda de construcci\u00f3n para intentar obtener un pago de $19 millones por suplir pruebas r\u00e1pidas de detecci\u00f3n de covid-19 al Gobierno de Puerto Rico el a\u00f1o pasado, la pregunta principal fue: \u00bfy d\u00f3nde est\u00e1n los funcionarios que participaron en la transacci\u00f3n?<\/p>\n<p>Las denuncias radicadas contra el licenciado Juan Maldonado de Jes\u00fas y Aaron Vick traen la respuesta: est\u00e1n en la lista de testigos del pueblo con los que cuentan los fiscales especiales independientes en contra de los imputados.<\/p>\n<p>Por lo menos, una parte de ellos, otros, como el c\u00edrculo \u00edntimo de la exgobernadora Wanda V\u00e1zquez Garced en La Fortaleza y la propia exgobernadora, no figuran como testigos y, por tanto, quedan cubiertos bajo la declaraci\u00f3n del FEI Ram\u00f3n Mendoza Rosario de que solo han presentado los cargos con la prueba que tienen hasta ahora y que, de surgir m\u00e1s prueba, podr\u00edan ampliar la lista de procesados.<\/p>\n<p>El jueves pasado, la jueza municipal Iraida Rodr\u00edguez Castro hall\u00f3 causa para arresto contra ambos imputados, aunque en el caso de Vick fue en ausencia porque no ha sido localizado y se cree est\u00e1 en Estados Unidos.<\/p>\n<p>La abogada de Maldonado de Jes\u00fas, Mayra L\u00f3pez Mulero, adelant\u00f3 que pedir\u00eda revisi\u00f3n de la determinaci\u00f3n por entender que la OPFEI no ten\u00eda jurisdicci\u00f3n porque, precisamente, no se acus\u00f3 a ning\u00fan funcionario p\u00fablico junto a los dos del sector privado.<\/p>\n<p>En la trama de las pruebas r\u00e1pidas de covid-19 contratadas a la empresa de construcci\u00f3n APEX General Contractors a trav\u00e9s de Maldonado de Jes\u00fas y Vick, la OPFEI tuvo referidos tanto por la v\u00eda del Departamento de Justicia como de la C\u00e1mara de Representantes.<\/p>\n<p>Justicia, que en ese momento segu\u00eda bajo el mando de la exsecretaria de la agencia, y gobernadora sucesoral, V\u00e1zquez Garced, dijo a la OPFEI que no hab\u00eda causa para investigar y acusar a nadie, ni siquiera a Maldonado de Jes\u00fas o a Vick. Ese resultado significaba un triunfo pol\u00edtico y legal para V\u00e1zquez Garced, quien result\u00f3 exonerada por Justicia junto al c\u00edrculo \u00edntimo de colaboradoras en La Fortaleza que se hab\u00eda visto envuelta tambi\u00e9n en la investigaci\u00f3n.<\/p>\n<p>Esta conclusi\u00f3n de Justicia ocurri\u00f3 a pesar de que le confirmaron a la OPFEI que hubo irregularidades en el manejo de los contratos y hasta la intervenci\u00f3n de cabilderos para agenciarlos, pero que no hab\u00eda responsabilidad penal porque las leyes aplicables eran \u201cinsuficientes\u201d o \u201cflexibles\u201d.<\/p>\n<p>En su resoluci\u00f3n anunciando la ampliaci\u00f3n de la investigaci\u00f3n y la designaci\u00f3n de fiscales, la OPFEI disput\u00f3 el argumento de Justicia y sostuvo que la emergencia por la pandemia no hab\u00eda dejado en suspenso la pol\u00edtica p\u00fablica de \u201ccero tolerancia a la corrupci\u00f3n\u201d y la necesidad de \u201cgarantizar que los recursos p\u00fablicos sean utilizados correcta y efectivamente para proteger la vida, la seguridad y la salud del Pueblo\u201d.<\/p>\n<p>De 19 personas que Justicia hab\u00eda exonerado en su investigaci\u00f3n preliminar, la resoluci\u00f3n de la OPFEI del 28 de diciembre ordenaba a los fiscales a investigar a cuatro: Maldonado de Jes\u00fas, la exsubsecretaria de la Gobernaci\u00f3n, Lilliam S\u00e1nchez P\u00e9rez, la exjefa de Personal del Departamento de Salud, Mabel Cabeza Rivera, y el excomisionado del Negociado de Emergencias y Administraci\u00f3n de Desastres (NMEAD), Jos\u00e9 Burgos Vega.<\/p>\n<p>De estos, ahora Burgos Vega es uno de los testigos de los fiscales contra Maldonado de Jes\u00fas y Vick. Otros testigos, que inicialmente estuvieron en la lista de investigados, son: la exsecretaria Auxiliar en Administraci\u00f3n del Departamento de Salud, Adil Marie Rosa Rivera; la exayudante especial en NMEAD, Guarina J. Delgado Garc\u00eda; la exdirectora de la Oficina de Gerencia y Presupuesto, Iris E. Santos D\u00edaz; el secretario auxiliar de Contabilidad del Departamento de Hacienda, Alfonso Rossy Ra\u00edces; la analista de compras en el Departamento de Salud, Mariel Rivera Rivera; y el presidente de APEX, Robert Rodr\u00edguez L\u00f3pez.<\/p><div class=\"notic-content-middle\" id=\"notic-1820980325\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-970&#215;90\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1.jpg 970w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-300x28.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-768x71.jpg 768w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-18x2.jpg 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"90\"   \/><\/a><\/div>\n<p>Adem\u00e1s de S\u00e1nchez P\u00e9rez y Cabeza Rivera, los funcionarios que fueron referidos para investigaci\u00f3n, pero no aparecen ahora como testigos, son la exsecretaria interina de Salud, Concepci\u00f3n Qui\u00f1ones de Longo; el exadministrador de Servicios Generales, Ottmar Ch\u00e1vez Pi\u00f1ero; el exsecretario de la Gobernaci\u00f3n, Antonio Pab\u00f3n Batlle; la exdirectora interina de Compras en Salud, Diana Mel\u00e9ndez D\u00edaz y los miembros del Task Force M\u00e9dico, doctores Segundo Rodr\u00edguez Quilichini y Juan Luis Salgado Morales.<\/p>\n<p>Tambi\u00e9n qued\u00f3, ni como acusado ni como cooperador, Ricardo Javier V\u00e1zquez Hern\u00e1ndez, presidente de 313, LLC, una empresa que, distinto a APEX, s\u00ed lleg\u00f3 a recibir pagos millonarios sin entregar los productos que se supone entregaran al punto de que hay una demanda civil pendiente entre la empresa y el gobierno sobre eso. En esa demanda, ya surgi\u00f3 informaci\u00f3n de que 313 sac\u00f3 casi inmediatamente de su cuenta de banco el dinero que le pag\u00f3 el gobierno y lo transfiri\u00f3 a otras, incluyendo a otra empresa que tambi\u00e9n controlan personas que estaban en 313.<\/p>\n<p>Otros testigos de la OPFEI contra Maldonado de Jes\u00fas y Vick son el exsecretario de Salud, Lorenzo Gonz\u00e1lez, el fiscal Dennis Soto Fantauzzi, Jos\u00e9 A. Toral Perey\u00f3, Vanessa Figueroa Col\u00f3n, Arlene Disdier Ortiz y el cal\u00edgrafo H\u00e9ctor J. Figueroa Ramos. Presumiblemente, este \u00faltimo declarar\u00eda que la firma de Vick que apareci\u00f3 en los documentos de la propuesta de APEX para las pruebas no es falsificada, sino real. Esto, porque Vick primero le pas\u00f3 su firma a Maldonado de Jes\u00fas para que la usara en el tr\u00e1mite y luego, cuando explot\u00f3 el esc\u00e1ndalo, aleg\u00f3 que le hab\u00edan falsificado la firma. Unos delitos de falsificaci\u00f3n que el d\u00fao enfrenta ahora no son porque la firma no fuera la de Vick, sino por las representaciones que se le hicieron al gobierno sobre esa firma. Esta parte del caso gira sobre c\u00f3mo Maldonado de Jes\u00fas ensambl\u00f3 una resoluci\u00f3n corporativa de APEX para presentarla al gobierno en el tr\u00e1mite del contrato.<\/p>\n<p>Para Vick, esta la primera consecuencia que tiene su decisi\u00f3n de prestar su firma para que Maldonado de Jes\u00fas pudiera someter documentos que ped\u00eda el gobierno para tramitar el contrato de $38 millones que, entre contacto inicial con el equipo del Departamento de Salud y desembolso de un pago de $19 millones, tom\u00f3 unos tres d\u00edas. Ese desembols\u00f3 qued\u00f3 detenido cuando levant\u00f3 banderas de seguridad en el Oriental Bank. Luego de detenido el pago, se desmoron\u00f3 la transacci\u00f3n y se conoci\u00f3 que las pruebas ven\u00edan por una cadena de suplidores que se originaba en Australia en una compa\u00f1\u00eda que nunca las produjo ni las pod\u00eda producir.<\/p>\n<p>Pero, para Maldonado de Jes\u00fas, es el segundo evento ya que todav\u00eda tiene pendiente ante el Tribunal Supremo una acci\u00f3n disciplinaria que puede culminar en sanciones en su contra como notario.<\/p>\n<p>Para ver la resoluci\u00f3n de la OPFEI ordenando la investigaci\u00f3n, pulse aqu\u00ed.<\/p>\n<p>Para ver las denuncias contra Maldonado de Jes\u00fas y Vick, pulse aqu\u00ed.<\/p>\n<p>Vea:<\/p>\n<p><a href=\"https:\/\/noticel.com\/en\/tribunales\/ahora\/gobierno\/top-stories\/20201027\/demanda-revela-transacciones-bancarias-de-cabildero-pnp-con-dineros-de-pruebas-covid-19\/\" id=\"link-5f945cefe9e76ae05cbd954a95b4bae8\" target=\"_blank\"> Demanda revela transacciones bancarias de cabildero PNP con dineros de pruebas COVID-19 <\/a><\/p>\n<p><a href=\"https:\/\/noticel.com\/en\/ahora\/top-stories\/20200629\/comision-de-salud-radica-informe-con-referidos-por-irregularidades-y-violaciones-de-ley-en-compras-d\/\" id=\"link-072dc1538626fd2e9eb105977baef21f\" target=\"_blank\">Comisi\u00f3n de Salud radica informe con referidos por irregularidades y violaciones de ley en compras de pruebas r\u00e1pidas <\/a><\/p>\n<p><a href=\"https:\/\/noticel.com\/en\/legislatura\/ahora\/top-stories\/20200414\/el-task-force-medico-evaluo-y-avalo-la-millonaria-compra-de-pruebas-a-apex-por-via-rapida\/\" id=\"link-04f59302f4c195bf36068b34352f35f2\" target=\"_blank\">El \u201cTask Force\u201d M\u00e9dico evalu\u00f3 y aval\u00f3 la millonaria compra de pruebas a Apex por v\u00eda r\u00e1pida <\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>La lista de testigos de los fiscales especiales independientes est\u00e1 llena de funcionarios que inicialmente fueron referidos para investigaci\u00f3n por posible comisi\u00f3n de delitos. Cuando la Oficina de Panel del Fiscal Especial Independiente (OPFEI) revel\u00f3 sus acusaciones por el tr\u00e1mite que sigui\u00f3 una compa\u00f1\u00eda de construcci\u00f3n para intentar obtener un pago de $19 millones por [&hellip;]<\/p>","protected":false},"author":0,"featured_media":328334,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[13,2],"tags":[],"class_list":["post-170138","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tribunales","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/170138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=170138"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/170138\/revisions"}],"predecessor-version":[{"id":328343,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/170138\/revisions\/328343"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/328334"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=170138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=170138"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=170138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}