{"id":169621,"date":"2021-10-26T08:22:00","date_gmt":"2021-10-26T12:22:00","guid":{"rendered":"https:\/\/www.noticel.com\/la-calle\/policiacas\/20211026\/hallan-otro-asesinado-dentro-de-un-carro\/"},"modified":"2025-07-15T11:39:51","modified_gmt":"2025-07-15T11:39:51","slug":"hallan-otro-asesinado-dentro-de-un-carro","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/la-calle\/20211026\/hallan-otro-asesinado-dentro-de-un-carro\/","title":{"rendered":"Hallan otro asesinado dentro de un carro"},"content":{"rendered":"<h3>El occido a\u00fan no ha sido identificado<\/h3>\n<p>Un asesinato se report\u00f3 a eso de las 7:00 de la ma\u00f1ana del martes, en la carretera PR-690, esquina del supermercado Selectos, en Vega Alta.<\/p>\n<p>Seg\u00fan la informaci\u00f3n preliminar, se recibi\u00f3 una llamada a trav\u00e9s del Sistema de Emergencias 9-1-1, sobre una persona herida de bala.<\/p>\n<p>Al llegar los agentes al lugar, encontraron el cuerpo de un hombre baleado en el interior de un veh\u00edculo.<\/p><div class=\"notic-content-middle\" id=\"notic-1886567699\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>Al momento se investigan las circunstancias de estos hechos.<\/p>\n<p>Personal de la Divisi\u00f3n de Homicidios del Cuerpo de Investigaciones Criminales de Vega Baja en uni\u00f3n al fiscal de turno se dirigen a la escena.<\/p>","protected":false},"excerpt":{"rendered":"<p>El occido a\u00fan no ha sido identificado Un asesinato se report\u00f3 a eso de las 7:00 de la ma\u00f1ana del martes, en la carretera PR-690, esquina del supermercado Selectos, en Vega Alta. Seg\u00fan la informaci\u00f3n preliminar, se recibi\u00f3 una llamada a trav\u00e9s del Sistema de Emergencias 9-1-1, sobre una persona herida de bala. Al llegar [&hellip;]<\/p>","protected":false},"author":0,"featured_media":332275,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12,15],"tags":[],"class_list":["post-169621","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-calle","category-policiacas"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/169621","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=169621"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/169621\/revisions"}],"predecessor-version":[{"id":332286,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/169621\/revisions\/332286"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/332275"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=169621"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=169621"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=169621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}