{"id":169566,"date":"2021-10-24T16:49:00","date_gmt":"2021-10-24T20:49:00","guid":{"rendered":"https:\/\/www.noticel.com\/deportes\/20211024\/activistas-antivacunas-intentaron-entrar-a-cancha-de-los-nets-en-apoyo-a-kyrie-irving\/"},"modified":"2025-07-15T11:44:02","modified_gmt":"2025-07-15T11:44:02","slug":"activistas-antivacunas-intentaron-entrar-a-cancha-de-los-nets-en-apoyo-a-kyrie-irving","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/deportes\/20211024\/activistas-antivacunas-intentaron-entrar-a-cancha-de-los-nets-en-apoyo-a-kyrie-irving\/","title":{"rendered":"Activistas antivacunas intentaron entrar a cancha de los Nets en apoyo a Kyrie Irving"},"content":{"rendered":"<h3>El jugador no ha visto acci\u00f3n esta temporada por negarse a inocularse contra el covid-19<\/h3>\n<p>Un grupo de activistas antivacunas intentaron este domingo irrumpir en el Coliseo Barclays Center de Nueva York donde se jugaba el partido de baloncesto entre los Brooklyn Nets y los Charlotte Hornets, en apoyo del jugador Kyrie Irving, que no ha sido convocado por los Nets al negarse a inyectarse la vacuna contra el covid-19, informaron medios locales.<\/p>\n<p>Los manifestantes, que han organizado varias protestas en las \u00faltimas semanas, convocaron la concentraci\u00f3n de hoy a las 2:00 p.m. hora local, dos horas antes de que arrancara el partido.<\/p>\n<p>En varios videos difundidos a trav\u00e9s de las redes sociales se puede ver a los participantes cantando lemas contra las vacunas y a varios de ellos superando el per\u00edmetro de seguridad y forcejeando con varios guardias para intentar entrar en el recinto.<\/p>\n<p>En su frustrado intento, los manifestantes \u2014algunos de los cuales llevaban camisetas en solidaridad con el jugador\u2014 gritaban \u00abdejar que Kyrie juegue\u00bb.<\/p>\n<p>https:\/\/twitter.com\/jasonrmcintyre\/status\/1452362871287926785<\/p><div class=\"notic-content-middle\" id=\"notic-988323013\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-970&#215;90\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1.jpg 970w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-300x28.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-768x71.jpg 768w, https:\/\/cdn.noticel.com\/2026\/07\/30100146\/Acodese-Adaptaciones-Noticel-970x90-1-18x2.jpg 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"90\"   \/><\/a><\/div>\n<p>Los Nets decidieron, el pasado 12 de noviembre, que su base estrella no estar\u00eda con el equipo porque no es elegible para jugar en su cancha local, debido a que un mandato de Nueva York requiere que los atletas profesionales est\u00e9n vacunados para practicar o competir en lugares p\u00fablicos.<\/p>\n<p>Irving reaccion\u00f3 asegurando que no quer\u00eda perder el salario ni la oportunidad de competir por un campeonato con su equipo, pero que estaba haciendo \u00ablo mejor\u00bb para \u00e9l al negarse a recibir la vacuna.<\/p>\n<p>Hablando en Instagram Live, Irving dijo que amaba el baloncesto y que no se iba a retirar.<\/p>\n<p>\u00abEstoy haciendo lo mejor para m\u00ed. Conozco las consecuencias aqu\u00ed y si eso significa que soy juzgado y demonizado por eso, eso es exactamente lo que es\u00bb, destac\u00f3 Irving. \u00abEse es el papel que interpreto, pero nunca quise renunciar a mi pasi\u00f3n, mi amor, mi sue\u00f1o por este mandato\u00bb.<\/p>","protected":false},"excerpt":{"rendered":"<p>El jugador no ha visto acci\u00f3n esta temporada por negarse a inocularse contra el covid-19 Un grupo de activistas antivacunas intentaron este domingo irrumpir en el Coliseo Barclays Center de Nueva York donde se jugaba el partido de baloncesto entre los Brooklyn Nets y los Charlotte Hornets, en apoyo del jugador Kyrie Irving, que no [&hellip;]<\/p>","protected":false},"author":0,"featured_media":332675,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[31],"tags":[],"class_list":["post-169566","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/169566","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=169566"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/169566\/revisions"}],"predecessor-version":[{"id":332677,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/169566\/revisions\/332677"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/332675"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=169566"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=169566"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=169566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}