{"id":169246,"date":"2021-10-16T09:46:00","date_gmt":"2021-10-16T13:46:00","guid":{"rendered":"https:\/\/www.noticel.com\/deportes\/20211016\/imparables-las-bravas-en-el-baloncesto-femenino\/"},"modified":"2025-07-15T12:16:55","modified_gmt":"2025-07-15T12:16:55","slug":"imparables-las-bravas-en-el-baloncesto-femenino","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/deportes\/20211016\/imparables-las-bravas-en-el-baloncesto-femenino\/","title":{"rendered":"Imparables las Bravas en el baloncesto femenino"},"content":{"rendered":"<h3>Vencieron anoche a las l\u00edderes Gigantes de Carolina<\/h3>\n<p>Las Bravas de Cidra derrotaron el viernes 85-73 a las Gigantes de Carolina en el coliseo Juanito Cabello de Cidra.<\/p>\n<p>Imani Watkins sum\u00f3 28 puntos y Lanese Bough 18 para sumar su sexta victoria consecutiva, en el Baloncesto Superior Nacional Femenino.<\/p>\n<p>Cidra mejor\u00f3 a 12-5 para sacar un juego de ventaja sobre las Cangrejeras de Santuce (10-5) en la disputa por uno de los dos boletos directos a la ronda semifinal. Carolina sigue en la cima, pero vio caer su marca a 12-3.<\/p><div class=\"notic-content-middle\" id=\"notic-1245140805\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>Adrienne Godbold agreg\u00f3 16 unidades con 13 rebotes y Rita Acevedo col\u00f3 13.<\/p>\n<p>Por las Gigantes, Tierra Henderson lider\u00f3 con 21 tantos y 10 capturas. Nici Gilday le sigui\u00f3 con 18 y Charity Harris con 17.<\/p>\n<p>Las Bravas visitar\u00e1n hoy s\u00e1bado, 16 de octubre, a las Atenienses de Manat\u00ed en el coliseo Juan Aubin \u2018Bincito\u2019 Cruz Abreu, desde las 8:00 de la noche.<\/p>","protected":false},"excerpt":{"rendered":"<p>Vencieron anoche a las l\u00edderes Gigantes de Carolina Las Bravas de Cidra derrotaron el viernes 85-73 a las Gigantes de Carolina en el coliseo Juanito Cabello de Cidra. Imani Watkins sum\u00f3 28 puntos y Lanese Bough 18 para sumar su sexta victoria consecutiva, en el Baloncesto Superior Nacional Femenino. Cidra mejor\u00f3 a 12-5 para sacar [&hellip;]<\/p>","protected":false},"author":0,"featured_media":335366,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[31],"tags":[],"class_list":["post-169246","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/169246","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=169246"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/169246\/revisions"}],"predecessor-version":[{"id":335373,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/169246\/revisions\/335373"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/335366"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=169246"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=169246"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=169246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}