{"id":167925,"date":"2021-09-16T19:54:00","date_gmt":"2021-09-16T23:54:00","guid":{"rendered":"https:\/\/www.noticel.com\/la-calle\/top-stories\/20210916\/juanma-lopez-esta-separado-del-resto-de-los-presos-en-la-carcel-de-bayamon\/"},"modified":"2025-07-15T14:18:30","modified_gmt":"2025-07-15T14:18:30","slug":"juanma-lopez-esta-separado-del-resto-de-los-presos-en-la-carcel-de-bayamon","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/la-calle\/20210916\/juanma-lopez-esta-separado-del-resto-de-los-presos-en-la-carcel-de-bayamon\/","title":{"rendered":"Juanma L\u00f3pez est\u00e1 separado del resto de los presos en la c\u00e1rcel de Bayam\u00f3n"},"content":{"rendered":"<h3>Mientras espera por su vista preliminar<\/h3>\n<p>El exp\u00fagil Juan Manuel \u2018\u2019Juanma\u2019\u2019 L\u00f3pez Rivera, se encuentra aislado del resto de la poblaci\u00f3n correccional mientras espera por la celebraci\u00f3n de la vista preliminar en el caso que enfrenta por violencia de g\u00e9nero contra su expareja, Andrea Ojeda Cruz.<\/p>\n<p>As\u00ed lo confirm\u00f3 la secretaria de Correcci\u00f3n, Ada Escobar Pab\u00f3n, al indicar que la medida responde al hecho de que se trata de una persona conocida por ser un boxeador y, debido a que el caso cobr\u00f3 gran notoriedad en el pa\u00eds, optaron por separarlo por motivos de seguridad.<\/p>\n<p>\u201cJuanma est\u00e1 en estos momentos en el centro de ingresos de Bayam\u00f3n 705\u201d, dijo Escobar Pab\u00f3n en Jugando Pelota Dura (TeleOnce).<\/p>\n<p>\u201cLuego del proceso de admisi\u00f3n est\u00e1 ubicado en una secci\u00f3n donde se le brinda una protecci\u00f3n adicional por la figura p\u00fablica y por lo que implica este caso. Est\u00e1 separado (del resto de la comunidad penal)\u201d, agreg\u00f3.<\/p>\n<p>L\u00f3pez Rivera fue encarcelado ayer por violar las condiciones de su fianza diferida otorgada por el Programa de Servicios con Antelaci\u00f3n a Juicio (PSAJ), tras emitir unas declaraciones en una entrevista televisiva en la que se dirigi\u00f3 a su expareja.<\/p>\n<p>El excampe\u00f3n mundial de boxeo se encontraba libre bajo supervisi\u00f3n electr\u00f3nica, luego que le fuera concedida una fianza diferida de $175,000 por parte del PSAJ.<\/p><div class=\"notic-content-middle\" id=\"notic-1147032009\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>La titular de correcci\u00f3n no especific\u00f3 si L\u00f3pez Rivera ha recibido alguna asistencia de profesionales de la salud mental una vez fue ingresado.<\/p>\n<p>\u2018\u2019No tengo conocimiento si al momento \u00e9l ha requerido ayuda psicol\u00f3gica adicional, pero, como parte del proceso de admisi\u00f3n e un confinado al sistema correccional siempre pasa por el proceso de evaluaci\u00f3n psicol\u00f3gica, f\u00edsica y dental\u2019\u2019, destac\u00f3.<\/p>\n<p>Contra el exp\u00fagil pesan siete cargos por maltrato f\u00edsico, sicol\u00f3gico, mediante amenaza y da\u00f1os a la propiedad, en violaci\u00f3n a los art\u00edculos 3.1 y 3.3 de la Ley 54 de 15 de agosto de 1989, conocida como Ley para la Prevenci\u00f3n e Intervenci\u00f3n con la Violencia Dom\u00e9stica, seg\u00fan enmendada.<\/p>\n<p>Fue a trav\u00e9s de un v\u00eddeo en las redes sociales que Ojeda Cruz denunci\u00f3 haber sido v\u00edctima de un patr\u00f3n de abuso f\u00edsico y psicol\u00f3gico por parte de L\u00f3pez Rivera. La mujer, quien es conocida en las redes sociales como \u201cLa Peki\u201d, present\u00f3 fotos que mostraban los golpes que supuestamente el exp\u00fagil le propin\u00f3 y tambi\u00e9n un v\u00eddeo que supuestamente fue grabado por el propio L\u00f3pez Rivera en el que se escucha la voz que la llamaba \u201cput\u2026\u201d y \u201cte voy a matar cabr\u2026\u201d<\/p>\n<p>La vista est\u00e1 pautada para el pr\u00f3ximo martes, 21 de septiembre.<\/p>","protected":false},"excerpt":{"rendered":"<p>Mientras espera por su vista preliminar El exp\u00fagil Juan Manuel \u2018\u2019Juanma\u2019\u2019 L\u00f3pez Rivera, se encuentra aislado del resto de la poblaci\u00f3n correccional mientras espera por la celebraci\u00f3n de la vista preliminar en el caso que enfrenta por violencia de g\u00e9nero contra su expareja, Andrea Ojeda Cruz. As\u00ed lo confirm\u00f3 la secretaria de Correcci\u00f3n, Ada Escobar [&hellip;]<\/p>","protected":false},"author":0,"featured_media":345163,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-167925","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-calle"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/167925","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=167925"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/167925\/revisions"}],"predecessor-version":[{"id":345166,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/167925\/revisions\/345166"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/345163"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=167925"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=167925"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=167925"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}