{"id":167920,"date":"2021-09-16T17:32:00","date_gmt":"2021-09-16T21:32:00","guid":{"rendered":"https:\/\/www.noticel.com\/ahora\/gobierno\/20210916\/comisionada-residente-anuncia-aprobacion-de-plan-de-accion-para-manejo-de-erosion-costera-en-zona-me\/"},"modified":"2025-07-15T14:18:56","modified_gmt":"2025-07-15T14:18:56","slug":"comisionada-residente-anuncia-aprobacion-de-plan-de-accion-para-manejo-de-erosion-costera-en-zona-me","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20210916\/comisionada-residente-anuncia-aprobacion-de-plan-de-accion-para-manejo-de-erosion-costera-en-zona-me\/","title":{"rendered":"Comisionada residente anuncia aprobaci\u00f3n de plan de acci\u00f3n para manejo de erosi\u00f3n costera en zona me"},"content":{"rendered":"<h3>El plan contempla un proyecto a un costo de $365.2 millones y debe tomar unos siete a\u00f1os, una vez se aprueben los fondos<\/h3>\n<p>La comisionada residente, Jenniffer Gonz\u00e1lez Col\u00f3n, anunci\u00f3 el jueves, la aprobaci\u00f3n del estudio de viabilidad para atender la erosi\u00f3n costera, del \u00e1rea de la Bah\u00eda de San Juan y la Laguna Condado, por parte del Cuerpo de Ingenieros del Ej\u00e9rcito de los Estados Unidos (USACE, por sus siglas en ingl\u00e9s).<\/p>\n<p>\u201cGracias a este estudio para el que conseguimos los fondos en el 2018, ya se tiene un plan de acci\u00f3n concreto y ahora podemos solicitar los fondos necesarios para su inicio\u201d, dijo en comunicaci\u00f3n escrita la comisionada residente luego que USACE le informara sobre la firma del estudio de viabilidad por parte del LTGEN Spellmon, jefe de Ingenieros y el comandante general del Cuerpo de Ingenieros del Ej\u00e9rcito de los Estados Unidos, con quien la comisionada se reuni\u00f3 en junio pasado en su visita a Puerto Rico.<\/p>\n<p>La comisionada explic\u00f3 que en 1970 (Ley P\u00fablica 91-611) se aprob\u00f3 en el Congreso hacer un estudio sobre la erosi\u00f3n costera en la zona metro, pero que no se hab\u00eda podido realizar por falta de fondos.<\/p>\n<p>Mencion\u00f3 que logr\u00f3 incluir la asignaci\u00f3n de los fondos necesarios para hacer el estudio en la Ley Bipartita de Presupuesto del 2018 (Ley P\u00fablica 115-123). La asignaci\u00f3n para el estudio fue de 3 millones de d\u00f3lares.<\/p><div class=\"notic-content-middle\" id=\"notic-1070780771\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.cst.pr.gov\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"CST Banners Pasa la llave\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/01063722\/CST_Suma-Pasa-La-Llave_728x90.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/01063722\/CST_Suma-Pasa-La-Llave_728x90.jpg 728w, https:\/\/cdn.noticel.com\/2026\/07\/01063722\/CST_Suma-Pasa-La-Llave_728x90-300x37.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/01063722\/CST_Suma-Pasa-La-Llave_728x90-18x2.jpg 18w\" sizes=\"(max-width: 728px) 100vw, 728px\" width=\"728\" height=\"90\"   \/><\/a><\/div>\n<p>El estudio se hizo con el objetivo de buscar alternativas para reducir el riesgo de da\u00f1os por inundaciones costeras a los activos (estructuras, veh\u00edculos e infraestructura cr\u00edtica) en el \u00e1rea metropolitana; reducir el riesgo de da\u00f1os a los activos por el embate de olas durante huracanes y tormentas e incrementar la resiliencia comunitaria en el \u00e1rea metropolitana.<\/p>\n<p>El plan contempla un proyecto a un costo de $365.2 millones, dividido entre la parte federal (USACE) $237.9 millones y el socio local unos $127.3 millones. Se espera que est\u00e9 listo a siete a\u00f1os una vez se asignen los fondos.<\/p>\n<p>El proyecto est\u00e1 dise\u00f1ado para hacer elevaciones de 7.5 pies a 9 pies que reducir\u00edan el riesgo de inundaciones costeras en un 98 por ciento a 100 por ciento durante un evento de probabilidad de excedencia promedio, con una efectividad del 92% al 100% sobre un aumento pronosticado del nivel del mar.<\/p>\n<p>Se prev\u00e9 incluir 1.5 millas de diques, 6.5 millas de muros de contenci\u00f3n, .7 millas de rompeolas, \u00e1reas de barrera natural, mitigaci\u00f3n de impacto de humedales y mangles, entre otras consideraciones.<\/p>","protected":false},"excerpt":{"rendered":"<p>El plan contempla un proyecto a un costo de $365.2 millones y debe tomar unos siete a\u00f1os, una vez se aprueben los fondos La comisionada residente, Jenniffer Gonz\u00e1lez Col\u00f3n, anunci\u00f3 el jueves, la aprobaci\u00f3n del estudio de viabilidad para atender la erosi\u00f3n costera, del \u00e1rea de la Bah\u00eda de San Juan y la Laguna Condado, [&hellip;]<\/p>","protected":false},"author":0,"featured_media":345197,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ep_exclude_from_search":false,"footnotes":""},"categories":[4,2],"tags":[],"class_list":["post-167920","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gobierno","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/167920","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=167920"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/167920\/revisions"}],"predecessor-version":[{"id":345200,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/167920\/revisions\/345200"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/345197"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=167920"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=167920"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=167920"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}