{"id":167609,"date":"2021-09-10T05:45:00","date_gmt":"2021-09-10T09:45:00","guid":{"rendered":"https:\/\/www.noticel.com\/?post_type=article&#038;p=167609"},"modified":"2025-07-15T14:43:35","modified_gmt":"2025-07-15T14:43:35","slug":"para-el-2022-los-miles-de-millones-de-dolares-para-la-construccion-en-puerto-rico","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20210910\/para-el-2022-los-miles-de-millones-de-dolares-para-la-construccion-en-puerto-rico\/","title":{"rendered":"Para el 2022 los miles de millones de d\u00f3lares para la construcci\u00f3n en Puerto Rico"},"content":{"rendered":"<h3>Aseguraron el gobernador Pedro Pierluisi y el director de COR3 Manuel Laboy en la Convenci\u00f3n de la Asociaci\u00f3n de Contratistas Generales<\/h3>\n<p>El pr\u00f3ximo a\u00f1o 2022 ser\u00e1 finalmente el que traer\u00e1 a Puerto Rico la actividad masiva y multimillonaria en construcci\u00f3n que se est\u00e1 esperando desde que iniciaron los procesos de reconstrucci\u00f3n tras los huracanes Irma y Mar\u00eda en el 2017, coincidieron el gobernador Pedro Pierluisi y el director ejecutivo de la Oficina Central De Recuperaci\u00f3n, Reconstrucci\u00f3n Y Resiliencia (COR3), Manuel Laboy.<\/p>\n<p>Ambos comparecieron ayer ante la 47ma Convenci\u00f3n de la Asociaci\u00f3n de Contratistas Generales, ante la cual Laboy proclam\u00f3 entre aplausos que es tiempo ya de \u201cmover los miles de millones que est\u00e1n en el papel a la realidad\u201d.<\/p>\n<p>\u201cLo que queremos lograr y lo que esperamos es que muchos de esos proyectos entren a construcci\u00f3n en el 2022 y estar\u00edan impactando toda la Isla\u201d, dijo Laboy refiri\u00e9ndose a proyectos de la Autoridad de Energ\u00eda El\u00e9ctrica, la Autoridad de Acueductos y Alcantarillados y el Departamento de Educaci\u00f3n, que entre las tres agencias tienen asignados $15,200 millones, de los $28,600 millones que otorg\u00f3 la Agencia Federal para el Manejo de Emergencias (FEMA) a Puerto Rico.<\/p>\n<p>Precis\u00f3 que en el caso de la AEE, hay 65 proyectos de transmisi\u00f3n y distribuci\u00f3n que est\u00e1n ahora en ingenier\u00eda y arquitectura y en aprobaciones finales de FEMA. Si todo sale como est\u00e1n esperando, casi $3,000 millones en proyectos deben ir a subasta de construcci\u00f3n a partir del a\u00f1o que viene.<\/p>\n<p>La misma situaci\u00f3n present\u00f3 para la AAA, donde sobre 30 proyectos, entre $500 y $1,000 millones deben estar entrando tambi\u00e9n a subasta de construcci\u00f3n; y en el caso de Educaci\u00f3n se espera que al menos 175 escuelas vayan a una estrategia de reparaci\u00f3n con una inversi\u00f3n de entre $200 a $300 millones tambi\u00e9n en el 2022.<\/p>\n<p>Por su parte el gobernador se\u00f1al\u00f3 que del dinero que aprob\u00f3 FEMA para Puerto Rico unos $24,000 millones ya est\u00e1n obligados, que quiere decir que est\u00e1n destinados a un proyecto en espec\u00edfico que est\u00e1 en proceso de dise\u00f1o, ingenier\u00eda, aprobaciones o subasta.<\/p>\n<p>Precis\u00f3 que cerca de $5,200 millones est\u00e1n destinados a trabajos de emergencia y los restantes $18,800 millones son proyectos de obra permanente.<\/p>\n<p>De los fondos CDBG-DR, agreg\u00f3, hay $10,000 millones asignados y ya se han obligado $3,300 millones para obras, de los cuales hay $2,300 millones est\u00e1n pendientes de aprobaci\u00f3n.<\/p>\n<p>Seg\u00fan el detalle que ofreci\u00f3 Laboy, hay 114 proyectos financiados con fondos de FEMA  ya asignados en los que la inversi\u00f3n sobrepasa los $5 millones, y otros 743 cuya inversi\u00f3n est\u00e1 entre $1 mill\u00f3n y $4.9 millones. Entre el rango de $123,000 y $999,000, agreg\u00f3, hay en proceso un total de 1,977 proyectos adicionales.<\/p><div class=\"notic-content-middle\" id=\"notic-1845230132\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>Las agencias que tienen la mayor\u00eda de estos proyectos por sobre los $5 millones son, entre otras, la Universidad de Puerto Rico, con 27 proyectos y $266 millones; el Departamento de Transportaci\u00f3n y Obras P\u00fablicas, con  nueve proyectos y $80 millones, el Departamento de Salud, con dos proyectos y $90 millones y la Autoridad de Edificios P\u00fablicos, con siete proyectos y $73 millones.<\/p>\n<p><strong id=\"strong-9d6d1bc4bbca264f6b123ce71792549d\">Cuestionan obligaci\u00f3n de negociar con sindicatos<\/strong><\/p>\n<p>Durante el evento de ayer el presidente de los contratistas, Umberto Donato, cuestion\u00f3 al gobernador sobre su posici\u00f3n ante la postura de Luma Energy de que en las labores de renovaci\u00f3n de la red el\u00e9ctrica de Puerto Rico solo utilizar\u00e1 personal que pertenezca o est\u00e9 representado por la International Brotherhood of Electrical Workers Local 222 (IBEW-222),<\/p>\n<p>Este sindicato anunci\u00f3 en julio pasado que se fusion\u00f3 con la Uni\u00f3n Insular de Trabajadores Industriales y Construcciones El\u00e9ctricas (Uitice), que es la que representa hoy a los empleados que trabajan para Luma Energy.<\/p>\n<p>Donato le plante\u00f3 al gobernador que de aplicarse esa pol\u00edtica se encarecer\u00edan los costos de las obras y quedar\u00edan adem\u00e1s fuera de participar en esos proyectos aquellas empresas locales que tienen \u201ctaller abierto\u201d y que no acepten esa condici\u00f3n.<\/p>\n<p>El primer ejecutivo record\u00f3 que seg\u00fan el contrato firmado con Luma, dicha empresa es la responsable de supervisar las labores de restauraci\u00f3n de la red. Inform\u00f3 adem\u00e1s que trajo el tema a la atenci\u00f3n del presidente de la corporaci\u00f3n en Puerto Rico, Wayne Stensby y le sugiri\u00f3 la posibilidad de hacer excepciones en algunos proyectos.<\/p>\n<p>Pierluisi indic\u00f3 que a\u00fan no tiene respuesta de Stensby, pero se expres\u00f3 confiado que se podr\u00e1 llegar a un \u201cpunto medio\u201d en esta controversia y opin\u00f3 que a nadie le conviene, incluyendo a Luma, que estos proyectos se retrasen por esta disputa.<\/p>\n<p>Le aclar\u00f3 a los contratistas que su deseo es que se tenga el mejor talento en esas labores, que se le pague bien a esos trabajadores y se le reconozcan buenas condiciones de trabajo.<\/p>","protected":false},"excerpt":{"rendered":"<p>Aseguraron el gobernador Pedro Pierluisi y el director de COR3 Manuel Laboy en la Convenci\u00f3n de la Asociaci\u00f3n de Contratistas Generales El pr\u00f3ximo a\u00f1o 2022 ser\u00e1 finalmente el que traer\u00e1 a Puerto Rico la actividad masiva y multimillonaria en construcci\u00f3n que se est\u00e1 esperando desde que iniciaron los procesos de reconstrucci\u00f3n tras los huracanes Irma [&hellip;]<\/p>","protected":false},"author":0,"featured_media":347260,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[4,2],"tags":[],"class_list":["post-167609","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gobierno","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/167609","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=167609"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/167609\/revisions"}],"predecessor-version":[{"id":347261,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/167609\/revisions\/347261"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/347260"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=167609"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=167609"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=167609"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}