{"id":165896,"date":"2021-08-03T08:46:00","date_gmt":"2021-08-03T12:46:00","guid":{"rendered":"https:\/\/www.noticel.com\/deportes\/20210803\/nuevo-record-mundial-en-400-metros-vallas-en-tokio\/"},"modified":"2025-07-15T17:21:52","modified_gmt":"2025-07-15T17:21:52","slug":"nuevo-record-mundial-en-400-metros-vallas-en-tokio","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/deportes\/20210803\/nuevo-record-mundial-en-400-metros-vallas-en-tokio\/","title":{"rendered":"Nuevo r\u00e9cord mundial en 400 metros vallas en Tokio"},"content":{"rendered":"<h3>El noruego Karsten Warholm mejor\u00f3 su propia marca al regustrar 45.94<\/h3>\n<p>El atleta noruego Karsten Warholm bati\u00f3 su r\u00e9cord mundial de 400 metros con vallas con un tiempo de 45.94 segundos en un formidable duelo con el estadounidense Ray Benjamin, que termin\u00f3 segundo con 46.17.<\/p>\n<p>Se trata del segundo r\u00e9cord mundial que cae durante los Juegos de Tokio 2020, despu\u00e9s del conseguido por la venezolana Yulimar Rojas en la final de triple salto (15.67).<\/p>\n<p>La medalla de bronce fue para el brasile\u00f1o Alison dos Santos, que bati\u00f3 su r\u00e9cord sudamericano con 46.72, a solo dos cent\u00e9simas del r\u00e9cord mundial anterior.<\/p>\n<p>La cara de asombro del propio Warholm, que ten\u00eda el r\u00e9cord anterior en 46.70 desde el 1 de julio pasado en Oslo, ilustraba el incre\u00edble rango de su nuevo r\u00e9cord.<\/p>\n<p>Era uno de los grandes enfrentamientos de los Juegos de Tokio y no defraud\u00f3. El plusmarquista mundial y el campe\u00f3n estadounidense se ve\u00edan las caras en Tokio por primera vez este a\u00f1o despu\u00e9s de haber sostenido un duelo de grandes marcas, cada uno por su cuenta.<\/p>\n<p>El 1 de julio, en los Bislett Games de Oslo, Warlhom logr\u00f3, al fin, con una marca de 46.70, acabar con el viejo r\u00e9cord acu\u00f1ado por el estadounidense Kevin Young en los Juegos de Barcelona&#8217;92 (46.78).<\/p>\n<p>Solo cuatro d\u00edas antes, en Eugene, Ray Benjamin se hab\u00eda quedado muy cerca de batirlo con 46.83, pero el noruego, que ha derrotado al norteamericano las cuatro veces que se han enfrentado, se apresur\u00f3 a tomar la delantera.<\/p>\n<p>En la hora suprema de la final ol\u00edmpica, Warholm ratific\u00f3 su hegemon\u00eda y Benjamin lo oblig\u00f3 a batir el r\u00e9cord del mundo si quer\u00eda ganar la medalla de oro, porque el estadounidense se emparej\u00f3 con el noruego a media recta final, poco antes de atacar el \u00faltimo obst\u00e1culo.<\/p>\n<p>Fue en ese punto, presionado por la presencia amenazante, hombro con hombro, del norteamericano, cuando Warholm meti\u00f3 una marcha m\u00e1s para ganar la meta con un crono asombroso que rebaja en 76 cent\u00e9simas su r\u00e9cord mundial anterior.<\/p>\n<p>Si la plusmarca de Kevin Young hab\u00eda permanecido intacta durante 29 a\u00f1os, la primera de Warholm ha tenido una vida ef\u00edmera, 33 d\u00edas.<\/p><div class=\"notic-content-middle\" id=\"notic-1404112562\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>El brasile\u00f1o Alison dos Santos, muy estable en los primeros puestos de las carreras m\u00e1s prestigiosas del a\u00f1o, fue un digno tercero que presenci\u00f3 de cerca el formidable combate entre los dos mejores.<\/p>\n<p><strong id=\"strong-e20937094f969625eeb3eb09b10b7c6e\">Oro en el \u00faltimo salto<\/strong><\/p>\n<p>En el foso de longitud, un salto de siete metros justos en la \u00faltima ronda proclam\u00f3 campeona ol\u00edmpica a la alemana Malaika Mihambo, tambi\u00e9n campeona mundial, en una final con las cuatro mejores separadas por nueve cent\u00edmetros.<\/p>\n<p>La estadounidense Brittney Reese, que acariciaba ya su segundo t\u00edtulo ol\u00edmpico a falta de una ronda, termin\u00f3 segunda con tres cent\u00edmetros menos que la alemana, y con la misma marca de 6.97 -pero peor segundo- la nigeriana Ese Brume recibi\u00f3 el bronce, mientras que la serbia Ivana Spanovic qued\u00f3 fuera del podio con 6.91.<\/p>\n<p>En ausencia de la campeona de R\u00edo, la estadounidense Tianna Bartoletta, la final ol\u00edmpica de Tokio quedaba abierta a muchas candidaturas, con la presencia de cinco con marcas superiores a los siete metros este a\u00f1o.<\/p>\n<p>El r\u00e1nking mundial se\u00f1alaba como primeras favoritas a Ese Brume, bronce en el \u00faltimo mundial, que encabeza la lista con sus 7.17 del 29 de mayo en Chula Vista (California), y a las estadounidenses Tara Davis (7,.4) y Brittney Reese (7.13), campeona ol\u00edmpica en Londres 2012.<\/p>\n<p>Las otras dos del club de los siete eran la anglo-virgenense Chantel Malone (7.08), que hoy cerr\u00f3 la clasificaci\u00f3n con 6.50, y la serbia Ivana Spanovic (7.00), bronce ol\u00edmpico en R\u00edo 2016.<\/p>\n<p>La igualdad era tan estrecha que a la sexta y \u00faltima ronda se lleg\u00f3 con las cuatro primeras en un margen de seis cent\u00edmetros. Reese dominaba con 6.97, igual marca que Brume pero con mejor segundo (6.95 frente a 6.88), y a continuaci\u00f3n estaban la campeona mundial, Malaika Mihambo (6.95), y Spanovic (6.91).<\/p>\n<p>Cualquiera pod\u00eda ganar con el \u00faltimo esfuerzo. En orden de intervenci\u00f3n, Spanovic, que estaba a solo seis cent\u00edmetros del oro, no mejor\u00f3 y se qued\u00f3, por tanto, sin medalla.<\/p>\n<p>Mihambo, en cambio, supo aprovechar su \u00faltima oportunidad para volar a los 7 metros justos y ponerse en cabeza, a la espera de Brume y Reese, pero ni la nigeriana (6.90 en el \u00faltimo) ni la estadounidense (6.84) mejoraron su registro ganador.<\/p>","protected":false},"excerpt":{"rendered":"<p>El noruego Karsten Warholm mejor\u00f3 su propia marca al regustrar 45.94 El atleta noruego Karsten Warholm bati\u00f3 su r\u00e9cord mundial de 400 metros con vallas con un tiempo de 45.94 segundos en un formidable duelo con el estadounidense Ray Benjamin, que termin\u00f3 segundo con 46.17. Se trata del segundo r\u00e9cord mundial que cae durante los [&hellip;]<\/p>","protected":false},"author":0,"featured_media":360151,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[31],"tags":[],"class_list":["post-165896","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/165896","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=165896"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/165896\/revisions"}],"predecessor-version":[{"id":360153,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/165896\/revisions\/360153"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/360151"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=165896"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=165896"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=165896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}