{"id":165769,"date":"2021-07-30T17:49:00","date_gmt":"2021-07-30T21:49:00","guid":{"rendered":"https:\/\/www.noticel.com\/ahora\/gobierno\/20210730\/gobernador-sobre-conflicto-en-muelles-tienen-que-ceder-por-el-bien-de-puerto-rico\/"},"modified":"2025-07-15T17:35:44","modified_gmt":"2025-07-15T17:35:44","slug":"gobernador-sobre-conflicto-en-muelles-tienen-que-ceder-por-el-bien-de-puerto-rico","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20210730\/gobernador-sobre-conflicto-en-muelles-tienen-que-ceder-por-el-bien-de-puerto-rico\/","title":{"rendered":"Gobernador sobre conflicto en muelles: \u201cTienen que ceder por el bien de Puerto Rico\u201d"},"content":{"rendered":"<h3>Pedro Pierluisi pidi\u00f3 que termine el paro.<\/h3>\n<p>El gobernador Pedro Rafael Pierluisi Urrutia dijo el viernes que las partes involucradas entre la empresa Luis Ayala Col\u00f3n, operador del Muelle de San Juan y la Uni\u00f3n de Trabajadores de los muelles \u2014International Longshoremen\u2019s Association (ILA Local 1740)\u2014, pues alrededor de 5,000 vagones est\u00e1n varados en los puertos.<\/p>\n<p>\u201cEs que ya estamos interviniendo. Eso es un conflicto obrero patronal en el sector privado entre una uni\u00f3n y la empresa Luis Ayala. Desde que nos enteramos del conflicto, el secretario del Trabajo y su equipo de mediaci\u00f3n ha estado interviniendo. Y ese conflicto se resuelve en la mesa de negociaci\u00f3n. Eso no se resuelve en la palestra p\u00fablica\u201d, dijo el gobernador a preguntas de la prensa.<\/p>\n<p>\u201cTienen que ceder en sus reclamos. Esto no es una cuesti\u00f3n de trancarse a la banda, tienen que ceder por el bien de Puerto Rico porque s\u00ed est\u00e1 teniendo un impacto, pero nuevamente, es una controversia innecesaria\u201d, a\u00f1adi\u00f3.<\/p>\n<p>As\u00ed las cosas, el mandatario solicit\u00f3 que culmine el paro.<\/p><div class=\"notic-content-middle\" id=\"notic-1276813519\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>\u201cYo lo que estoy pidiendo es que ya termine el paro, entonces, si queda algo por negociar que usen los buenos oficios del secretario del Trabajo para resolverlo. Pero que no contin\u00fae el paro, a pesar de que no hayan resuelto todas las controversias\u201d, sentenci\u00f3 Pierluisi Urrutia.<\/p>\n<p>Mencion\u00f3 que entre los reclamos que est\u00e1n en la mesa de negociaci\u00f3n, un 60 por ciento de ellas han sido resueltas, aunque no especific\u00f3 cu\u00e1les.<\/p>\n<p>La pasadas semanas, los camioneros llevaron a cabo sus manifestaciones por lo que la carga de los muelles se vio afectada, as\u00ed como el suministro de comida en supermercados, al igual que el suministro de combustible en todo el pa\u00eds.<\/p>","protected":false},"excerpt":{"rendered":"<p>Pedro Pierluisi pidi\u00f3 que termine el paro. El gobernador Pedro Rafael Pierluisi Urrutia dijo el viernes que las partes involucradas entre la empresa Luis Ayala Col\u00f3n, operador del Muelle de San Juan y la Uni\u00f3n de Trabajadores de los muelles \u2014International Longshoremen\u2019s Association (ILA Local 1740)\u2014, pues alrededor de 5,000 vagones est\u00e1n varados en los [&hellip;]<\/p>","protected":false},"author":0,"featured_media":361163,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[4,2],"tags":[],"class_list":["post-165769","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gobierno","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/165769","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=165769"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/165769\/revisions"}],"predecessor-version":[{"id":361167,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/165769\/revisions\/361167"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/361163"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=165769"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=165769"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=165769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}