{"id":165526,"date":"2021-07-25T09:18:00","date_gmt":"2021-07-25T13:18:00","guid":{"rendered":"https:\/\/www.noticel.com\/ahora\/top-stories\/20210725\/covid-19-salud-reporta-una-muerte-124-casos-confirmados-y-119-probables\/"},"modified":"2025-07-15T17:54:12","modified_gmt":"2025-07-15T17:54:12","slug":"covid-19-salud-reporta-una-muerte-124-casos-confirmados-y-119-probables","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20210725\/covid-19-salud-reporta-una-muerte-124-casos-confirmados-y-119-probables\/","title":{"rendered":"Covid-19: Salud reporta una muerte, 124 casos confirmados y 119 probables"},"content":{"rendered":"<h3>Mientras, 106 personas permanecen hospitalizadas<\/h3>\n<p>El Departamento de Salud, a trav\u00e9s de su informe diario de rastreo del COVID \u201319, revel\u00f3 que para hoy domingo los casos confirmados mediante prueba molecular alcanzan los 124 y se suma una muerte, lo que eleva el total de fallecidos a 2,568.<\/p>\n<p>En tanto, existen 119 casos probables luego de realizada una prueba de ant\u00edgenos. El total incluye casos con muestras tomadas del 09 de julio al 23 de julio de 2021.<\/p><div class=\"notic-content-middle\" id=\"notic-248655842\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>Actualmente, 106 personas se encuentran hospitalizadas a causa de la enfermedad, de los cuales 85 son adultos y 21 son menores.<\/p>\n<p>Mientras, se mantiene un aumento en el n\u00famero de personas vacunadas. Al momento, dos millones, 125 mil, 043 personas ya cuentan con al menos una de la dosis de la vacuna. Con la serie de dosis, hay un mill\u00f3n, 855 mil, 490 personas.<\/p>","protected":false},"excerpt":{"rendered":"<p>Mientras, 106 personas permanecen hospitalizadas El Departamento de Salud, a trav\u00e9s de su informe diario de rastreo del COVID \u201319, revel\u00f3 que para hoy domingo los casos confirmados mediante prueba molecular alcanzan los 124 y se suma una muerte, lo que eleva el total de fallecidos a 2,568. En tanto, existen 119 casos probables luego [&hellip;]<\/p>","protected":false},"author":0,"featured_media":362589,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-165526","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/165526","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=165526"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/165526\/revisions"}],"predecessor-version":[{"id":362590,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/165526\/revisions\/362590"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/362589"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=165526"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=165526"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=165526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}