{"id":164692,"date":"2021-07-07T15:15:00","date_gmt":"2021-07-07T19:15:00","guid":{"rendered":"https:\/\/www.noticel.com\/ahora\/politica\/top-stories\/20210707\/cee-certifica-a-ricardo-rossello-como-delegado-congresional\/"},"modified":"2025-07-15T19:10:31","modified_gmt":"2025-07-15T19:10:31","slug":"ricardo-rossello-ya-juramento-como-delegado-congresional-tras-certificacion-de-la-cee","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20210707\/ricardo-rossello-ya-juramento-como-delegado-congresional-tras-certificacion-de-la-cee\/","title":{"rendered":"Ricardo Rossell\u00f3 ya jurament\u00f3 como delegado congresional tras certificaci\u00f3n de la CEE"},"content":{"rendered":"<h3>Lo hizo en la oficina de la Administraci\u00f3n de Asuntos Federales de Puerto Rico en Washington DC.<\/h3>\n<p>El exgobernador Ricardo Rossell\u00f3 Nevares ya jurament\u00f3 como delegado congresional tras recibir la certificaci\u00f3n de la Comisi\u00f3n Estatal de Elecciones (CEE).<\/p>\n<p>La sencilla ceremonia, a la que asisti\u00f3 acompa\u00f1ado de su esposa, Beatriz Rossell\u00f3 y sus dos hijos, se llev\u00f3 a cabo a eso de las 4:50 p.m. en la oficina de la Administraci\u00f3n de Asuntos Federales de Puerto Rico en Washington D.C. donde le tom\u00f3 juramento una abogada notaria.<\/p>\n<p>Lo hizo en ingl\u00e9s, contrario a sus otros cuatro compa\u00f1eros delegados congresionales que juramentaron en Puerto Rico y en espa\u00f1ol.<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.facebook.com\/plugins\/video.php?height=350&#038;href=https%3A%2F%2Fwww.facebook.com%2Fnoticelpr%2Fvideos%2F330597951890132%2F&#038;show_text=false&#038;width=560&#038;t=0\" width=\"560\" height=\"350\" style=\"border:none;overflow:hidden\" scrolling=\"no\" frameborder=\"0\" allowfullscreen=\"true\" allow=\"autoplay; clipboard-write; encrypted-media; picture-in-picture; web-share\"><\/iframe><\/p>\n<p>La certificaci\u00f3n oficial ocurri\u00f3 al filo de las 3:00 p.m. luego de que Rossell\u00f3 Nevares present\u00f3 el formulario de radicaci\u00f3n de candidatura con una declaraci\u00f3n jurada dejando claro que no se present\u00f3 a la elecci\u00f3n especial como candidato sino que result\u00f3 ganador a trav\u00e9s del mecanismo de nominaci\u00f3n directa.<\/p>\n<p>Dicho documento cuenta con las firmas del presidente de la CEE, Francisco Rosado Colomer, el secretario del ente electoral, Rolando Cuevas y de la comisionada electoral del PNP, Vanessa Santo Domingo Cruz.<\/p>\n<p>Ayer, el Tribunal de Apelaciones orden\u00f3 a la CEE continuar con el proceso de certificaci\u00f3n mientras atiende el recurso legal de los abogados del PNP, Ram\u00f3n Rosario Cort\u00e9s y Francisco Gonz\u00e1lez Magaz,. Los letrados apelaron la sentencia que descalific\u00f3 a Rossell\u00f3 Nevares e impidi\u00f3 que la CEE lo certificara junto a los otros cinco miembros de la delegaci\u00f3n congresional, alegando que la jueza Rebecca de Le\u00f3n R\u00edos del Tribunal de San Juan, err\u00f3 en cinco ocasiones al intervenir en el pleito incoado por el comisionado del Proyecto Dignidad.<\/p><div class=\"notic-content-middle\" id=\"notic-1280221411\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>Justo cuando la CEE completaba el tr\u00e1mite de certificaci\u00f3n, el comisionado electoral del Proyecto Dignidad, Nelson Rosario Rodr\u00edguez, radicaba una petici\u00f3n de auxilio de jurisdicci\u00f3n ante el Tribunal de Apelaciones para detener el proceso.<\/p>\n<p>Explic\u00f3 a NotiCel que el ente electoral manejaba este asunto con una prisa inusitada a pesar de que la resoluci\u00f3n de ayer del Apelativo no ordenaba de forma directa expedir dicha certificaci\u00f3n y tampoco revocaba la sentencia que descalific\u00f3 a Rossell\u00f3 Nevares.<\/p>\n<p>\u00abLa Comisi\u00f3n no puede funcionar as\u00ed facinerosamente, cargando a una persona y violentando los derechos de las personas que yo represento\u00bb, afirm\u00f3 Rosario Rodr\u00edguez.<\/p>\n<p>Destac\u00f3 que la decisi\u00f3n del Apelativo era preliminar y que no atend\u00eda los m\u00e9ritos de la controversia. Se\u00f1al\u00f3 tambi\u00e9n que en el escenario de que la decisi\u00f3n final fuera ratificar la nulidad de la elecci\u00f3n del exgobernador, resultar\u00eda muy oneroso para la CEE puesto que tendr\u00eda que celebrar una elecci\u00f3n nueva.<\/p>\n<p>Al momento de radicar su recurso legal, Rosario Rodr\u00edguez no hab\u00eda evaluado el expediente, ni los documentos que permitieron a la CEE extender la certificaci\u00f3n a Rossell\u00f3 Nevares. Ten\u00eda cita a las 3:30 p.m. con el Secretario de la CEE para evaluar ese expediente y confirmar que -en efecto- Rossell\u00f3 Nevares cumpli\u00f3 con todos los requisitos para convertirse en delegado ante la C\u00e1mara de Representantes de Estados Unidos.<\/p>\n<p>Mira la certificaci\u00f3n aqu\u00ed.<\/p>","protected":false},"excerpt":{"rendered":"<p>Lo hizo en la oficina de la Administraci\u00f3n de Asuntos Federales de Puerto Rico en Washington DC. El exgobernador Ricardo Rossell\u00f3 Nevares ya jurament\u00f3 como delegado congresional tras recibir la certificaci\u00f3n de la Comisi\u00f3n Estatal de Elecciones (CEE). La sencilla ceremonia, a la que asisti\u00f3 acompa\u00f1ado de su esposa, Beatriz Rossell\u00f3 y sus dos hijos, [&hellip;]<\/p>","protected":false},"author":19,"featured_media":368751,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[7,2],"tags":[],"class_list":["post-164692","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/164692","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=164692"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/164692\/revisions"}],"predecessor-version":[{"id":368758,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/164692\/revisions\/368758"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/368751"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=164692"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=164692"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=164692"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}