{"id":163765,"date":"2021-06-18T14:35:00","date_gmt":"2021-06-18T18:35:00","guid":{"rendered":"https:\/\/www.noticel.com\/ahora\/legislatura\/20210618\/georgie-navarro-retira-medida-legislativa-sobre-credencial-digital\/"},"modified":"2025-07-15T20:48:57","modified_gmt":"2025-07-15T20:48:57","slug":"georgie-navarro-retira-medida-legislativa-sobre-credencial-digital","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20210618\/georgie-navarro-retira-medida-legislativa-sobre-credencial-digital\/","title":{"rendered":"Georgie Navarro retira medida legislativa sobre credencial digital"},"content":{"rendered":"<h3>El representante se\u00f1al\u00f3 que la medida gener\u00f3 confusi\u00f3n y tensi\u00f3n entre grupos conservadores que interpretaron err\u00f3neamente que la medida obliga al ciudadano a recibir la vacunaci\u00f3n del Covid-19.<\/h3>\n<p>El representante Georgie Navarro anunci\u00f3 el viernes, que luego de conversar con varios sectores del distrito representativo acord\u00f3 retirar el Proyecto de la C\u00e1mara 822.<\/p>\n<p>\u201cLa medida legislativa ten\u00eda como prop\u00f3sito facultar al Departamento de Salud de Puerto Rico a expedir una credencial digital a favor de toda persona que reciba la vacuna del Covid-19. La intenci\u00f3n era sustituir la tarjeta de vacunaci\u00f3n de papel por una digital. Este tipo de medida ha sido adoptada en estados como New York y California. Adem\u00e1s, ha sido adoptado en la Uni\u00f3n Europea y pa\u00edses como Argentina\u201d, dijo el legislador en comunicaci\u00f3n escrita.<\/p>\n<p>\u201cSomet\u00ed el Proyecto de la C\u00e1mara 822 para sustituir la tarjeta de vacunaci\u00f3n de papel por una digital. Sin embargo, sectores conservadores interpretaron la medida err\u00f3neamente y me han solicitado que retire la medida. Quiero facilitar el di\u00e1logo e iniciar un proceso educativo sobre la importancia de la vacunaci\u00f3n y c\u00f3mo debemos evitar el fraude. Por esa raz\u00f3n, decid\u00ed retirar el Proyecto de la C\u00e1mara 822 hasta que pueda culminar dicho di\u00e1logo y orientaci\u00f3n en torno a la medida\u201d, afirm\u00f3 el legislador.<\/p><div class=\"notic-content-middle\" id=\"notic-3097869636\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>Se\u00f1al\u00f3 que la medida gener\u00f3 confusi\u00f3n y tensi\u00f3n entre grupos conservadores del Distrito Representativo. Interpretaron err\u00f3neamente que la medida obliga al ciudadano a recibir la vacunaci\u00f3n del Covid-19. Seg\u00fan el representante, la medida tiene como prop\u00f3sito principal combatir el fraude con las tarjetas de vacunaci\u00f3n del Covid-19.<\/p>\n<p>A\u00f1adi\u00f3 que \u201cen los pr\u00f3ximos d\u00edas estar\u00e9 anunciando medidas adicionales para combatir el fraude con la vacunaci\u00f3n del Covid-19 y fomentar la vacunaci\u00f3n\u201d.<\/p>","protected":false},"excerpt":{"rendered":"<p>El representante se\u00f1al\u00f3 que la medida gener\u00f3 confusi\u00f3n y tensi\u00f3n entre grupos conservadores que interpretaron err\u00f3neamente que la medida obliga al ciudadano a recibir la vacunaci\u00f3n del Covid-19. El representante Georgie Navarro anunci\u00f3 el viernes, que luego de conversar con varios sectores del distrito representativo acord\u00f3 retirar el Proyecto de la C\u00e1mara 822. \u201cLa medida [&hellip;]<\/p>","protected":false},"author":0,"featured_media":376122,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[5,2],"tags":[],"class_list":["post-163765","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-legislatura","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/163765","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=163765"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/163765\/revisions"}],"predecessor-version":[{"id":376125,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/163765\/revisions\/376125"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/376122"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=163765"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=163765"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=163765"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}