{"id":163510,"date":"2021-06-14T09:18:00","date_gmt":"2021-06-14T13:18:00","guid":{"rendered":"https:\/\/www.noticel.com\/ahora\/top-stories\/20210614\/padres-de-ninos-que-sacaron-f-y-que-no-se-matriculen-en-clases-de-verano-podrian-ser-referidos-a\/"},"modified":"2025-07-15T21:09:04","modified_gmt":"2025-07-15T21:09:04","slug":"padres-de-ninos-que-sacaron-f-y-que-no-se-matriculen-en-clases-de-verano-podrian-ser-referidos-a","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20210614\/padres-de-ninos-que-sacaron-f-y-que-no-se-matriculen-en-clases-de-verano-podrian-ser-referidos-a\/","title":{"rendered":"Padres de ni\u00f1os que sacaron \u00bbF\u00bb y que no se matriculen en clases de verano podr\u00edan ser referidos a"},"content":{"rendered":"<h3>Aunque los cursos comenzaron hoy, el proceso de matr\u00edcula tard\u00eda se extender\u00e1 hasta ma\u00f1ana<\/h3>\n<p>El subsecretario del Departamento de Educaci\u00f3n (DE), H\u00e9ctor Joaqu\u00edn S\u00e1nchez \u00c1lvarez, dijo que aquellos padres de estudiantes que hayan fracasado en el pasado semestre escolar y no se hayan matriculado en los cursos de verano que arrancaron hoy, podr\u00edan ser referidos al Departamento de la Familia por negligencia.<\/p>\n<p>Unas 220 escuelas abrieron hoy para recibir a m\u00e1s 34,000 estudiantes del sistema p\u00fablico que preliminarmente tendr\u00edan que repetir el a\u00f1o escolar.<\/p>\n<p>Sin embargo, el proceso de matr\u00edcula tard\u00eda se extender\u00e1 hasta ma\u00f1ana, por lo que exhort\u00f3 a aquellos padres de estudiantes que todav\u00eda no se han registrado, a que acudan lo antes posible a matricularlos.<\/p>\n<p>\u201cEstamos dando un seguimiento directo para poder identificar a esos estudiantes que no han llegado, para decirle a mam\u00e1 y pap\u00e1 que entre hoy y ma\u00f1ana todav\u00eda tienen oportunidad de matricularse. Queremos que todos los estudiantes repongan esa \u2018F\u2019\u201d, coment\u00f3 S\u00e1nchez \u00c1lvarez en entrevista en \u201cEl Push de la Ma\u00f1ana\u201d de NotiCel.<\/p>\n<p>\u201cNuestros trabajadores sociales est\u00e1n documentando todo el proceso y estar\u00e1n refiriendo al Departamento de la Familia cualquier asunto que sea identificado como negligencia. Lo que no queremos son desertores escolares. Si tenemos que dar ex\u00e1menes de ubicaci\u00f3n, lo vamos a hacer, pero lo que queremos es que nuestros estudiantes est\u00e9n preparados\u201d, enfatiz\u00f3 el subsecretario del DE.<\/p>\n<blockquote class=\"instagram-media\" data-instgrm-captioned data-instgrm-permalink=\"https:\/\/www.instagram.com\/tv\/CQGeCRqnSrd\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"13\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:540px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\">\n<div style=\"padding:16px;\"> <a href=\"https:\/\/www.instagram.com\/tv\/CQGeCRqnSrd\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" background:#FFFFFF; line-height:0; padding:0 0; text-align:center; text-decoration:none; width:100%;\" target=\"_blank\"> <\/p>\n<div style=\" display: flex; flex-direction: row; align-items: center;\">\n<div style=\"background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\">\n<div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div>\n<div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div>\n<\/div>\n<\/div>\n<div style=\"padding: 19% 0;\"><\/div>\n<div style=\"display:block; height:50px; margin:0 auto 12px; width:50px;\"><svg width=\"50px\" height=\"50px\" viewbox=\"0 0 60 60\" version=\"1.1\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"https:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g transform=\"translate(-511.000000, -20.000000)\" fill=\"#000000\"><g><path d=\"M556.869,30.41 C554.814,30.41 553.148,32.076 553.148,34.131 C553.148,36.186 554.814,37.852 556.869,37.852 C558.924,37.852 560.59,36.186 560.59,34.131 C560.59,32.076 558.924,30.41 556.869,30.41 M541,60.657 C535.114,60.657 530.342,55.887 530.342,50 C530.342,44.114 535.114,39.342 541,39.342 C546.887,39.342 551.658,44.114 551.658,50 C551.658,55.887 546.887,60.657 541,60.657 M541,33.886 C532.1,33.886 524.886,41.1 524.886,50 C524.886,58.899 532.1,66.113 541,66.113 C549.9,66.113 557.115,58.899 557.115,50 C557.115,41.1 549.9,33.886 541,33.886 M565.378,62.101 C565.244,65.022 564.756,66.606 564.346,67.663 C563.803,69.06 563.154,70.057 562.106,71.106 C561.058,72.155 560.06,72.803 558.662,73.347 C557.607,73.757 556.021,74.244 553.102,74.378 C549.944,74.521 548.997,74.552 541,74.552 C533.003,74.552 532.056,74.521 528.898,74.378 C525.979,74.244 524.393,73.757 523.338,73.347 C521.94,72.803 520.942,72.155 519.894,71.106 C518.846,70.057 518.197,69.06 517.654,67.663 C517.244,66.606 516.755,65.022 516.623,62.101 C516.479,58.943 516.448,57.996 516.448,50 C516.448,42.003 516.479,41.056 516.623,37.899 C516.755,34.978 517.244,33.391 517.654,32.338 C518.197,30.938 518.846,29.942 519.894,28.894 C520.942,27.846 521.94,27.196 523.338,26.654 C524.393,26.244 525.979,25.756 528.898,25.623 C532.057,25.479 533.004,25.448 541,25.448 C548.997,25.448 549.943,25.479 553.102,25.623 C556.021,25.756 557.607,26.244 558.662,26.654 C560.06,27.196 561.058,27.846 562.106,28.894 C563.154,29.942 563.803,30.938 564.346,32.338 C564.756,33.391 565.244,34.978 565.378,37.899 C565.522,41.056 565.552,42.003 565.552,50 C565.552,57.996 565.522,58.943 565.378,62.101 M570.82,37.631 C570.674,34.438 570.167,32.258 569.425,30.349 C568.659,28.377 567.633,26.702 565.965,25.035 C564.297,23.368 562.623,22.342 560.652,21.575 C558.743,20.834 556.562,20.326 553.369,20.18 C550.169,20.033 549.148,20 541,20 C532.853,20 531.831,20.033 528.631,20.18 C525.438,20.326 523.257,20.834 521.349,21.575 C519.376,22.342 517.703,23.368 516.035,25.035 C514.368,26.702 513.342,28.377 512.574,30.349 C511.834,32.258 511.326,34.438 511.181,37.631 C511.035,40.831 511,41.851 511,50 C511,58.147 511.035,59.17 511.181,62.369 C511.326,65.562 511.834,67.743 512.574,69.651 C513.342,71.625 514.368,73.296 516.035,74.965 C517.703,76.634 519.376,77.658 521.349,78.425 C523.257,79.167 525.438,79.673 528.631,79.82 C531.831,79.965 532.853,80.001 541,80.001 C549.148,80.001 550.169,79.965 553.369,79.82 C556.562,79.673 558.743,79.167 560.652,78.425 C562.623,77.658 564.297,76.634 565.965,74.965 C567.633,73.296 568.659,71.625 569.425,69.651 C570.167,67.743 570.674,65.562 570.82,62.369 C570.966,59.17 571,58.147 571,50 C571,41.851 570.966,40.831 570.82,37.631\"><\/path><\/g><\/g><\/g><\/svg><\/div>\n<div style=\"padding-top: 8px;\">\n<div style=\" color:#3897f0; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:550; line-height:18px;\"> View this post on Instagram<\/div>\n<\/div>\n<div style=\"padding: 12.5% 0;\"><\/div>\n<div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\">\n<div>\n<div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div>\n<div style=\"background-color: #F4F4F4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div>\n<div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div>\n<\/div>\n<div style=\"margin-left: 8px;\">\n<div style=\" background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div>\n<div style=\" width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg)\"><\/div>\n<\/div>\n<div style=\"margin-left: auto;\">\n<div style=\" width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div>\n<div style=\" background-color: #F4F4F4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div>\n<div style=\" width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div>\n<\/div>\n<\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\">\n<div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div>\n<div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div>\n<\/div>\n<p><\/a><\/p>\n<p style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; line-height:17px; margin-bottom:0; margin-top:8px; overflow:hidden; padding:8px 0 7px; text-align:center; text-overflow:ellipsis; white-space:nowrap;\"><a href=\"https:\/\/www.instagram.com\/tv\/CQGeCRqnSrd\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:normal; line-height:17px; text-decoration:none;\" target=\"_blank\">A post shared by NotiCel (@noticelpr)<\/a><\/p>\n<\/div>\n<\/blockquote>\n<p> <script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><\/p>\n<p>Contrario al a\u00f1o anterior, el Departamento de Educaci\u00f3n decidi\u00f3 que los estudiantes no pasar\u00edan de grado autom\u00e1ticamente y que tendr\u00edan que ganarse el pase con las notas que se requieren. De esos 34,429 estudiantes, seg\u00fan dijo a NotiCel el secretario interino, Eliezer Ramos Par\u00e9s, m\u00e1s de 13,000 obtuvieron calificaci\u00f3n de F en todas las materias, seg\u00fan el funcionario, por muchas razones incluyendo dejadez.<\/p><div class=\"notic-content-middle\" id=\"notic-3957407794\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-970&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1.jpg 970w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-300x77.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-768x198.jpg 768w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-18x5.jpg 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"250\"   \/><\/a><\/div>\n<p>S\u00e1nchez \u00c1lvarez confirm\u00f3 que se trata de 13, 833 estudiantes que sacaron \u201cF\u201d en la mayor\u00eda de las clases en el pasado semestre escolar.<\/p>\n<p>T\u00edpicamente, el porciento de estudiantes que no pasan de grado ronda el 4%. En este ocasi\u00f3n se trata de un 9%.<\/p>\n<p>\u201cEstamos d\u00e1ndole un trato especial a todos esos estudiantes que fracasaron totalmente en cuatro o m\u00e1s clases. B\u00e1sicamente queremos ayudarle a que regresen a la escuela. Que entiendan que en la escuela tenemos oportunidades para transformar su vida, para desarrollar sus destrezas acad\u00e9micas e insertarlos en el mundo laboral exitosamente\u201d, sostuvo S\u00e1nchez \u00c1lvarez.<\/p>\n<p>El Verano Educativo 2021 busca ser herramienta para que los estudiantes puedan mejorar calificaciones, atender el rezago acad\u00e9mico y reponer hasta cuatro clases.<\/p>\n<p>La regi\u00f3n educativa de Bayam\u00f3n tiene la cifra m\u00e1s alta con unos 6,902 estudiantes; Mayag\u00fcez unos 6,874; San Juan unos 5,739; Humacao unos 3,889; Ponce tiene 3,887; Arecibo tiene 3,804; y Caguas tiene 3,334, seg\u00fan se inform\u00f3.<\/p>\n<p>los estudiantes recibir\u00e1n los cursos de manera presencial, excepto en los pueblos de Gu\u00e1nica, Guayanilla, Pe\u00f1uelas y Santa Isabel que lo har\u00e1n, otra vez m\u00e1s, de manera virtual. El problema educativo en esa zona afectada por los terremotos, es serio. El Departamento de Educaci\u00f3n admiti\u00f3 que a\u00fan no ha podido identificar alguna escuela que cumpliera, en su totalidad, con las evaluaciones para recibir a los estudiantes de manera presencial.<\/p>\n<p>El Verano Educativo tendr\u00e1 una duraci\u00f3n de 30 d\u00edas lectivos en un horario desde las 8:00 a.m. hasta las 3:00 p.m. Todas las escuelas abiertas se regir\u00e1n por los protocolos que ha impuesto el Departamento de Salud y tendr\u00e1n equipos de limpieza, desinfecci\u00f3n, mascarillas y term\u00f3metros. Igualmente, se autoriz\u00f3 la activaci\u00f3n de enfermeras, sic\u00f3logos y guardias de seguridad para estas escuelas.<\/p>\n<p>Adem\u00e1s, se mantendr\u00e1 el servicio de desayuno y almuerzo en los comedores escolares para todos los estudiantes que participar\u00e1n del programa de verano.<\/p>","protected":false},"excerpt":{"rendered":"<p>Aunque los cursos comenzaron hoy, el proceso de matr\u00edcula tard\u00eda se extender\u00e1 hasta ma\u00f1ana El subsecretario del Departamento de Educaci\u00f3n (DE), H\u00e9ctor Joaqu\u00edn S\u00e1nchez \u00c1lvarez, dijo que aquellos padres de estudiantes que hayan fracasado en el pasado semestre escolar y no se hayan matriculado en los cursos de verano que arrancaron hoy, podr\u00edan ser referidos [&hellip;]<\/p>","protected":false},"author":0,"featured_media":377900,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-163510","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/163510","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=163510"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/163510\/revisions"}],"predecessor-version":[{"id":377904,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/163510\/revisions\/377904"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/377900"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=163510"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=163510"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=163510"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}