{"id":162824,"date":"2021-05-29T10:57:00","date_gmt":"2021-05-29T14:57:00","guid":{"rendered":"https:\/\/www.noticel.com\/ahora\/la-calle\/20210529\/conceden-ultimo-termino-a-condominios-para-que-entreguen-plan-de-emergencias\/"},"modified":"2025-07-15T22:12:56","modified_gmt":"2025-07-15T22:12:56","slug":"conceden-ultimo-termino-a-condominios-para-que-entreguen-plan-de-emergencias","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20210529\/conceden-ultimo-termino-a-condominios-para-que-entreguen-plan-de-emergencias\/","title":{"rendered":"Conceden \u00faltimo t\u00e9rmino a condominios para que entreguen plan de emergencias"},"content":{"rendered":"<h3>Son muchos los condominios que faltan por cumplir con ese requisito, seg\u00fan DACO<\/h3>\n<p>El Departamento de Asuntos del Consumidor (DACO) concedi\u00f3 hasta el martes 8 de junio como \u00faltimo plazo para que los condominios sujetos al R\u00e9gimen de Propiedad Horizontal sometan y divulguen toda aquella informaci\u00f3n que la Ley de Condominios les exige proveer, tanto a los titulares, como a ciertas agencias de Gobierno, en torno a c\u00f3mo prev\u00e9n atender situaciones de emergencia.<\/p>\n<p>\u201cLos planes de emergencia en los condominios son clave para que, ante cualquier eventualidad, las comunidades de titulares est\u00e9n debidamente protegidas. Sabemos que la situaci\u00f3n con la pandemia ha atrasado mucho la toma de decisiones; pero, a d\u00edas de comenzar la temporada de huracanes es imperante contar con esa informaci\u00f3n. Por eso, estamos concediendo un \u00faltimo plazo para cumplir con los requisitos de ley\u201d, asever\u00f3 Edan Rivera Rodr\u00edguez, Secretario del DACO.<\/p>\n<p>El funcionario explic\u00f3 que, respecto a los planes de emergencia, la Ley de Condominios exige dos aspectos esenciales; primero, la aprobaci\u00f3n anual de un plan de desastres y emergencias que debe ser notificado de manera eficaz a todos los titulares; y segundo, la elaboraci\u00f3n de un plan de racionamiento de agua y de electricidad en situaciones de emergencia que debe notificarse al DACO, junto con informaci\u00f3n de contacto.<\/p>\n<p>\u201cLa idea de notificar el plan de emergencias a todos los titulares es que estos tengan la oportunidad de revisarlo en detalle y as\u00ed sepan c\u00f3mo prepararse o c\u00f3mo actuar de tener lugar alguna eventualidad; mientras que el plan de racionamiento de agua y electricidad debe cumplir con los criterios establecidos por el DACO v\u00eda reglamento, a fin de que atienda unos requisitos m\u00ednimos de prevenci\u00f3n. Es exactamente esto lo que estamos advirtiendo a los condominios que cumplan, a m\u00e1s tardar, el 8 de junio\u201d, sentenci\u00f3 Rivera.<\/p><div class=\"notic-content-middle\" id=\"notic-4219627612\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-728&#215;90\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1.jpg 728w, https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1-300x37.jpg 300w, https:\/\/cdn.noticel.com\/2026\/07\/30095222\/Acodese-Adaptaciones-Noticel-728x90-1-18x2.jpg 18w\" sizes=\"(max-width: 728px) 100vw, 728px\" width=\"728\" height=\"90\"   \/><\/a><\/div>\n<p>El Secretario expres\u00f3 que, al momento, son muchos los condominios que faltan por cumplir con disposiciones de la Ley de Condominios que obligan, adem\u00e1s, a proveer informaci\u00f3n de contacto en situaciones de emergencia.<\/p>\n<p>\u201cEl incumplimiento nos llev\u00f3 a emitir una Orden, por medio de la cual les estamos dando este \u00faltimo plazo para que cumplan con tales directrices\u201d, indic\u00f3 el funcionario.<\/p>\n<p>\u201cSiempre la prevenci\u00f3n va a ser la mejor estrategia. Es por ello que exhortamos a aquellos condominios que a\u00fan no hayan elaborado sus planes, o que no hubiesen informado de los mismos a los titulares y a todas las agencias correspondientes, que lo hagan de forma inmediata\u201d, puntualiz\u00f3 Rivera.<\/p>","protected":false},"excerpt":{"rendered":"<p>Son muchos los condominios que faltan por cumplir con ese requisito, seg\u00fan DACO El Departamento de Asuntos del Consumidor (DACO) concedi\u00f3 hasta el martes 8 de junio como \u00faltimo plazo para que los condominios sujetos al R\u00e9gimen de Propiedad Horizontal sometan y divulguen toda aquella informaci\u00f3n que la Ley de Condominios les exige proveer, tanto [&hellip;]<\/p>","protected":false},"author":0,"featured_media":382660,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12,2],"tags":[],"class_list":["post-162824","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-calle","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/162824","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=162824"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/162824\/revisions"}],"predecessor-version":[{"id":382667,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/162824\/revisions\/382667"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/382660"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=162824"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=162824"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=162824"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}