{"id":15859,"date":"2017-06-27T00:00:00","date_gmt":"2017-06-27T04:00:00","guid":{"rendered":"http:\/\/www.noticel.com\/la-calle\/20170627\/madrugada-de-arrestos-federales-por-fraude-al-seguro-social\/"},"modified":"2025-07-16T22:07:45","modified_gmt":"2025-07-16T22:07:45","slug":"madrugada-de-arrestos-federales-por-fraude-al-seguro-social","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/la-calle\/20170627\/madrugada-de-arrestos-federales-por-fraude-al-seguro-social\/","title":{"rendered":"Madrugada de arrestos federales por fraude al Seguro Social"},"content":{"rendered":"<p>Unas trece personas han sido arrestadas en la madrugada de hoy, martes, por el Negociado Federal de Investigaciones (FBI por sus siglas en Ingles) por un aparente esquema de fraude al Sistema de Seguro Social.<\/p>\n<p>Seg\u00fan explic\u00f3 Manuel Rivera, portavoz de la oficina del Seguro Social en Puerto Rico, los arrestos se efectuaron a personas que aludieron a tener incapacidad para solicitar el Seguro Social.<\/p>\n<p>&#8216;[Los arrestos] son a personas que solicitan el Seguro Social por incapacidad y siguen trabajando o tienen negocios y siguen trabajando en sus negocios&#8217;, indic\u00f3 Rivera entrevistado por WKAQ.<\/p>\n<p>No obstante, a pesar de que previo a la otorgaci\u00f3n del Seguro Social, un m\u00e9dico debe certificar la incapacidad de la persona que la alega, en esta ocasi\u00f3n, Rivera estableci\u00f3 que no se investiga ning\u00fan m\u00e9dico particular como parte de estos 13 arrestos.<\/p><div class=\"notic-content-middle\" id=\"notic-3908390120\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>Los 13 arrestados corresponden, seg\u00fan remit\u00f3 la jefa defiscal\u00eda federal, Rosa Emilia Rodr\u00edguez en un comunicado de prensa, a Damaris Marrero Santiago e Isaias Diaz Torres, quienes recibieron un pago por 254,100.90 d\u00f3lares; Mariluz Rodr\u00edguez Rodr\u00edguez y Juan Rodr\u00edguez Miranda, con un pago de 82,700.90 d\u00f3lares; Roberto Padilla y Ednali Ramirez Maldonado, con un pao de 317,083.40 d\u00f3lares; Nancy Serrano Pic\u00f3n, con un pago de 130,493.20 d\u00f3lares; Edwin Maldonado Burgos y Consuelo Nu\u00f1ez Serrano, quienes recibieron 72,235.30 d\u00f3lares.<\/p>\n<p>Adem\u00e1s de Elson Fern\u00e1ndez, que recibi\u00f3 77,647.50 d\u00f3lares; Arnaldo Ramos Martir, que recibi\u00f3 un pago de 142,096.40 d\u00f3lares; Minerva Carr Rivera, con 311,976.10 d\u00f3lares y Luis \u00c1lvarez Ramos, alias. &#8216;Wichy&#8217;, que recibi\u00f3 un pago de 56,207.20 d\u00f3lares.<\/p>\n<p>Estas personas arrestadas ubican en los municipios de Arecibo, Humacao, Ponce, Caguas y Orocovis.<\/p>\n<p>&#8216;El fraude no est\u00e1 tolerado en el Seguro Social&#8217;, cerr\u00f3 diciendo Rivera a la vez que indic\u00f3 que todav\u00eda est\u00e1n en el proceso de investigaci\u00f3n.<\/p>","protected":false},"excerpt":{"rendered":"<p>Unas trece personas han sido arrestadas en la madrugada de hoy, martes, por el Negociado Federal de Investigaciones (FBI por sus siglas en Ingles) por un aparente esquema de fraude al Sistema de Seguro Social. Seg\u00fan explic\u00f3 Manuel Rivera, portavoz de la oficina del Seguro Social en Puerto Rico, los arrestos se efectuaron a personas [&hellip;]<\/p>","protected":false},"author":0,"featured_media":477494,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-15859","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-calle"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/15859","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=15859"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/15859\/revisions"}],"predecessor-version":[{"id":477495,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/15859\/revisions\/477495"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/477494"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=15859"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=15859"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=15859"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}