{"id":158573,"date":"2021-03-08T16:17:00","date_gmt":"2021-03-08T20:17:00","guid":{"rendered":"https:\/\/www.noticel.com\/mundo\/20210308\/el-supremo-rechaza-una-demanda-de-trump-y-acaba-su-batalla-contra-las-elecciones\/"},"modified":"2025-07-16T05:44:24","modified_gmt":"2025-07-16T05:44:24","slug":"el-supremo-rechaza-una-demanda-de-trump-y-acaba-su-batalla-contra-las-elecciones","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/mundo\/20210308\/el-supremo-rechaza-una-demanda-de-trump-y-acaba-su-batalla-contra-las-elecciones\/","title":{"rendered":"El Supremo rechaza una demanda de Trump y acaba su batalla contra las elecciones"},"content":{"rendered":"<h3>El rechazo fue de forma un\u00e1nime al pleito que el expresidente present\u00f3 contra los resultados de la votaci\u00f3n en Wisconsin.<\/h3>\n<p>WASHINGTON &#8211; El Tribunal Supremo de EE.UU. rechaz\u00f3 este lunes de forma un\u00e1nime una demanda que el ahora expresidente Donald Trump present\u00f3 contra los resultados de la votaci\u00f3n en Wisconsin, uno de los estados claves en los comicios de noviembre por la Casa Blanca, con lo que puso punto final a la cruzada del republicano contra ese proceso.<\/p>\n<p>En una orden emitida por el m\u00e1ximo tribunal, los nueve magistrados denegaron, sin precisar la causa, la solicitud del exgobernante de que declararan \u00abinconstitucional y nula\u00bb la elecci\u00f3n de Wisconsin y que designaran electores para una nueva votaci\u00f3n.<\/p>\n<p>Medios locales indicaron que la negativa del Supremo a la apelaci\u00f3n de Trump significa que menos de cuatro jueces aceptaron escuchar su caso.<\/p>\n<p>El Supremo estadounidense est\u00e1 integrado por seis magistrados conservadores -tres de ellos nombrados por el expresidente republicano- y tres progresistas.<\/p><div class=\"notic-content-middle\" id=\"notic-4113757804\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094423\/Acodese-Adaptaciones-Noticel-300x250-1-14x12.jpg 14w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"250\"   \/><\/a><\/div>\n<p>Trump, quien perdi\u00f3 por alrededor de 20.000 votos la elecci\u00f3n en ese estado frente al actual gobernante, Joe Biden, aleg\u00f3 que la Comisi\u00f3n Electoral de Wisconsin y los funcionarios locales violaron la Constituci\u00f3n al permitir la implementaci\u00f3n del voto ausente, que tom\u00f3 fuerza en la elecci\u00f3n de noviembre pasado debido a la pandemia del coronavirus.<\/p>\n<p>El entonces jefe de Estado argument\u00f3 que se implement\u00f3 el voto ausente \u00absin tener en cuenta el mandato expl\u00edcito de la Legislatura de Wisconsin\u00bb de que ese mecanismo debe ser \u00abcuidadosamente regulado\u00bb.<\/p>\n<p>Y en una moci\u00f3n para que se acelerara la consideraci\u00f3n de su pedido, Trump indic\u00f3 que, adem\u00e1s de solicitar que se anulara la elecci\u00f3n en Wisconsin, estaba pendiente un recurso similar ante un tribunal de Pensilvania y que emprender\u00eda una acci\u00f3n legal en Georgia, con el fin de impugnar los 46 votos que conced\u00edan esos estados para \u00abcambiar el resultado\u00bb de la votaci\u00f3n en el Colegio Electoral, que tuvo lugar el 14 de diciembre pasado.<\/p>\n<p>Pese a los intentos del l\u00edder republicano, Biden jur\u00f3 al cargo el pasado 20 de enero en una ceremonia que transcurri\u00f3 en medio de un fuerte dispositivo de seguridad, luego de que seguidores de Trump asaltaran 14 d\u00edas antes el Capitolio en un intento por detener la sesi\u00f3n conjunta del Congreso encabezada por el entonces vicepresidente, Mike Pence, para confirmar la victoria electoral del candidato dem\u00f3crata.<\/p>","protected":false},"excerpt":{"rendered":"<p>El rechazo fue de forma un\u00e1nime al pleito que el expresidente present\u00f3 contra los resultados de la votaci\u00f3n en Wisconsin. WASHINGTON &#8211; El Tribunal Supremo de EE.UU. rechaz\u00f3 este lunes de forma un\u00e1nime una demanda que el ahora expresidente Donald Trump present\u00f3 contra los resultados de la votaci\u00f3n en Wisconsin, uno de los estados claves [&hellip;]<\/p>","protected":false},"author":0,"featured_media":413803,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-158573","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/158573","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=158573"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/158573\/revisions"}],"predecessor-version":[{"id":413804,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/158573\/revisions\/413804"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/413803"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=158573"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=158573"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=158573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}