{"id":158363,"date":"2021-03-03T21:38:00","date_gmt":"2021-03-04T01:38:00","guid":{"rendered":"https:\/\/www.noticel.com\/mundo\/20210303\/la-violencia-policial-en-ee-uu-30-anos-despues-de-la-paliza-a-rodney-king\/"},"modified":"2025-07-16T06:01:52","modified_gmt":"2025-07-16T06:01:52","slug":"la-violencia-policial-en-ee-uu-30-anos-despues-de-la-paliza-a-rodney-king","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/mundo\/20210303\/la-violencia-policial-en-ee-uu-30-anos-despues-de-la-paliza-a-rodney-king\/","title":{"rendered":"La violencia policial en EE.UU., 30 a\u00f1os despu\u00e9s de la paliza a Rodney King"},"content":{"rendered":"<h3>Ese episodio del 3 de marzo de 1991 dio la vuelta al mundo despu\u00e9s de ser filmado por un aficionado que ten\u00eda casualmente su videoc\u00e1mara en ese momento.<\/h3>\n<p>LOS \u00c1NGELES &#8211; Cuando se cumplen 30 a\u00f1os de la brutal paliza a manos de la Polic\u00eda que recibi\u00f3 el afroamericano Rodney King en Los \u00c1ngeles, Estados Unidos sigue enfrentando un problema \u201csist\u00e9mico\u201d que deja a las minor\u00edas raciales desprotegidas frente a la violencia desmedida de las autoridades.<\/p>\n<p>Ese episodio del 3 de marzo de 1991 dio la vuelta al mundo despu\u00e9s de ser filmado por un aficionado que ten\u00eda casualmente su videoc\u00e1mara en ese momento, registrando todos los golpes que recibi\u00f3 King estando completamente estirado en el suelo, sin oponer resistencia.<\/p>\n<p>Tres d\u00e9cadas despu\u00e9s, parte de la Polic\u00eda en EE.UU. sigue un \u00abpatr\u00f3n\u00bb en su manera de \u00abc\u00f3mo se acerca a los afroamericanos\u00bb, un colectivo que ha sido \u00abcriminalizado\u00bb desde la fundaci\u00f3n del pa\u00eds, dijo a Efe \u00abBaba\u00bb Akili, uno de los dirigentes de la organizaci\u00f3n Black Lives Matter (\u00abLas Vidas Negras Importan\u00bb) en Los \u00c1ngeles.<\/p>\n<p>\u00abSent\u00ed indignaci\u00f3n, disgusto e ira. Al igual que la indignaci\u00f3n, el disgusto y la ira que sent\u00ed con el asesinato de George Floyd\u00bb, indic\u00f3 Akili, comparando la situaci\u00f3n actual con la de hace 30 a\u00f1os.<\/p>\n<p>\u00abSI RODNEY KING HUBIERA SIDO BLANCO&#8230;\u00bb<\/p>\n<p>\u00abSi Rodney King hubiera sido blanco, nunca lo hubieran hecho y nunca lo hubieran sacado de su veh\u00edculo para golpearlo por exceso de velocidad. Es posible que lo hubieran multado&#8230; Y eso es un patr\u00f3n, un ejemplo cl\u00e1sico de c\u00f3mo el Departamento de Polic\u00eda de Los \u00c1ngeles (LAPD, en sus siglas en ingl\u00e9s) se acerca a los negros\u00bb, reflexion\u00f3 Akili, con la bandera panafricana de fondo, en su casa.<\/p>\n<p>\u00abY todo el mundo en Los \u00c1ngeles y en el pa\u00eds sabe eso\u00bb, agreg\u00f3.<\/p>\n<p>Akili, que demand\u00f3 en 2017 al LAPD por \u00abuso excesivo de fuerza\u00bb y por haber sido detenido \u00aberr\u00f3neamente\u00bb, consider\u00f3 que este tipo de abusos suceden porque a los polic\u00edas en EE.UU. se les ense\u00f1a a \u00abcontrolar y reprimir\u00bb.<\/p>\n<p>\u00abLes ense\u00f1an a controlar la amenaza y a reprimir el peligro. Y como nos ven, a los negros, como criminales, pues as\u00ed nos tratan\u00bb, apunt\u00f3 el activista sexagenario.<\/p>\n<p>Con esa idea coincidi\u00f3 y fue m\u00e1s all\u00e1 la vicepresidenta del grupo Race Forward (\u00abRaza hacia adelante\u00bb), Julie Nelson, que explic\u00f3 en declaraciones a Efe que es \u00abimportante recordar que este pa\u00eds fue fundado por supremacistas blancos que quitaron las tierras a los nativos americanos\u00bb.<\/p>\n<p>\u00abEsta es la realidad de los \u00faltimos 30 a\u00f1os y de los \u00faltimos dos siglos, desde nuestra fundaci\u00f3n. Esta es nuestra historia y hay supremacismo blanco en todas las p\u00e1ginas\u00bb, subray\u00f3 Nelson.<\/p>\n<p>CAMBIAR LA POLIC\u00cdA DESDE DENTRO<\/p>\n<p>Quien ha visto centenares de agresiones de este tipo en los \u00faltimos 35 a\u00f1os ha sido el abogado de derechos civiles James DeSimone, cuyo primer caso fue el de representar a personas que hab\u00edan sido arrestadas en la Universidad de California en Los \u00c1ngeles (UCLA, en sus siglas en ingl\u00e9s) durante las protestas contra el apartheid.<\/p>\n<p>En la \u00e9poca en la que King fue vapuleado por los agentes, DeSimone record\u00f3 en una entrevista con Efe que \u00abrecib\u00eda llamadas de personas que hab\u00edan sido golpeadas por la Polic\u00eda y sab\u00eda que ser\u00eda un caso muy dif\u00edcil de probar si no hab\u00eda testigos porque la gente no andaba con c\u00e1maras de video en la mano como ahora\u00bb.<\/p>\n<p>La presencia de dispositivos m\u00f3viles, seg\u00fan el experto, le ayuda posteriormente a defender a sus clientes en el juzgado, pero para \u00e9l todav\u00eda existe un problema \u00absist\u00e9mico\u00bb en los Departamentos de Polic\u00eda: las escaladas de violencia por parte de los agentes de la ley.<\/p>\n<p>\u00abEn muchos casos son los agentes quienes agravan la situaci\u00f3n y provocan la violencia y eso tiene que cambiar ya\u00bb, defendi\u00f3.<\/p>\n<p>Una \u00abreforma\u00bb desde dentro de los departamentos es lo que pidi\u00f3 la presidenta de la International Society of Black Latinos, Juanita Palacios-Sims, para evitar que las minor\u00edas contin\u00faen sufriendo.<\/p>\n<p>\u00abHay m\u00e1s buenos polic\u00edas que malos, (&#8230;) pero rezo cada d\u00eda por mi marido, mis hermanos, mis sobrinos, porque nunca sabes lo que puede pasar\u00bb, dijo a Efe emocionada.<\/p>\n<p>AGREDIDA Y ENJAULADA<\/p>\n<p>Una de las clientes de DeSimone, Laura Montilla, vivi\u00f3 esta violencia desproporcionada tras ser detenida cuando se manifestaba \u00abpac\u00edficamente\u00bb en julio pasado en Los \u00c1ngeles por la violencia policial contra las minor\u00edas.<\/p>\n<p>\u201cEstaba esposada contra la pared, y esta se\u00f1ora (agente de polic\u00eda) vino hacia m\u00ed, me golpe\u00f3 los tobillos y agarr\u00f3 mi vagina y mis pechos en dos ocasiones, pese a que todo el tiempo estaba vigilada por varios polic\u00edas y era imposible que tuviese algo en mi posesi\u00f3n\u201d, narr\u00f3 a Efe Montilla, de 22 a\u00f1os, con la voz entrecortada.<\/p>\n<p>Posteriormente, Montilla fue trasladada a un autob\u00fas y encerrada en una jaula durante cinco horas con otra decena de personas, \u201ctan apretada\u201d que no pod\u00eda ni moverse, seg\u00fan la demanda que present\u00f3 contra el LAPD.<\/p>\n<p>Estos violentos episodios, junto a los asesinatos a manos de la Polic\u00eda en EE.UU. de los afroamericanos Rayshard Brooks, Daniel Prude, George Floyd y Breonna Taylor, todos en 2020, dibujan una realidad que \u00abno ha avanzado\u00bb, seg\u00fan los expertos, desde la paliza a Rodney King en 1991.<\/p>","protected":false},"excerpt":{"rendered":"<p>Ese episodio del 3 de marzo de 1991 dio la vuelta al mundo despu\u00e9s de ser filmado por un aficionado que ten\u00eda casualmente su videoc\u00e1mara en ese momento. LOS \u00c1NGELES &#8211; Cuando se cumplen 30 a\u00f1os de la brutal paliza a manos de la Polic\u00eda que recibi\u00f3 el afroamericano Rodney King en Los \u00c1ngeles, Estados [&hellip;]<\/p>","protected":false},"author":0,"featured_media":414871,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-158363","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/158363","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=158363"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/158363\/revisions"}],"predecessor-version":[{"id":414874,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/158363\/revisions\/414874"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/414871"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=158363"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=158363"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=158363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}