{"id":156274,"date":"2021-01-22T05:45:00","date_gmt":"2021-01-22T09:45:00","guid":{"rendered":"https:\/\/www.noticel.com\/?post_type=article&#038;p=156274"},"modified":"2025-07-16T09:25:04","modified_gmt":"2025-07-16T09:25:04","slug":"sin-fecha-la-declaracion-de-un-estado-de-emergencia-por-violencia-de-genero","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20210122\/sin-fecha-la-declaracion-de-un-estado-de-emergencia-por-violencia-de-genero\/","title":{"rendered":"Sin fecha la declaraci\u00f3n de un estado de emergencia por violencia de g\u00e9nero"},"content":{"rendered":"<h3>La secretaria de la Gobernaci\u00f3n, Noelia Garc\u00eda Bardales, se\u00f1al\u00f3 que el Ejecutivo toma su tiempo porque \u201cno va a ser algo que se haga para salir del paso\u201d.<\/h3>\n<p>A tres semanas de plantar pie en La Fortaleza, el gobernador Pedro Pierluisi Urrutia todav\u00eda no ha decretado un estado de emergencia por violencia de g\u00e9nero, aunque ya emiti\u00f3 12 \u00f3rdenes ejecutivas para atender otros asuntos.<\/p>\n<p>El martes, luego de que las autoridades confirmaran que el marido de Angie Noem\u00ed Gonz\u00e1lez Santos la asesin\u00f3,  el Mandatario reconoci\u00f3 -a trav\u00e9s de sus redes sociales- \u201cque estamos en una emergencia de violencia de g\u00e9nero y vamos a implementar una estrategia abarcadora para manejar esta crisis\u201d.<\/p>\n<p>Pero no ofreci\u00f3 una fecha para la presentaci\u00f3n de su propuesta para combatir ese flagelo, pese a que se trata de una promesa de campa\u00f1a.<\/p>\n<p>\u00bfA qu\u00e9 se debe la tardanza?<\/p>\n<p>La secretaria de la Gobernaci\u00f3n, Noelia Garc\u00eda Bardales, asegur\u00f3 que el Gobernador y su equipo de trabajo toman su tiempo para cincelar una propuesta que vendr\u00e1 acompa\u00f1ada con las partidas de presupuesto para su puesta en vigor.<\/p>\n<p>\u201cNo va a ser algo que se haga para salir del paso. Es algo concertado. Tiene que ser una estrategia contundente y est\u00e1 en proceso de identificarse la estrategia completa. Esto no \u00fanicamente va a ser palabra en una orden. Van a haber fondos destinados a estrategias espec\u00edficas para poder atender contundentemente el problema social por el cual Puerto Rico atraviesa\u201d, apunt\u00f3 en entrevista con NotiCel esta semana.<\/p>\n<p><strong id=\"strong-747f17ee0b396a949c448e1d814dfd6f\">Lea tambi\u00e9n:<\/strong> <a href=\"https:\/\/noticel.com\/en\/gobierno\/ahora\/top-stories\/20210113\/gobernador-voy-a-respetar-los-derechos-de-la-mujer-que-todos-esten-claros\/\" id=\"link-99e972c635bf646605a8414f64b33a1f\">Gobernador: \u201cVoy a respetar los derechos de la mujer. Que todos est\u00e9n claros\u201d.<\/a><\/p>\n<p>\u201cNo podemos acelerar la maduraci\u00f3n de las estrategias. Hay estrategias que tienen que ser bien pensadas, que tenemos que estar todos en la misma p\u00e1gina y que para verdaderamente poder tener resultados tenemos que trabajarlas y analizarlas antes de soltarlas porque necesitamos que sean efectivas. El Gobernador se est\u00e1 tomando su tiempo para que esto no sea una estrategia m\u00e1s\u201d, agreg\u00f3.<\/p>\n<p>El pasado 26 de octubre, la entonces gobernadora Wanda V\u00e1zquez Garced emiti\u00f3 una orden ejecutiva para decretar que los servicios para atajar la violencia contra las mujeres se tratasen como una prioridad gubernamental. Esa directriz no consign\u00f3 los fondos para su implementaci\u00f3n, pero orden\u00f3 a la Oficina de la Procuradora de las Mujeres y a la Polic\u00eda a realizar un an\u00e1lisis y someter peticiones presupuestarias para garantizar la prestaci\u00f3n de esos servicios prioritarios.<\/p>\n<p>Solo la Oficina de la Procuradora someti\u00f3 una petici\u00f3n, que se encuentra ante la consideraci\u00f3n de la Junta de Control Fiscal.<\/p>\n<p>Dicha orden, que sigue vigente, cre\u00f3 un Comit\u00e9 Multisectorial contra la Violencia a la Mujer (Comuvi) para asesorar a la Gobernadora e implementar un plan de acci\u00f3n elaborado por el Ejecutivo en reuniones con algunas organizaciones de mujeres. A pesar de los t\u00e9rminos de cumplimiento r\u00edgidos que estableci\u00f3 la orden, el Comit\u00e9 solo se ha reunido una vez y la puesta en marcha del protocolo no ha iniciado.<\/p>\n<p>Al hablar de la orden ejecutiva que prepara la administraci\u00f3n Pierluisi, Garc\u00eda Bardales indic\u00f3 que el Ejecutivo eval\u00faa alternativas para asignar m\u00e1s fondos a la Oficina de la Procuradora de las Mujeres (OPM), cuyos fondos han menguado en medio de la quiebra gubernamental.<\/p>\n<p>\u201cEs una realidad que la Oficina de la Procuradora de las Mujeres ha sufrido unos recortes y lo estamos analizando porque afectan la ejecutoria y la fuerza de la ejecuci\u00f3n que tiene esa oficina sobre la diferentes agencias y responsabilidades que tiene en ley. La Oficina de la Procuradora tiene como 80 leyes que tiene que hacer cumplir y si no se le dan los recursos adecuados b\u00e1sicamente estamos coartando la posibilidad de ejecuci\u00f3n, as\u00ed que tenemos que revisar eso\u201d, respondi\u00f3 a preguntas de este medio digital.<\/p>\n<p><strong id=\"strong-9f78393713219422b2b42e68674e0c5b\">Lea tambi\u00e9n:<\/strong> <a href=\"https:\/\/noticel.com\/en\/mujeres\/gobierno\/ahora\/top-stories\/20210117\/sin-prisa-puesta-en-vigor-de-directriz-que-debe-atender-la-violencia-contra-las-mujeres-como-priorid\/\" id=\"link-b5978e86855f1ab731d2ce55550e433e\">Sin prisa puesta en vigor de directriz que debe atender la violencia contra las mujeres como prioridad de gobierno<\/a><\/p>\n<p>Aunque organizaciones de mujeres como la Colectiva Feminista en Acci\u00f3n llevan tiempo reclamando que el Gobierno declare un estado de emergencia, el Comit\u00e9 Multisectorial creado para implantar la pol\u00edtica p\u00fablica vigente no incluy\u00f3 a representantes de esta organizaci\u00f3n o de otros grupos que han tomado las calles para exigir el estado de emergencia en el cuerpo asesor.<\/p>\n<p>\u201cCon relaci\u00f3n a los grupos de mujeres que reconocen que hay una situaci\u00f3n de emergencia en contra de la violencia de la mujer en Puerto Rico, es que todos coincidimos. Todos coincidimos en que hay una situaci\u00f3n alarmante. En la mesa de ideas, nos tenemos que sentar todos: los que no pensamos igual, los que pensemos igual, todos. Porque la soluci\u00f3n no solo incide en poder identificar cu\u00e1l es la soluci\u00f3n sino que todos rememos para el mismo lado\u201d, se\u00f1al\u00f3 Garc\u00eda Bardales.<\/p>\n<p>\u201cLa soluci\u00f3n est\u00e1 en la uni\u00f3n y la educaci\u00f3n tambi\u00e9n est\u00e1 en la uni\u00f3n. Queremos llevar m\u00e1s educaci\u00f3n contundente al pueblo y queremos penetrar comunidades donde se nos hace dif\u00edcil llevar la voz, nos tenemos que unir todos\u201d, agreg\u00f3.<\/p>\n<p>Los feminicidios aumentaron un 62% el a\u00f1o pasado, seg\u00fan un an\u00e1lisis del Observatorio de Equidad de G\u00e9nero de Puerto Rico. El 2020 cerr\u00f3 con 60 feminicidios directos e indirectos, seis transfeminicidios y 26 casos que segu\u00edan bajo investigaci\u00f3n o sin informaci\u00f3n.<\/p>\n<p>Un estudio reciente de ONU Mujer tambi\u00e9n concluy\u00f3 que durante la pandemia del Covid-19 se ha intensificado todo tipo de violencia contra las mujeres y las ni\u00f1as, sobre todo, la violencia en el hogar debido a las medidas de confinamiento impuestas para evitar la propagaci\u00f3n del peligroso virus.<\/p>","protected":false},"excerpt":{"rendered":"<p>La secretaria de la Gobernaci\u00f3n, Noelia Garc\u00eda Bardales, se\u00f1al\u00f3 que el Ejecutivo toma su tiempo porque \u201cno va a ser algo que se haga para salir del paso\u201d. A tres semanas de plantar pie en La Fortaleza, el gobernador Pedro Pierluisi Urrutia todav\u00eda no ha decretado un estado de emergencia por violencia de g\u00e9nero, aunque [&hellip;]<\/p>","protected":false},"author":0,"featured_media":428242,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[4,2],"tags":[],"class_list":["post-156274","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gobierno","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/156274","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=156274"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/156274\/revisions"}],"predecessor-version":[{"id":428249,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/156274\/revisions\/428249"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/428242"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=156274"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=156274"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=156274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}