{"id":156002,"date":"2021-01-15T19:21:00","date_gmt":"2021-01-15T23:21:00","guid":{"rendered":"https:\/\/www.noticel.com\/deportes\/20210115\/el-frio-de-green-bay-no-sera-excusa-para-los-rams-en-su-duelo-ante-packers\/"},"modified":"2025-07-16T09:58:39","modified_gmt":"2025-07-16T09:58:39","slug":"el-frio-de-green-bay-no-sera-excusa-para-los-rams-en-su-duelo-ante-packers","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/deportes\/20210115\/el-frio-de-green-bay-no-sera-excusa-para-los-rams-en-su-duelo-ante-packers\/","title":{"rendered":"El fr\u00edo de Green Bay no ser\u00e1 excusa para los Rams en su duelo ante Packers"},"content":{"rendered":"<h3>El partido ser\u00e1 el s\u00e1bado desde las 5:35 de la tarde.<\/h3>\n<p>LOS \u00c1NGELES &#8211; Una vez m\u00e1s el factor campo ser\u00e1 decisivo en los duelos a un solo partido en Rondas Divisionales de la NFL, como las que protagonizar\u00e1n este s\u00e1bado los Packers de Green Bay y los Rams de Los Angeles, donde adem\u00e1s el fr\u00edo y la nieve tambi\u00e9n estar\u00e1n presentes.<\/p>\n<p>Los Rams tendr\u00e1n que dejar el sol de california para enfrentarse en Green Bay en el campo a los Packers, acompa\u00f1ados de unos elementos climatol\u00f3gicos nada favorables como ser\u00e1n el fr\u00edo y la nieve. El partido comenzar\u00e1 a las 5:35 de la tarde.<\/p>\n<p>El entrenador en jefe de los Rams, Sean McVay, en consciente de esa realidad, al igual que todos los jugadores del equipo, que ha entrenado los \u00faltimos d\u00edas bajo el sol cl\u00e1sico del invierno californiano que es en realidad primaveral.<\/p>\n<p>McVay admiti\u00f3 que los elementos climatol\u00f3gicos no ser\u00e1n f\u00e1ciles, pero estaban preparados para hacerles frente con las garant\u00edas de no buscar excusas en su rendimiento cuando est\u00e9n en el campo.<\/p>\n<p>\u00abSolo se trata de antes de comenzar el partido, una vez que las acciones se inician no creo que los jugadores vayan a sentir ning\u00fan tipo de fr\u00edo\u00bb, coment\u00f3 McVay antes de viajar rumbo a Green Bay.<\/p>\n<p>Los Rams vienen de vencer de manera sorpresiva a los Seattle Seahawks en la Ronda de Comodines en un duelo en el que su defensiva, que termin\u00f3 como la n\u00famero uno en la temporada regular, sum\u00f3 cinco capturas y golpe\u00f3 10 veces a Russell Wilson.<\/p>\n<p>Mientras tanto, el mariscal de campo Jared Goff, confirmado como titular, y los Rams se preparan para el adverso clima.<\/p>\n<p>En la campa\u00f1a regular, los Rams registraron 53 capturas (segundos en la NFL), guiados por Leonard Floyd y Aaron Donald, quienes tendr\u00e1n ahora el reto de frenar al mariscal de campo Aaron Rodgers y a la ofensiva de los Packers, que terminaron la temporada regular como l\u00edderes en anotaciones en la liga con efectividad del 80 por ciento en zona roja.<\/p>\n<p>Goff, quien no inici\u00f3 el duelo ante Seattle y fue nombrado quarterback titular para el duelo ante los Rams luego de que el novato John Wolford fue descartado por conmoci\u00f3n, se ha entrenado con guantes en la semana para proteger su pulgar derecho, pero tambi\u00e9n como medida contra el fr\u00edo que experimentar\u00e1 en el Lambeau Field.<\/p>\n<p>El veterano Blake Bortles ser\u00e1 el suplente de Goff ante cualquier adversidad.<\/p>","protected":false},"excerpt":{"rendered":"<p>El partido ser\u00e1 el s\u00e1bado desde las 5:35 de la tarde. LOS \u00c1NGELES &#8211; Una vez m\u00e1s el factor campo ser\u00e1 decisivo en los duelos a un solo partido en Rondas Divisionales de la NFL, como las que protagonizar\u00e1n este s\u00e1bado los Packers de Green Bay y los Rams de Los Angeles, donde adem\u00e1s el [&hellip;]<\/p>","protected":false},"author":0,"featured_media":430427,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ep_exclude_from_search":false,"footnotes":""},"categories":[31],"tags":[],"class_list":["post-156002","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/156002","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=156002"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/156002\/revisions"}],"predecessor-version":[{"id":430430,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/156002\/revisions\/430430"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/430427"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=156002"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=156002"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=156002"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}