{"id":155911,"date":"2021-01-14T12:09:00","date_gmt":"2021-01-14T16:09:00","guid":{"rendered":"https:\/\/www.noticel.com\/ahora\/legislatura\/20210114\/presidente-del-senado-anuncia-nueva-comision-para-trabajar-con-fondos-federales\/"},"modified":"2025-07-16T10:08:34","modified_gmt":"2025-07-16T10:08:34","slug":"presidente-del-senado-anuncia-nueva-comision-para-trabajar-con-fondos-federales","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20210114\/presidente-del-senado-anuncia-nueva-comision-para-trabajar-con-fondos-federales\/","title":{"rendered":"Presidente del Senado anuncia nueva comisi\u00f3n para \u00abtrabajar\u00bb con fondos federales"},"content":{"rendered":"<h3>La misma es llamada \u201cComisi\u00f3n de Cumplimiento y Reestructuraci\u00f3n\u201d<\/h3>\n<p>El presidente del Senado, Jos\u00e9 Luis Dalmau, anunci\u00f3 hoy que a\u00f1adir\u00e1 una nueva comisi\u00f3n al cuerpo legislativo enfocado en que Puerto Rico trabaje con los fondos federales adecuadamente para ver el resultado. La misma ser\u00e1 llamada \u201cComisi\u00f3n de Cumplimiento y Reestructuraci\u00f3n\u201d.<\/p>\n<p>El Senador del Partido Popular Democr\u00e1tico (PPD) tambi\u00e9n asegur\u00f3 que las comisiones del Senado no ser\u00e1n \u00abde rojo o azul\u00bb: ser\u00e1n de todos los colores.<\/p>\n<p>\u201cHoy voy a asignar a personas de todos los partidos a que dirijan las comisiones\u201d, manifest\u00f3 el Presidente.  \u201cTodos los partidos est\u00e1n dentro de los hemiciclos, no est\u00e1n en las gradas, ahora estamos todos representados adentro\u201d, abund\u00f3.<\/p>\n<p>Actualmente el Senado cuenta con senadores de todos los partidos, como Mar\u00eda de Lourdes Santiago, del Partido Independentista Puertorrique\u00f1o (PIP), Ana Irma Rivera Lass\u00e9n del Movimiento Victoria Ciudadana (MVC), Rafael Bernabe del MVC, Joanne Rodr\u00edguez Veve de Proyecto Dignidad (PD), y Jos\u00e9 Vargas Vidot como legislador independiente.<\/p>\n<p>Pendientes a NotiCel para ampliaci\u00f3n de esta noticia.<\/p>","protected":false},"excerpt":{"rendered":"<p>La misma es llamada \u201cComisi\u00f3n de Cumplimiento y Reestructuraci\u00f3n\u201d El presidente del Senado, Jos\u00e9 Luis Dalmau, anunci\u00f3 hoy que a\u00f1adir\u00e1 una nueva comisi\u00f3n al cuerpo legislativo enfocado en que Puerto Rico trabaje con los fondos federales adecuadamente para ver el resultado. La misma ser\u00e1 llamada \u201cComisi\u00f3n de Cumplimiento y Reestructuraci\u00f3n\u201d. El Senador del Partido Popular [&hellip;]<\/p>","protected":false},"author":0,"featured_media":431122,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[5,2],"tags":[],"class_list":["post-155911","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-legislatura","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/155911","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=155911"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/155911\/revisions"}],"predecessor-version":[{"id":431123,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/155911\/revisions\/431123"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/431122"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=155911"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=155911"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=155911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}