{"id":153808,"date":"2020-11-25T16:03:00","date_gmt":"2020-11-25T20:03:00","guid":{"rendered":"https:\/\/www.noticel.com\/ahora\/top-stories\/20201125\/estadounidenses-ignoran-advertencias-por-covid-19-y-rompen-record-de-viajes-desde-marzo\/"},"modified":"2025-07-16T13:31:52","modified_gmt":"2025-07-16T13:31:52","slug":"estadounidenses-ignoran-advertencias-por-covid-19-y-rompen-record-de-viajes-desde-marzo","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20201125\/estadounidenses-ignoran-advertencias-por-covid-19-y-rompen-record-de-viajes-desde-marzo\/","title":{"rendered":"Estadounidenses ignoran advertencias por COVID-19 y rompen r\u00e9cord de viajes desde marzo"},"content":{"rendered":"<h3>\u00abUn sacrificio ahora puede salvar vidas\u00bb, hab\u00eda pedido Fauci.<\/h3>\n<p>Millones de viajeros han ignorado en Estados Unidos las advertencias de las autoridades sanitarias de no desplazarse antes de las festividades de Acci\u00f3n de Gracias debido a la pandemia, que est\u00e1 teniendo un crecimiento explosivo en todo el pa\u00eds y que amenaza con te\u00f1ir las Navidades de negro.<\/p>\n<p>Seg\u00fan la Administraci\u00f3n de Seguridad de Transporte (TSA), encargada de los controles aeroportuarios, esta es la semana con m\u00e1s afluencia de viajeros desde que en marzo comenz\u00f3 la pandemia, con una media de un mill\u00f3n de viajeros diarios desde el pasado fin de semana.<\/p>\n<p>Muchos estadounidenses est\u00e1n ignorando las advertencias del Centro de Control de Enfermedades (CDC, en ingl\u00e9s) para que no se viaje en este per\u00edodo vacacional que culmina con la cena de Acci\u00f3n de Gracias de este jueves, pero que es el pistoletazo de salida para todo el per\u00edodo navide\u00f1o y de fin de a\u00f1o en Estados Unidos.<\/p>\n<p>Las autoridades sanitarias temen que la circulaci\u00f3n de personas y los intercambios entre n\u00facleos familiares durante estas fiestas dispare a\u00fan m\u00e1s el n\u00famero de contagios en todo el pa\u00eds, incluidas zonas que hasta el momento han conseguido mantener la pandemia relativamente bajo control durante este oto\u00f1o.<\/p>\n<p>Los contagios se est\u00e1n elevando a una velocidad no vista hasta el momento en este pa\u00eds, que lidera al mundo en n\u00famero total de contagiados, con m\u00e1s de 12.6 millones, y que en las \u00faltimas dos semanas ha experimentado 2 millones de casos nuevos, y ya acumula m\u00e1s de 260,000 muertos.<\/p>\n<p>El medio oeste y el norte del pa\u00eds son ahora los focos de esta tragedia en varios actos, con algunos hospitales desbordados y unas cifras de contagios y hospitalizaciones en m\u00e1ximos desde que comenz\u00f3 la alerta sanitaria.<\/p>\n<p>Las medidas de control de las multitudes, toques de queda en bares y restaurantes o cierre de colegios o tiendas (este sol\u00eda ser el per\u00edodo de mayor consumo del a\u00f1o) que se est\u00e1n dando por todo el pa\u00eds no han servido hasta el momento para detener el nuevo pico de infecciones y las alrededor de 2,000 muertes diarias que se est\u00e1n produciendo.<\/p>\n<p>Si Acci\u00f3n de Gracias, como se teme, acaba acelerando esta oleada explosiva de infecciones, diciembre y la temporada navide\u00f1a puede convertirse en el per\u00edodo m\u00e1s negro de la historia estadounidense reciente, con 311,000 muertos antes de fin de a\u00f1o, seg\u00fan las proyecciones m\u00e1s optimistas del Instituto de M\u00e9tricas de Salud y Evaluaci\u00f3n (IHME, en ingl\u00e9s).<\/p>\n<p>\u00ab\u00daLTIMO RUEGO\u00bb<\/p>\n<p>El epidemi\u00f3logo jefe de Estados Unidos, Anthony Fauci, emiti\u00f3 hoy un \u00ab\u00faltimo ruego\u00bb a los estadounidenses para que hagan sacrificios en estas vacaciones tan familiares con el fin de evitar muertes dentro de unas semanas.<\/p>\n<p>\u00abUn sacrificio ahora puede salvar vidas y hacer el futuro mucho m\u00e1s brillante para superar esto (la pandemia)\u00bb, indic\u00f3 el director del Instituto Nacional de Alergias y Enfermedades Infecciosas (NIAID, en ingl\u00e9s) en una entrevista con ABC News.<\/p>\n<p>Fauci record\u00f3 que las vacunas est\u00e1n \u00aben el horizonte\u00bb y que solo hay que tener un poco m\u00e1s de paciencia, evitar multitudes, especialmente en espacios cerrados, para poder ver la salida de una pandemia que dura ya diez meses.<\/p>\n<p>Al menos, dos vacunas podr\u00edan recibir autorizaci\u00f3n para ser suministradas a partir de diciembre a grupos de riesgo y prioritarios, aunque seguramente ser\u00e1 la candidata de Pfizer, que ya ha solicitado autorizaci\u00f3n de emergencia a la Administraci\u00f3n de Alimentos y Medicamentos (FDA), la que estar\u00e1 disponible primero.<\/p>\n<p>Algunos estados han impuesto nuevas restricciones en coincidencia con la \u00e9poca festiva que se inicia con Acci\u00f3n de Gracias. Pensilvania ha impuesto un toque de queda a partir de las 5 de la tarde de hoy y la prohibici\u00f3n de servir alcohol en bares para evitar aglomeraciones en la que tradicionalmente es considerada una de las noches en que m\u00e1s se bebe y se socializa de todo el a\u00f1o.<\/p>\n<p>PANDEMIA FUERA DE CONTROL<\/p>\n<p>Con la falta de liderazgo por parte de la Administraci\u00f3n saliente de Donald Trump, est\u00e1n siendo los estados los que por separado est\u00e1n imponiendo las medidas que consideran oportunas para detener la extensi\u00f3n de la pandemia, aunque a\u00fan algunos no obligan a llevar mascarillas en lugares cerrados o donde no se puede mantener la distancia.<\/p>\n<p>El presidente electo, Joe Biden, se ha marcado como su principal tarea detener la extensi\u00f3n del coronavirus y aprobar las ayudas para los hogares m\u00e1s afectados por la par\u00e1lisis econ\u00f3mica a la que se ha enfrentado el pa\u00eds.<\/p>\n<p>Estados como Maine, Minesota y Dakota del Norte ya han dicho que con la velocidad actual a la que se expande el virus es pr\u00e1cticamente imposible para ellos realizar un rastreo de contactos en l\u00ednea con las recomendaciones del CDC.<\/p>\n<p>La mayor parte de los estados del pa\u00eds est\u00e1n en alerta roja, con las infecciones, que aumentaron en 2 millones en las \u00faltimas dos semanas hasta 12.6 millones, fuera de control.<\/p>","protected":false},"excerpt":{"rendered":"<p>\u00abUn sacrificio ahora puede salvar vidas\u00bb, hab\u00eda pedido Fauci. Millones de viajeros han ignorado en Estados Unidos las advertencias de las autoridades sanitarias de no desplazarse antes de las festividades de Acci\u00f3n de Gracias debido a la pandemia, que est\u00e1 teniendo un crecimiento explosivo en todo el pa\u00eds y que amenaza con te\u00f1ir las Navidades [&hellip;]<\/p>","protected":false},"author":0,"featured_media":445835,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-153808","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/153808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=153808"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/153808\/revisions"}],"predecessor-version":[{"id":445837,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/153808\/revisions\/445837"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/445835"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=153808"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=153808"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=153808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}