{"id":153668,"date":"2020-11-22T16:17:00","date_gmt":"2020-11-22T20:17:00","guid":{"rendered":"https:\/\/www.noticel.com\/ahora\/elecciones\/top-stories\/20201122\/informe-de-observadores-electorales-expone-que-hubo-maquinas-que-llegaron-con-papeletas-votadas-el-d\/"},"modified":"2025-07-16T13:43:21","modified_gmt":"2025-07-16T13:43:21","slug":"informe-de-observadores-electorales-expone-que-hubo-maquinas-que-llegaron-con-papeletas-votadas-el-d","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20201122\/informe-de-observadores-electorales-expone-que-hubo-maquinas-que-llegaron-con-papeletas-votadas-el-d\/","title":{"rendered":"Informe de observadores electorales expone que hubo m\u00e1quinas que llegaron con papeletas votadas el d"},"content":{"rendered":"<h3>Tambi\u00e9n aborda problemas para garantizar el distanciamiento social durante la elecci\u00f3n general.<\/h3>\n<p>El Colegio de Abogados y Abogadas de Puerto Rico (CAAPR) remiti\u00f3 un informe a la Comisi\u00f3n Estatal de Elecciones (CEE) sobre las elecciones generales del pasado 3 de noviembre que, entre otras cosas, aborda que hubo m\u00e1quinas que llegaron con votos a los colegios electorales.<\/p>\n<p>Seg\u00fan establece el informe de 85 p\u00e1ginas, observadores electorales concluyeron que hubo m\u00e1quinas que llegaron con papeletas votadas, en lugar de estar en cero. La situaci\u00f3n descrita ocurri\u00f3 en colegios de San Juan.<\/p>\n<p>Espec\u00edficamente, \u00aben el precinto 1 de San Juan, Unidad 2, Colegio 2, se proveyeron m\u00e1quinas de escrutinio electr\u00f3nico que al introducir en el men\u00fa administrativo el comando de abrir la elecci\u00f3n, no aparec\u00edan con resultados en cero\u00bb, lee el documento.<\/p>\n<p>\u00abLos funcionarios de colegio tuvieron problemas para llevarla a cero\u00bb, agrega tambi\u00e9n, sin especificar si las papeletas eran legislativas, estatales, o municipales.<\/p>\n<p>El informe sostiene adem\u00e1s la misma situaci\u00f3n se repiti\u00f3 en la Escuela Ram\u00f3n Vil\u00e1 Ramos en el Viejo San Juan. En ese caso, no utilizaron la m\u00e1quina, se expone.<\/p>\n<p>El documento agrega que la suma de esas situaciones y otras, llevaron a elevar el tiempo de votaci\u00f3n y a que se extendieran filas que en ocasiones, representaba horas de espera para los electores.<\/p><div class=\"notic-content-middle\" id=\"notic-1063243954\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>\u00abDebido a que solamente hab\u00eda una m\u00e1quina por colegio y de que cada colegio pod\u00eda admitir alrededor de 400 electores, esto l\u00f3gicamente ocasion\u00f3 largas filas y un prolongado tiempo para votar que en muchas ocasiones se extend\u00eda casi siempre por m\u00e1s de una hora, llegando a veces a dos horas, en arduas condiciones de espera\u00bb, se indica.<\/p>\n<p>Espec\u00edficamente sobre las condiciones, el informe expone que aunque las filas fuera de los colegios manten\u00edan por lo general el distanciamiento social, ello llevaba a que se hicieran en lugares que por ejemplo, no inclu\u00edan la posibilidad de asientos si eran necesarios para que alg\u00fan elector descansara.<\/p>\n<p>Otra particularidad importante es que una vez los electores pasaban a votar, dentro del colegio electoral no exist\u00eda el distanciamiento de seis pies requerido para minimizar la probabilidad de contagios por COVID-19.<\/p>\n<p>\u00abUna vez dentro de los colegios, espor\u00e1dicamente se produc\u00edan aglomeraciones moment\u00e1neas de electores\u00bb, se indica.<\/p>\n<p>Las elecciones generales se dieron en medio de llamados de expertos a evitar aglomeraciones, tomando en cuenta que Puerto Rico se encuentra en un nivel naranja. Al momento, en la isla hay 45,268 casos confirmados de COVID-19 y 37,873 sospechosos.<\/p>\n<p>Mira el informe a continuaci\u00f3n:<\/p>","protected":false},"excerpt":{"rendered":"<p>Tambi\u00e9n aborda problemas para garantizar el distanciamiento social durante la elecci\u00f3n general. El Colegio de Abogados y Abogadas de Puerto Rico (CAAPR) remiti\u00f3 un informe a la Comisi\u00f3n Estatal de Elecciones (CEE) sobre las elecciones generales del pasado 3 de noviembre que, entre otras cosas, aborda que hubo m\u00e1quinas que llegaron con votos a los [&hellip;]<\/p>","protected":false},"author":0,"featured_media":446616,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[10,2],"tags":[],"class_list":["post-153668","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-elecciones-2020","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/153668","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=153668"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/153668\/revisions"}],"predecessor-version":[{"id":446618,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/153668\/revisions\/446618"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/446616"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=153668"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=153668"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=153668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}