{"id":153492,"date":"2020-11-18T18:47:00","date_gmt":"2020-11-18T22:47:00","guid":{"rendered":"https:\/\/www.noticel.com\/article\/20201118\/se-caldean-los-animos-en-el-coliseo-roberto-clemente\/"},"modified":"2025-07-16T14:02:17","modified_gmt":"2025-07-16T14:02:17","slug":"se-caldean-los-animos-en-el-coliseo-roberto-clemente","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/ultima-hora\/20201118\/se-caldean-los-animos-en-el-coliseo-roberto-clemente\/","title":{"rendered":"Se caldean los \u00e1nimos en el Coliseo Roberto Clemente"},"content":{"rendered":"<h3>Se producen encontronazos entre funcionarios que trabajan en el escrutinio.<\/h3>\n<p>Un encontronazo se produjo entre funcionarios que trabajaban en el proceso de escrutinio en el Coliseo Roberto Clemente.<\/p>\n<p>El incidente se produjo luego que se paralizaran las labores de escrutinio, a ra\u00edz de una orden judicial que ordenaba a la Comisi\u00f3n Estatal de Elecciones (CEE) entregar a los comisionados electorales la lista de votantes ausentes y por adelantado, tal como hab\u00eda solicitado el Movimiento Victoria Ciudadana.<\/p>\n<p>El comisionado del Movimiento Victoria Ciudadana, Olvin A. Valent\u00edn, culp\u00f3 a su hom\u00f3logo del Partido Nuevo Progresista, H\u00e9ctor Joaqu\u00edn S\u00e1nchez, de incitar a los presentes.<\/p>\n<p>\u00abPor alguna raz\u00f3n, le pasan el micr\u00f3fono al comisionado del Partido Nuevo Progresista para hacer un grito de guerra\u00bb, sostuvo Valent\u00edn.<\/p>\n<p>Igual reclamo hizo el representante electoral del Partido Independentista Puertorrique\u00f1o (PIP), Iv\u00e1n Aponte, qui\u00e9n pidi\u00f3 tambi\u00e9n censur\u00f3 la acci\u00f3n del comisionado o novoprogresista.<\/p><div class=\"notic-content-middle\" id=\"notic-665107519\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-300&#215;600\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-150x300.jpg 150w, https:\/\/cdn.noticel.com\/2026\/05\/30094652\/Acodese-Adaptaciones-Noticel-300x600-1-6x12.jpg 6w\" sizes=\"(max-width: 300px) 100vw, 300px\" width=\"300\" height=\"600\"   \/><\/a><\/div>\n<p>\u00abTienen que haber consecuencias. Me resulta incre\u00edble que un director de escrutinio le de un micr\u00f3fono a un comisionado electoral y cree este clima\u00bb.<\/p>\n<p>Sin embargo, S\u00e1nchez asegur\u00f3 que estaba defendiendo a una de sus funcionarias porque le estaban pidiendo un malet\u00edn de forma agresiva.<\/p>\n<p>\u00bbNo se hab\u00eda dado ninguna instrucci\u00f3n de remover ese malet\u00edn. Hab\u00eda papeletas vivas y hab\u00eda que proteger el voto de nuestros electores\u00bb, asegur\u00f3 S\u00e1nchez a la prensa.<\/p>\n<p>Vea el video del incidente aqu\u00ed.<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.facebook.com\/plugins\/video.php?height=314&#038;href=https%3A%2F%2Fwww.facebook.com%2Fnoticelpr%2Fvideos%2F1006757519833439%2F&#038;show_text=false&#038;width=560\" width=\"560\" height=\"314\" style=\"border:none;overflow:hidden\" scrolling=\"no\" frameborder=\"0\" allowfullscreen=\"true\" allow=\"autoplay; clipboard-write; encrypted-media; picture-in-picture; web-share\"><\/iframe><\/p>","protected":false},"excerpt":{"rendered":"<p>Se producen encontronazos entre funcionarios que trabajan en el escrutinio. Un encontronazo se produjo entre funcionarios que trabajaban en el proceso de escrutinio en el Coliseo Roberto Clemente. El incidente se produjo luego que se paralizaran las labores de escrutinio, a ra\u00edz de una orden judicial que ordenaba a la Comisi\u00f3n Estatal de Elecciones (CEE) [&hellip;]<\/p>","protected":false},"author":0,"featured_media":447750,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[10,4,2],"tags":[],"class_list":["post-153492","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-elecciones-2020","category-gobierno","category-ultima-hora"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/153492","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=153492"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/153492\/revisions"}],"predecessor-version":[{"id":447753,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/153492\/revisions\/447753"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/447750"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=153492"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=153492"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=153492"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}