{"id":152257,"date":"2020-10-23T13:21:00","date_gmt":"2020-10-23T17:21:00","guid":{"rendered":"https:\/\/www.noticel.com\/la-calle\/policiacas\/20201023\/hallan-muerto-a-un-siquiatra-en-arecibo\/"},"modified":"2025-07-16T15:50:26","modified_gmt":"2025-07-16T15:50:26","slug":"hallan-muerto-a-un-siquiatra-en-arecibo","status":"publish","type":"post","link":"https:\/\/noticel.com\/en\/noticias\/la-calle\/20201023\/hallan-muerto-a-un-siquiatra-en-arecibo\/","title":{"rendered":"Hallan muerto a un siquiatra en Arecibo"},"content":{"rendered":"<h3>Un empleado lo encontr\u00f3 tirado en el piso con una herida en la frente<\/h3>\n<p>La Polic\u00eda report\u00f3 hoy una muerte sospechosa en la avenida V\u00edctor Rojas de Arecibo.<\/p>\n<p>Seg\u00fan el informe preliminar, un empleado del doctor Jorge Robles Irizarry, de 56 a\u00f1os, lo encontr\u00f3 muerto tirado en el suelo de su residencia y el cuerpo presenta una herida en el \u00e1rea de la frente de su rostro.<\/p><div class=\"notic-content-middle\" id=\"notic-986473661\"><div class=\"notic-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.asegurate-bien.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Acodese-Adaptaciones-Noticel-970&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1.jpg\" alt=\"\"  srcset=\"https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1.jpg 970w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-300x77.jpg 300w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-768x198.jpg 768w, https:\/\/cdn.noticel.com\/2026\/05\/30100504\/Acodese-Adaptaciones-Noticel-970x250-1-18x5.jpg 18w\" sizes=\"(max-width: 970px) 100vw, 970px\" width=\"970\" height=\"250\"   \/><\/a><\/div>\n<p>El cuerpo de Robles Irizarry, quien se desempe\u00f1aba como siquiatra, ser\u00e1 transportado hacia el Negociado Ciencia forenses para que determine la causa de la muerte.<\/p>\n<p>El agente Edwin Caldero Torres, de la divisi\u00f3n Homicidios, en uni\u00f3n a la fiscal Yolanda Pitino, se hicieron a cargo de la investigaci\u00f3n.<\/p>","protected":false},"excerpt":{"rendered":"<p>Un empleado lo encontr\u00f3 tirado en el piso con una herida en la frente La Polic\u00eda report\u00f3 hoy una muerte sospechosa en la avenida V\u00edctor Rojas de Arecibo. Seg\u00fan el informe preliminar, un empleado del doctor Jorge Robles Irizarry, de 56 a\u00f1os, lo encontr\u00f3 muerto tirado en el suelo de su residencia y el cuerpo [&hellip;]<\/p>","protected":false},"author":0,"featured_media":455694,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12,15],"tags":[],"class_list":["post-152257","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-calle","category-policiacas"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/152257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/comments?post=152257"}],"version-history":[{"count":1,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/152257\/revisions"}],"predecessor-version":[{"id":455696,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/posts\/152257\/revisions\/455696"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media\/455694"}],"wp:attachment":[{"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/media?parent=152257"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/categories?post=152257"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticel.com\/en\/wp-json\/wp\/v2\/tags?post=152257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}